{"id":26735,"date":"2013-05-25T16:20:24","date_gmt":"2013-05-25T20:20:24","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/ipor-que-no-existen-gatos-machos-de-3-colores-2\/"},"modified":"2013-05-25T16:20:24","modified_gmt":"2013-05-25T20:20:24","slug":"ipor-que-no-existen-gatos-machos-de-3-colores-2","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ipor-que-no-existen-gatos-machos-de-3-colores-2\/","title":{"rendered":"\u00bfPor qu\u00e9 no existen gatos (machos) de 3 colores?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-26730\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_4678219403_6db124424f_z-630x427.jpg\" width=\"600\" height=\"400\" alt=\"4678219403_6db124424f_z-630x427\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_4678219403_6db124424f_z-630x427.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_4678219403_6db124424f_z-630x427-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>La gen\u00e9tica como ciencia tiene formas maravillosas de expresarse. Una de las m\u00e1s curiosas puede estar ahora mismo deambulando por tu jard\u00edn: el color de los gatos.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>Como sabemos, estos peque\u00f1os felinos vienen en 3 colores (o sus mezclas): blancos, negros y anaranjados. Pero, \u00bfsab\u00edas que si te topas con un gato de 3 colores a la vez\u2026 s\u00f3lo puede tratarse de una gata?<\/p>\n<p>Esto se produce porque en los gatos, los colores s\u00f3lo est\u00e1n determinados por el cromosoma X (femenino). De \u00e9l depende que un minino tenga tonalidades negras o anaranjadas, mientras que el color blanco est\u00e1 regido por un gen totalmente distinto, sin relaci\u00f3n con el sexo del animal.<\/p>\n<p>De esta forma, un gato macho (de cromosomas XY) s\u00f3lo tiene la posibilidad de ser blanco + negro o anaranjado, pero no los tres. En tanto una hembra, con dos cromosomas X, tiene la posibilidad de mezclar todas las tonalidades anteriores, en lo que se conoce como un gato \u201ccalic\u00f3\u201d, explica About.com<\/p>\n<p>\u00bfEntonces no existen machos de 3 colores? En casos muy raros, s\u00ed. Sin embargo, estos animales sufren una anormalidad gen\u00e9tica similar al s\u00ednfrome de Klinefelter en los humanos, que los lleva a tener 3 cromosomas: dos XX y uno Y, provocando que sean gatos est\u00e9riles.<\/p>\n<p>Una \u00faltima curiosidad es que desde 2001, los gatos \u201ccalic\u00f3\u201d son los animales oficiales del estado de Maryland, en Estados Unidos, debido a que sus 3 colores -blanco, negro y anaranjado- coinciden con los de su escudo.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La gen\u00e9tica como ciencia tiene formas maravillosas de expresarse. Una de las m\u00e1s curiosas puede estar ahora mismo deambulando por tu jard\u00edn: el color de los gatos.<\/p>\n","protected":false},"author":3,"featured_media":26730,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-26735","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=26735"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26735\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/26730"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=26735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=26735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=26735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}