{"id":26823,"date":"2013-05-28T02:27:25","date_gmt":"2013-05-28T06:27:25","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/al-humorista-margaro-por-poco-lo-matan-dos-atracadores\/"},"modified":"2013-05-28T02:27:25","modified_gmt":"2013-05-28T06:27:25","slug":"al-humorista-margaro-por-poco-lo-matan-dos-atracadores","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/al-humorista-margaro-por-poco-lo-matan-dos-atracadores\/","title":{"rendered":"Al humorista Margaro por poco lo matan dos atracadores"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-26822\" alt=\"Margaro-\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_Margaro-.jpg\" width=\"713\" height=\"530\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_Margaro-.jpg 713w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_Margaro--300x223.jpg 300w\" sizes=\"auto, (max-width: 713px) 100vw, 713px\" \/>Santo Domingo. El humorista Nicol\u00e1s D\u00edaz (Margaro) es la nueva v\u00edctima en la ola de atracos que azota la Rep\u00fablica Dominicana. El programa Vacilando La Tarde que se transmite por Ne\u00f3n 89.3 FM pudo contactar al artista quien explic\u00f3 que dos j\u00f3venes aparentemente menores de edad le dieron 5 pu\u00f1aladas y le despojaron de un revolver calibre 38 siendo aproximadamente las 7 de la noche del domingo cuando se dirig\u00eda a atender un garaje en el sector de Villa Mar\u00eda.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Margaro quien pertenece al elenco de humoristas del Show del Medio D\u00eda, explic\u00f3 a Jos\u00e9 Antonio Aybar, Kenny Vald\u00e9z y Jos\u00e9 Peguero que recibi\u00f3 las 5 estocadas en distintas partes de su cuerpo, brazos, pecho, espalda y sus dedos.<\/p>\n<p>Los delincuentes lograron perforar uno de los pulmones Nicol\u00e1s, pero gracias a Dios encuentra estable, posiblemente le den de alta en las pr\u00f3ximas 48 horas.<\/p>\n<p>El humorista pidi\u00f3 a la poblaci\u00f3n dominicana que se cuiden de los menores que andan atracando en las calles.<\/p>\n<p>Vacilando La Tarde se transmite de lunes a viernes por Ne\u00f3n 89.3 FM de 4 a de la tarde.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo. El humorista Nicol\u00e1s D\u00edaz (Margaro) es la nueva v\u00edctima en la ola de atracos que azota la Rep\u00fablica Dominicana. El programa Vacilando La Tarde que se transmite por Ne\u00f3n 89.3 FM pudo contactar al artista quien explic\u00f3 que dos j\u00f3venes aparentemente menores de edad le dieron 5 pu\u00f1aladas y le despojaron de un revolver calibre 38 siendo aproximadamente las 7 de la noche del domingo cuando se dirig\u00eda a atender un garaje en el sector de Villa Mar\u00eda.<\/p>\n","protected":false},"author":3,"featured_media":26822,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-26823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=26823"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26823\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/26822"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=26823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=26823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=26823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}