{"id":27227,"date":"2013-06-07T13:12:51","date_gmt":"2013-06-07T17:12:51","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/parejas-que-se-conocen-en-internet-duran-mas-estudio\/"},"modified":"2013-06-07T13:12:51","modified_gmt":"2013-06-07T17:12:51","slug":"parejas-que-se-conocen-en-internet-duran-mas-estudio","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/parejas-que-se-conocen-en-internet-duran-mas-estudio\/","title":{"rendered":"Parejas que se conocen en Internet duran m\u00e1s (estudio)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-27226\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/06\/sosua_images_parejas-que-se-conocen-en-Internet.jpg\" width=\"275\" height=\"183\" alt=\"parejas-que-se-conocen-en-Internet\" class=\"caption\" style=\"float: left;\" \/>Curioso estudio este que se\u00f1ala que las parejas sentimentales que se conocen online suelen evitar m\u00e1s el divorcio y duran m\u00e1s en el tiempo.<\/p>\n<p>  <!--more-->  <\/p>\n<p>El informe ha sido elaborado por la Academia Nacional de las Ciencias en Estados Unidos, que ha analizado a 20.000 personas que se casaron durante 2005 y 2012. Seg\u00fan el organismo,&nbsp;<strong>el 35% de estas parejas se conocieron en Internet<\/strong>&nbsp;y s\u00f3lo el 7% se han separado ya.<\/p>\n<p>El porcentaje de divorcio fue algo mayor entre las personas que no se hab\u00edan conocido en internet.<\/p>\n<p>Cabe destacar que&nbsp;<strong>el porcentaje de matrimonios que se produjeron gracias a Internet ya supera el tercio del total<\/strong>.<\/p>\n<p>El informe tambi\u00e9n analiza en qu\u00e9 plataformas se conocen las parejas m\u00e1s duraderas. Por ejemplo, aquellos que se conocieron gracias a eHarmony son los m\u00e1s felices, mientras que los que no encontraron la felicidad deseada fueron los que coincidieron gracias a Yahoo!<\/p>\n<p>El informe analiza todo tipo de sitios en los que se puede conocer a otra persona gracias a Internet, incluidos foros, juegos online, chats y por supuesto, p\u00e1ginas de contactos.<\/p>\n<p>Todos los resultados indican que conocerse en Internet da m\u00e1s posibilidades a la pareja de perdurar, \u00bfpor qu\u00e9? Seg\u00fan algunos expertos, porque las personas<strong>&nbsp;se toman m\u00e1s tiempo para conocerse<\/strong>&nbsp;y realizan una selecci\u00f3n m\u00e1s exhaustiva a priori.<\/p>\n<p><a href=\"http:\/\/www.trecebits.com\/2013\/06\/05\/las-parejas-que-se-conocen-en-internet-duran-mas\/\" target=\"_blank\">Fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Curioso estudio este que se\u00f1ala que las parejas sentimentales que se conocen online suelen evitar m\u00e1s el divorcio y duran m\u00e1s en el tiempo.<\/p>\n","protected":false},"author":3,"featured_media":27226,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-27227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/27227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=27227"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/27227\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/27226"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=27227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=27227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=27227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}