{"id":27269,"date":"2013-06-09T14:06:10","date_gmt":"2013-06-09T18:06:10","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/alegria-en-puerto-plata-odebrech-construira-carretera-4-carriles\/"},"modified":"2013-06-09T14:06:10","modified_gmt":"2013-06-09T18:06:10","slug":"alegria-en-puerto-plata-odebrech-construira-carretera-4-carriles","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/alegria-en-puerto-plata-odebrech-construira-carretera-4-carriles\/","title":{"rendered":"Alegr\u00eda en Puerto Plata, Odebrech construir\u00e1 carretera 4 carriles"},"content":{"rendered":"<div><b><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-27268\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/06\/sosua_images_carretera_4_carriles.jpg\" width=\"300\" height=\"194\" alt=\"carretera_4_carriles\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/06\/sosua_images_carretera_4_carriles.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/06\/sosua_images_carretera_4_carriles-400x260.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>PUERTO PLATA.-<\/b>La adjudicaci\u00f3n de la construcci\u00f3n de la carretera Puerto Plata-Navarrete a la empresa Odebrecht de Brasil por el gobierno del presidente Danilo Medina ha producido inmensa alegr\u00eda entre los puertoplate\u00f1os, que desde hace a\u00f1os han venido demandando la ejecuci\u00f3n de esa obra.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<p> <a name=\"more\" target=\"_blank\"><\/a><br \/>Tanto pronto se conoci\u00f3 la noticia del otorgamiento de la obra a la citada empresa carioca, se han producido decenas de llamadas a los medios de comunicaci\u00f3n locales saludando la medida y, al mismo tiempo, demandando que ese proyecto sea puesto en marcha cuanto antes para que sea concluida antes de finalizar la gesti\u00f3n del actual gobernante. <\/p>\n<div>Agradecieron al gobierno del presidente Medina la decisi\u00f3n de rescindir el contrato para la ejecuci\u00f3n de esa autov\u00eda a la empresa Colombiana DOVICON, por ser altamente lesivo al inter\u00e9s nacional y por su decisi\u00f3n de readjudicar esa obra para que su construcci\u00f3n sea iniciada a la mayor brevedad posible.<\/div>\n<div>Los puertoplate\u00f1os que han expresado su satisfacci\u00f3n por el otorgamiento de la obra a&nbsp;la Odebrechtesperan que los trabajos comiencen desde Puerto Plata hacia Navarrete y no al rev\u00e9s, para que, por lo menos, el tramo Puerto Plata-Maim\u00f3n se complete a tiempo para ser inaugurado junto con la terminal de cruceros que construir\u00e1&nbsp;la Carnival&nbsp;en Maim\u00f3n.<\/div>\n<div>Creen que la ejecuci\u00f3n de esa obra garantiza que se registre un incremento del flujo de turistas desde Santiago, el resto del Cibao y otros puntos del pa\u00eds, lo que contribuir\u00e1 a un mejoramiento de la ocupaci\u00f3n de los hoteles del destino Puerto Plata, el cual se ha venido deprimiendo y perdiendo competitividad frente a otros destinos tur\u00edsticos.<\/div>\n<div>El conocimiento de la adjudicaci\u00f3n de la construcci\u00f3n Puerto Plata-Navarrete se conoci\u00f3 a trav\u00e9s de una cr\u00edtica hecha por la Fundaci\u00f3n Justicia y Transparencia (FJT) al Gobierno por haber asignado, sin concurso, a la compa\u00f1\u00eda&nbsp;brasile\u00f1a ODEBRECHT&nbsp;la carretera Navarrete-Puerto Plata, en la que el Estado invertir\u00e1&nbsp;varios cientos de millones de d\u00f3lares.<\/div>\n<div>En su cr\u00edtica al gobierno, el presidente de la entidad, Trajano Potentini, dijo que la referida obra estaba asignada originalmente a la empresa VIADOM, a la cual le fue&nbsp;rescindido el contrato y entregada \u00a8grado a grado\u00bb a la empresa brasile\u00f1a.<\/div>\n<div>En su cuestionamiento a la medida Potentini llam\u00f3 a las autoridades de Obras P\u00fablicas a \u201cdescontinuar la pr\u00e1ctica de asignar obras sin concurso, ya que eso viola la ley 340-06 sobre compra y contrataciones de bienes y servicios con el Estado. Resalt\u00f3 que la&nbsp;ODEBRECHT&nbsp; ha manejado en los \u00faltimos a\u00f1os mas del 80% de las megas obras del Estado Dominicano\u201d.<\/div>\n<div>Record\u00f3 que, en violaci\u00f3n a las leyes, a&nbsp;esa firma brasile\u00f1a tambi\u00e9n le fue adjudicada&nbsp; la reparaci\u00f3n y ampliaci\u00f3n de la carretera San Pedro-Romana, concesi\u00f3n que anteriormente pertenec\u00eda a CODACSA.<\/div>\n<div>No obstante su cr\u00edtica,&nbsp;la Fundaci\u00f3n Justicia&nbsp;y Transparencia&nbsp;reconoci\u00f3 la importancia y trascendencia de los trabajos de reconstrucci\u00f3n y ampliaci\u00f3n de las referidas v\u00edas, indispensables para el desarrollo del Cibao, pero reclam\u00f3 el respeto a las leyes y apego a la institucionalidad<\/div>\n<div><\/div>\n<div><\/div>\n<div>Manuel Emilio Gilbert<\/div>\n<div>fuente: sacandomelao.com&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>PUERTO PLATA.-La adjudicaci\u00f3n de la construcci\u00f3n de la carretera Puerto Plata-Navarrete a la empresa Odebrecht de Brasil por el gobierno del presidente Danilo Medina ha producido inmensa alegr\u00eda entre los puertoplate\u00f1os, que desde hace a\u00f1os han venido demandando la ejecuci\u00f3n de esa obra.<\/p>\n","protected":false},"author":3,"featured_media":27268,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-27269","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/27269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=27269"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/27269\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/27268"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=27269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=27269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=27269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}