{"id":27271,"date":"2013-06-09T14:13:31","date_gmt":"2013-06-09T18:13:31","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/irealmente-comer-parado-da-indigestion\/"},"modified":"2013-06-09T14:13:31","modified_gmt":"2013-06-09T18:13:31","slug":"irealmente-comer-parado-da-indigestion","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/irealmente-comer-parado-da-indigestion\/","title":{"rendered":"\u00bfRealmente comer parado da indigesti\u00f3n?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-27270\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/06\/sosua_images_comer_parado45745245.jpg\" width=\"600\" height=\"400\" alt=\"comer_parado45745245\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/06\/sosua_images_comer_parado45745245.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/06\/sosua_images_comer_parado45745245-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>Parecer\u00eda que cada vez hay menos tiempo para disfrutar de un buen almuerzo. Ya casi no hay esa \u00abhora de comer\u00bb, incluso en Francia, donde los tradicionales entrada, plato fuerte y postre han sido remplazados por emparedados y comida r\u00e1pida.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>Si uno est\u00e1 apurado y agarra algo r\u00e1pido, la tendencia es pensar que al menos hay que sentarse a com\u00e9rselo, as\u00ed sea sent\u00e1ndose en un bus camino a la siguiente cita.<\/p>\n<p>Si no, seguro que le dar\u00e1 indigesti\u00f3n.<\/p>\n<p>Pero, \u00bfes cierto?<\/p>\n<p><strong>A veces es bueno estar de pie<\/strong><\/p>\n<p>Cuando uno se fija en la lista de las causas de la indigesti\u00f3n o dispepsia funcional, como se le llama en la literatura m\u00e9dica, comer parado no figura.<\/p>\n<p>Tras descartar causas probables como \u00falceras estomacales y gastritis, el manejo de la dispepsia puede incluir cambios en el estilo de vida pero eso se refiere a comer sano, no fumar y reducir el consumo de alcohol y caf\u00e9. No significa sentarse cuando uno come.<\/p>\n<p>De hecho, los doctores recomiendan lo opuesto, si la causa del dolor es reflujo gastroesof\u00e1gico, cuando el \u00e1cido del est\u00f3mago sube al es\u00f3fago. En ese caso, la gravedad puede ayudar: mantenerse erguido durante y despu\u00e9s de comer puede mantener a los jugos g\u00e1stricos donde deben estar.<\/p>\n<p>Por esa misma raz\u00f3n, a los pacientes que sufren de reflujo se les aconseja levantar la cabecera de su cama, para que duerman inclinados hacia adelante.<\/p>\n<p>Pero hay un problema con comer de pie.<\/p>\n<p><strong>Devorar en vez de comer<\/strong><\/p>\n<p>Cuando uno est\u00e1 parado hace las cosas m\u00e1s r\u00e1pido, de ah\u00ed la tendencia de algunas compa\u00f1\u00edas de instalar mesas altas para que las reuniones se hagan de pie, despu\u00e9s de que un estudio determinara que las reuniones en las que los asistentes est\u00e1n sentados se demoran un 34% m\u00e1s.<\/p>\n<p>As\u00ed que quiz\u00e1s el riesgo de comer sin sentarse sea la tentaci\u00f3n de engullirse la comida a una velocidad que provoque indigesti\u00f3n.<\/p>\n<p>Hay muy pocos estudios que comparan a gente que come r\u00e1pido y despacio, en parte porque ser\u00eda dif\u00edcil obligar a la gente a comer a una velocidad espec\u00edfica todas las comidas.<\/p>\n<p>Un estudio de 1994, sin embargo, incluy\u00f3 preguntas sobre la velocidad al comer en una encuesta sobre h\u00e1bitos alimenticios. Encontr\u00f3 que la velocidad en la que la gente cree que come no estaba ligada a la frecuencia con que le daba indigesti\u00f3n. Otro estudio hecho en 2010 lleg\u00f3 a la misma conclusi\u00f3n, pero esos dos estudios dependen de la habilidad de la gente de juzgar la velocidad con precisi\u00f3n y de reportarla honestamente.<\/p>\n<p>El problema fue superado en una investigaci\u00f3n hecha en Corea del Sur en la que se midi\u00f3 cu\u00e1nto tiempo le tomaba comer a un grupo de cadetes que estaban en entrenamiento en la Academia de enfermer\u00eda de las Fuerzas Armadas.<\/p>\n<p>Con una vida regimentada, en la que se despertaban, com\u00edan y hac\u00edan ejercicio al mismo tiempo, eran el grupo ideal para este tipo de estudio.<\/p>\n<p>La \u00fanica diferencia en su rutina diaria era la velocidad con la que cada persona com\u00eda. Una vez m\u00e1s, si se examina el estudio en detalle, la velocidad con la que com\u00edan no parece tener ning\u00fan efecto en la digesti\u00f3n.<\/p>\n<p>Y, \u00bfqu\u00e9 pasa con los verdaderos expertos en comer r\u00e1pido, los comedores competitivos?<\/p>\n<p><strong>Abundante y raudo<\/strong><\/p>\n<p>Un estadounidense conocido como Pete el Furioso se gana la vida comiendo r\u00e1pido y ostenta cuatro r\u00e9cords Guinness, el m\u00e1s reciente por devorarse una pizza de 12 pulgadas en 41,31 segundos.<\/p>\n<p>Otro rompe r\u00e9cords es el japon\u00e9s Takeru Kobayashi, quien se comi\u00f3 58 salchichas Bratwurst (las gordas) en 10 minutos.<\/p>\n<p>Sin duda eso es lo suficientemente r\u00e1pido para causar indigesti\u00f3n&#8230; pero aparentemente no.<\/p>\n<p>El radi\u00f3logo Marc Levine, del hospital de la Universidad de Pensilvania, le tom\u00f3 rayos X al est\u00f3mago de un campe\u00f3n luego de que se engull\u00f3 36 perros calientes en 10 minutos.<\/p>\n<p>El participante quer\u00eda seguir comiendo despu\u00e9s de tragarse la salchicha&nbsp;<a href=\"http:\/\/search.twitter.com\/search?q=%2336\">#36<\/a>, pero se decidi\u00f3 terminar el estudio por su seguridad.<\/p>\n<p>No se indigest\u00f3, pero el desafortunado hombre que se prest\u00f3 como voluntario para ser el sujeto de control, se sinti\u00f3 enfermo tras el s\u00e9ptimo perro caliente y tuvo que terminar.<\/p>\n<p>El examen con rayos X mostr\u00f3 que el comedor competitivo hab\u00eda entrenado a su est\u00f3mago a expandirse a tal punto que ya no se sent\u00eda lleno cuando com\u00eda.<\/p>\n<p>Y eso nos lleva a lo que podr\u00eda ser el problema de comer r\u00e1pido: no es que produzca indigesti\u00f3n, sino que perturba al mecanismo que usualmente nos hace sentir llenos.<\/p>\n<p>No obstante, incluso en este caso, la evidencia es inconsistente. Algunos estudios apuntan a que comer r\u00e1pido hace que sintamos m\u00e1s hambre, lo que nos lleva a comer m\u00e1s. Pero otros muestran lo opuesto.<\/p>\n<p>As\u00ed que la pr\u00f3xima vez que no tenga tiempo para sentarse a almorzar, no se sienta tan mal por devorarse la comida demasiado r\u00e1pido: mientras no se sienta enfermo, parece que no hace da\u00f1o.<\/p>\n<p>Fuente:<a href=\"http:\/\/www.bbc.co.uk\/mundo\/noticias\/2013\/06\/130605_mitos_medicos_comer_parado_finde.shtml\" title=\"http:\/\/www.bbc.co.uk\/mundo\/noticias\/2013\/06\/130605_mitos_medicos_comer_parado_finde.shtml\" rel=\"nofollow\">http:\/\/www.bbc.co.uk\/mundo\/noticias\/2013\/06\/130605_mitos_medicos_comer_p&#8230;<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Parecer\u00eda que cada vez hay menos tiempo para disfrutar de un buen almuerzo. Ya casi no hay esa \u00abhora de comer\u00bb, incluso en Francia, donde los tradicionales entrada, plato fuerte y postre han sido remplazados por emparedados y comida r\u00e1pida.<\/p>\n","protected":false},"author":3,"featured_media":27270,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-27271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/27271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=27271"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/27271\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/27270"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=27271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=27271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=27271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}