{"id":27295,"date":"2013-06-09T14:23:18","date_gmt":"2013-06-09T18:23:18","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/segun-estudio-el-exito-y-la-forma-de-la-cara-estan-relacionados\/"},"modified":"2013-06-09T14:23:18","modified_gmt":"2013-06-09T18:23:18","slug":"segun-estudio-el-exito-y-la-forma-de-la-cara-estan-relacionados","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/segun-estudio-el-exito-y-la-forma-de-la-cara-estan-relacionados\/","title":{"rendered":"Segun estudio, el \u00e9xito y la forma de la cara est\u00e1n relacionados"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-27294\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/06\/sosua_images_cara-exito.jpg\" width=\"600\" height=\"400\" alt=\"cara-exito\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/06\/sosua_images_cara-exito.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/06\/sosua_images_cara-exito-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>Los hombres con \u00e9xito tienen ciertos rasgos diferenciales en su rostros, seg\u00fan ha demostrado un estudio de la Universidad de Sussex (Reino Unido) que publica la revista British Journal of Psychology.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>La investigaci\u00f3n se basa en la proporci\u00f3n facial del ancho por el largo de la cara o \u00edndice FWH, por sus siglas en ingl\u00e9s, que se obtiene dividiendo la distancia horizontal m\u00e1xima del extremo derecho y el izquierdo del rostro entre la distancia que separa la zona superior del labio del punto m\u00e1s alto de las cejas. Pues bien, seg\u00fan los cient\u00edficos, las caras masculinas que asociamos a personas m\u00e1s dominantes y exitosas son aquellas con un ratio FWH alto, es decir, m\u00e1s anchas que largas. Por el contrario, tendemos a asociar los rostros alargados con una limitada capacidad de liderazgo y menores niveles de \u00e9xito.<\/p>\n<p>Seg\u00fan Jamie Ward, coautor del trabajo, hay dos posibles explicaciones a este hallazgo. Un opci\u00f3n es que el FWH sea realmente un indicador visible de la personalidad dominante de un individuo, dado que tambi\u00e9n se asocia a ciertos niveles de testosterona. La otra posibilidad es que los humanos tendamos a escoger como l\u00edderes a individuos con el rostro ancho.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los hombres con \u00e9xito tienen ciertos rasgos diferenciales en su rostros, seg\u00fan ha demostrado un estudio de la Universidad de Sussex (Reino Unido) que publica la revista British Journal of Psychology.<\/p>\n","protected":false},"author":3,"featured_media":27294,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-27295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/27295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=27295"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/27295\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/27294"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=27295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=27295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=27295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}