{"id":27553,"date":"2013-06-19T11:53:52","date_gmt":"2013-06-19T15:53:52","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/miami-le-gana-a-los-spurs-y-obliga-un-7mo-juego-decisivo-ver-videos\/"},"modified":"2013-06-19T11:53:52","modified_gmt":"2013-06-19T15:53:52","slug":"miami-le-gana-a-los-spurs-y-obliga-un-7mo-juego-decisivo-ver-videos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/miami-le-gana-a-los-spurs-y-obliga-un-7mo-juego-decisivo-ver-videos\/","title":{"rendered":"Miami le gana a los Spurs y obliga un 7mo juego decisivo (VER VIDEOS)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-27552\" alt=\"6to_juego_gana_miami\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/06\/sosua_images_6to_juego_gana_miami.jpg\" width=\"436\" height=\"257\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/06\/sosua_images_6to_juego_gana_miami.jpg 436w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/06\/sosua_images_6to_juego_gana_miami-300x176.jpg 300w\" sizes=\"auto, (max-width: 436px) 100vw, 436px\" \/>MIAMI.- Lo lamentar\u00e1 San Antonio. Porque ganaba por cinco puntos con 28 segundos por jugar y ya acariciaba su quinto anillo. Pero enfrente hay un gran campe\u00f3n. LeBron James y Ray Allen metieron un triple cada uno y llevaron el partido a suplementario. Tras empatar en 95, Miami gan\u00f3 103-100 y llev\u00f3 esta dram\u00e1tica serie a un s\u00e9ptimo juego, que se har\u00e1 ma\u00f1ana, en el American Airlines.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Eric Spoelstra mantuvo la formaci\u00f3n inicial con cuatro jugadores bajos y Popovich la espej\u00f3, por lo que Manu Gin\u00f3bili volvi\u00f3 a ser titular en los Spurs. La estrategia defensiva de San Antonio no se modific\u00f3. Las marcas pusieron especial atenci\u00f3n en cerrarle la zona pintada a LeBron cada vez que intentaba penetrar. Si James descargaba para el tiro exterior, los tiradores de Miami ten\u00edan cierta ventaja, pero el objetivo ya estaba cumplido para los Spurs, que obligaron a sus rivales a tomar tiros lejanos, de menor eficacia. La marca al mejor jugador del mundo se la repartieron entre Leonard y Diaw. En el primer cuarto, los dos lo hicieron correctamente.<\/p>\n<p>El inesperado l\u00edder del ataque de los locales fue Mario Chalmers (12 tantos en la primera mitad). San Antonio se nutri\u00f3 del fant\u00e1stico comienzo de Tim Duncan, que meti\u00f3 sus primeros ocho tiros y cerr\u00f3 el primer tiempo con \u00a125 puntos!<\/p>\n<p> Lo de Duncan merece una menci\u00f3n aparte. A los 37 a\u00f1os lleg\u00f3 a esta temporada en una excelente forma f\u00edsica. Como en sus mejores tiempos. Con su paciencia y serenidad habituales fue el que mejor asimil\u00f3 la importancia de este juego. San Antonio lleg\u00f3 match point a Miami y al menos \u00e9l hizo todo lo necesario para llegar a un nuevo anillo. <\/p>\n<p>Si por la edad sus rivales en el puesto (Chris Bosh, Haslem o Andersen) tienen una ventaja atl\u00e9tica sobre \u00e9l, jam\u00e1s se not\u00f3. Los domin\u00f3 con clases de fundamentos: tiros cortos, a media distancia, volcadas, lanzamientos en 45 grados, empezando de espalda o jugando de frente al aro. Un verdadero show.<\/p>\n<p>Lo m\u00e1s importante es que todo eso sirvi\u00f3 para mantener en juego a un San Antonio, que no ten\u00eda en la ofensiva con dos de los integrantes del Big Three, Tony Parker (4 puntos en la primera mitad) y Gin\u00f3bili (0). El primer tiempo termin\u00f3 con ventaja de seis puntos para los Spurs (50-44).<\/p>\n<p>Las diez mejores jugadas de anoche<\/p>\n<p><iframe loading=\"lazy\" width=\"630\" height=\"360\" src=\"http:\/\/www.youtube.com\/embed\/D6cGX0FcWeo?feature=player_embedded\" frameborder=\"0\" allowfullscreen=\"\"><\/iframe> <\/p>\n<p>El triple Allen para ir a tiempo extra<\/p>\n<p> <iframe loading=\"lazy\" width=\"630\" height=\"360\" src=\"http:\/\/www.youtube.com\/embed\/tr6XsZVb-ZE?feature=player_embedded\" frameborder=\"0\" allowfullscreen=\"\"><\/iframe> <\/p>\n<p>Trtiple de Miller, con un solo tenis<\/p>\n<p> <iframe loading=\"lazy\" width=\"630\" height=\"360\" src=\"http:\/\/www.youtube.com\/embed\/7LDH66ja2Zc?feature=player_embedded\" frameborder=\"0\" allowfullscreen=\"\"><\/iframe> <\/p>\n<p>En la cara de Leonard<\/p>\n<p> <iframe loading=\"lazy\" width=\"630\" height=\"360\" src=\"http:\/\/www.youtube.com\/embed\/yOrvDtOG5zA?feature=player_embedded\" frameborder=\"0\" allowfullscreen=\"\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MIAMI.- Lo lamentar\u00e1 San Antonio. Porque ganaba por cinco puntos con 28 segundos por jugar y ya acariciaba su quinto anillo. Pero enfrente hay un gran campe\u00f3n. LeBron James y Ray Allen metieron un triple cada uno y llevaron el partido a suplementario. Tras empatar en 95, Miami gan\u00f3 103-100 y llev\u00f3 esta dram\u00e1tica serie a un s\u00e9ptimo juego, que se har\u00e1 ma\u00f1ana, en el American Airlines.<\/p>\n","protected":false},"author":3,"featured_media":27552,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-27553","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/27553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=27553"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/27553\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/27552"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=27553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=27553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=27553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}