{"id":27608,"date":"2013-06-23T19:45:17","date_gmt":"2013-06-23T23:45:17","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/mas-de-15-millones-de-dominicanos-viven-en-estados-unidos\/"},"modified":"2013-06-23T19:45:17","modified_gmt":"2013-06-23T23:45:17","slug":"mas-de-15-millones-de-dominicanos-viven-en-estados-unidos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/mas-de-15-millones-de-dominicanos-viven-en-estados-unidos\/","title":{"rendered":"M\u00e1s de 1.5 millones de dominicanos viven en Estados Unidos"},"content":{"rendered":"<div><strong><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-27607\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/06\/sosua_images_Ms_de_1.5_millones_de_dominicanos_viven_en_Estados_Unidos.jpg\" width=\"348\" height=\"232\" alt=\"Ms_de_1.5_millones_de_dominicanos_viven_en_Estados_Unidos\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/06\/sosua_images_Ms_de_1.5_millones_de_dominicanos_viven_en_Estados_Unidos.jpg 348w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/06\/sosua_images_Ms_de_1.5_millones_de_dominicanos_viven_en_Estados_Unidos-300x200.jpg 300w\" sizes=\"auto, (max-width: 348px) 100vw, 348px\" \/>NUEVA YORK.<\/strong>&nbsp;Un nuevo reporte sobre la poblaci\u00f3n latina en los Estados Unidos, divulgado por el Centro Piew, confirma que los dominicanos radicados en la naci\u00f3n suman 1.5 millones de habitantes o el 2.9% de la poblaci\u00f3n total.<\/div>\n<p>  <!--more-->  <\/p>\n<div>\n<p><a name=\"more\" target=\"_blank\"><\/a><br \/>El estudio sostiene que esa estad\u00edstica es v\u00e1lida hasta el 2011, un dato tambi\u00e9n refrendado por los n\u00fameros del Censo de Poblaci\u00f3n y Familia 2010.<\/p>\n<p>Explica que los dominicanos son la quinta poblaci\u00f3n hispana de mayor presencia en Estados Unidos y sit\u00faa a los mexicanos en primer lugar con 33.5 millones de habitantes (64.6%).<\/p>\n<p>El centro Piew dijo que los datos se basan en su encuesta sobre la comunidad latina en Estados Unidos realizada en el 201. A los mexicanos les siguen los puertorrique\u00f1os con alrededor de 5 millones, siendo considerado el segundo grupo latino mayor, pero en la tabulaci\u00f3n la entidad no explica que los boricuas son ciudadanos estadounidenses por nacimiento.<\/p>\n<p>El reporte sostiene que han surgido 14 subgrupos latinos entre los que figuran argentinos, nicarag\u00fcenses, espa\u00f1oles y venezolanos.<\/p>\n<p>Destaca que m\u00e1s de la mitad de los dominicanos (56%) nacieron en la Rep\u00fablica Dominicana en comparaci\u00f3n con el 36% de todos los otros hispanos que es el 13% de la poblaci\u00f3n total de Estados Unidos.<\/p>\n<p>El 64% de los inmigrantes dominicanos, lleg\u00f3 a Estados Unidos a partir de 1990 o m\u00e1s tarde y menos de la mitad, el 48%, son ciudadanos norteamericanos. El 56% habla ingl\u00e9s \u00abpro eficiente\u00bb y el 44%, entre los que est\u00e1n ni\u00f1os y ni\u00f1as de 5 a\u00f1os de edad, lo habla \u00abmenos que muy bien\u00bb en comparaci\u00f3n con el 34% de todos los hispanos.<\/p>\n<p>El reporte Piew revela que la edad promedio de los criollos en Estados Unidos es de 28 a\u00f1os y ligeramente mayor que las de los otros hispanos en general y la media de las edades de los norteamericanos nativos, que oscilan entre 37 y 27 a\u00f1os.<\/p>\n<p>Un 35% de dominicanos no est\u00e1 casado o casada, mientras el 43% de los latinos en general ha contra\u00eddo matrimonio y la poblaci\u00f3n general de Estados Unidos con un 48%.<\/p>\n<p>Las dominicanas en edades de entre 15 a 44 a\u00f1os que dieron a luz fue de un 7% en los 12 meses anteriores a la encuesta y esa tasa fue similar para todos los hispanos que es de un 8%, en tanto la estad\u00edstica global en Estados Unidos fue de un 6% de mujeres parturientas.<\/p>\n<p>Ocho de cada diez dominicanos (78%) viven en el Noreste de Estados Unidos y casi la mitad (48%) en Nueva York.&nbsp;<\/p>\n<p>En cuanto a lo acad\u00e9mico, el reporte de Piew revela que los dominicanos tienen el nivel m\u00e1s alto de la poblaci\u00f3n hispana con el 16% en edades de 25 a\u00f1os o m\u00e1s, han obtenido una licenciatura en comparaci\u00f3n con el 13% de los latinos en general y un 29% de la poblaci\u00f3n total de Estados Unidos.<\/p>\n<p>}Respecto a la situaci\u00f3n econ\u00f3mica, los dominicanos siguen siendo uno de los grupos m\u00e1s pobres de Estados Unidos con un ingreso promedio anual de $20.000 d\u00f3lares entre mayores de 16 a\u00f1os, lo mismo que los ingresos de la generalidad de los hispanos, siendo la media nacional de $29.000 d\u00f3lares al a\u00f1o.<\/p>\n<p>Un 28% de los dominicanos vive en nivel de pobreza, superior a la tasa general (16%) y ligeramente m\u00e1s alta a la de todos los dem\u00e1s hispanos que es de un 26%.<\/p>\n<p>En cuanto al seguro de salud, dos de cada diez criollos no lo tiene (21%) en comparaci\u00f3n con el 30% de los hispanos en general y el 15% de la poblaci\u00f3n general.<\/p>\n<p>Un 8% de dominicanos menores de 18 a\u00f1os no tiene seguro m\u00e9dico y la tasa de propiedad de viviendas es de un 25%, inferior a la media nacional de todos los hispanos con un 46%, mientras en la poblaci\u00f3n global de Estados Unidos es del 65%.<\/p>\n<p><a href=\"http:\/\/www.sacandomelao.com\/2013\/06\/mas-de-15-millones-de-dominicanos-viven.html\">fuente<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>NUEVA YORK.&nbsp;Un nuevo reporte sobre la poblaci\u00f3n latina en los Estados Unidos, divulgado por el Centro Piew, confirma que los dominicanos radicados en la naci\u00f3n suman 1.5 millones de habitantes o el 2.9% de la poblaci\u00f3n total.<\/p>\n","protected":false},"author":3,"featured_media":27607,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-27608","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/27608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=27608"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/27608\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/27607"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=27608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=27608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=27608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}