{"id":27742,"date":"2013-06-27T14:18:55","date_gmt":"2013-06-27T18:18:55","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/primer-testimonio-de-prince-jackson\/"},"modified":"2013-06-27T14:18:55","modified_gmt":"2013-06-27T18:18:55","slug":"primer-testimonio-de-prince-jackson","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/primer-testimonio-de-prince-jackson\/","title":{"rendered":"Primer testimonio de Prince Jackson"},"content":{"rendered":"<div id=\"ArticleSourceDiv\"><b><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-27741\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/06\/sosua_images_8BDEA59F-4481-4965-A2A4-B3730E152D75.jpg__294__440__CROPz0x294y440.jpeg\" width=\"294\" height=\"416\" alt=\"8BDEA59F-4481-4965-A2A4-B3730E152D75.jpg__294__440__CROPz0x294y440\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/06\/sosua_images_8BDEA59F-4481-4965-A2A4-B3730E152D75.jpg__294__440__CROPz0x294y440.jpeg 294w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/06\/sosua_images_8BDEA59F-4481-4965-A2A4-B3730E152D75.jpg__294__440__CROPz0x294y440-212x300.jpeg 212w\" sizes=\"auto, (max-width: 294px) 100vw, 294px\" \/>Los \u00c1ngeles.-<\/b>El hijo mayor del cantante Michael Jackson, Prince, afirm\u00f3 el mi\u00e9rcoles ante la justicia que su padre dijo varias veces, las semanas previas a su muerte en 2009, que los promotores de la gira para la que \u00e9l ensayaba en Los \u00c1ngeles lo quer\u00edan \u201cmatar\u201d.<\/div>\n<p>  <!--more-->  <\/p>\n<div id=\"ArticleBody\">\n<p>Por primera vez el adolescente proporcion\u00f3 p\u00fablicamente detalles sobre los d\u00edas previos a la muerte de su padre. Prince testific\u00f3 que vio a Murray tratando de reanimar a su padre mediante resucitaci\u00f3n cardiopulmonar mientras la mitad del cuerpo de Jackson estaba guindando a un lado de cama. Los ojos de Jackson parec\u00edan en blanco, dijo Prince al jurado.&nbsp;<\/p>\n<p>Prince Jackson dijo a los jurados que su padre quer\u00eda m\u00e1s tiempo para ensayar y que tuvo varias conversaciones telef\u00f3nicas tensas con los promotores del espect\u00e1culo que preparaba, \u201cThis Is It\u201d, que en algunos casos terminaron con el cantante en l\u00e1grimas.<\/p>\n<p>El joven de 16 a\u00f1os expres\u00f3 que luego de una de las conversaciones su padre dijo: \u201cMe van a matar\u201d. No ofreci\u00f3 detalles.<\/p>\n<p>El testimonio se produjo como parte de una demanda que alega que AEG contrat\u00f3 de manera negligente a Conrad Murray, el m\u00e9dico que luego fue condenado por homicidio involuntario por administrarle al cantante una sobredosis mortal del anest\u00e9sico propofol. AEG niega que haya contratado al m\u00e9dico o que tenga responsabilidad alguna con la muerte de Jackson. Vestido con un traje negro y una corbata gris oscuro, y con el cabello casta\u00f1o largo acomodado detr\u00e1s de las orejas, Prince testific\u00f3 que vio al director general de AEG Live, Randy Phillips, en la mansi\u00f3n que rentaba la familia en una conversaci\u00f3n tensa con Murray los d\u00edas antes de la muerte de su padre. El adolescente dijo que Phillips tom\u00f3 a Murray por el codo. Phillips \u201cme pareci\u00f3 agresivo\u201d, dijo Prince.<\/p>\n<p>Michael Jackson no se encontraba en la mansi\u00f3n en ese momento y probablemente estaba ensayando, agreg\u00f3. La abogada de Murray, Valerie Wass, y el abogado defensor de AEG, Marvin S. Putnam, negaron despu\u00e9s que el encuentro que describi\u00f3 Prince hubiera ocurrido.<\/p>\n<p>Putnam dijo que Prince ser\u00e1 convocado para declarar nuevamente ante la defensa m\u00e1s adelante en el juicio. \u201cCreo que el testimonio demostrar\u00e1 cuando sea convocado por nuestra defensa que eso no ocurri\u00f3\u201d, dijo Putnam. \u201cEra un chico de 12 a\u00f1os que despu\u00e9s ha tenido que enfrentar esta gran tragedia\u201d. Los propios ojos de Prince lucieron rojos mientras recordaba el momento en el que Murray le dijo que su padre muri\u00f3.<\/p>\n<p><b>(+)<br \/>OTROS PUNTOS CLAVES DURANTE EL JUICIO<\/b><br \/>Prince dijo que su padre siempre estaba trabajando, pero que sus hijos no ten\u00edan idea de que era una superestrella mundial. \u201cSiempre escuchamos su m\u00fasica, pero nunca supimos cu\u00e1n famoso era\u201d, dijo Prince. A\u00f1adi\u00f3 que su hermana Paris vio un video de una de las actuaciones de su padre y se hizo una idea de su fama cuando vio a admiradores&nbsp;abrumados ser retirados en camillas de sus shows.<\/p>\n<p>&nbsp;Prince es el primer miembro de la familia Jackson que testific\u00f3 en el juicio, ahora en su novena semana. Prince dijo que nunca vio el tipo de tratamiento que le daba Conrad Murray a su padre. \u201cTen\u00eda doce a\u00f1os. A mi modo de ver, se supon\u00eda que \u00e9l deb\u00eda hacer que mi padre se mantuviera saludable\u201d, testific\u00f3 Prince. \u00c9l dijo que nadie del personal que trabajaba en la casa pod\u00eda ir al piso superior.<\/p>\n<p><a href=\"http:\/\/www.listindiario.com\/\/entretenimiento\/2013\/6\/26\/282264\/Primer-testimonio-de-Prince-Jackson\">fuente<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los \u00c1ngeles.-El hijo mayor del cantante Michael Jackson, Prince, afirm\u00f3 el mi\u00e9rcoles ante la justicia que su padre dijo varias veces, las semanas previas a su muerte en 2009, que los promotores de la gira para la que \u00e9l ensayaba en Los \u00c1ngeles lo quer\u00edan \u201cmatar\u201d.<\/p>\n","protected":false},"author":3,"featured_media":27741,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-27742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/27742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=27742"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/27742\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/27741"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=27742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=27742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=27742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}