{"id":27995,"date":"2013-07-07T12:50:49","date_gmt":"2013-07-07T16:50:49","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/once-dominicanos-estaran-en-el-juego-de-estrellas-13\/"},"modified":"2013-07-07T12:50:49","modified_gmt":"2013-07-07T16:50:49","slug":"once-dominicanos-estaran-en-el-juego-de-estrellas-13","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/once-dominicanos-estaran-en-el-juego-de-estrellas-13\/","title":{"rendered":"Once dominicanos estar\u00e1n en el Juego de Estrellas \u201813"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-27994\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/07\/sosua_images_7A986958-4124-4474-894B-B7189E45782A.jpg__460__390__CROPz0x460y390_1.jpeg\" width=\"460\" height=\"361\" alt=\"7A986958-4124-4474-894B-B7189E45782A.jpg__460__390__CROPz0x460y390_1\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/07\/sosua_images_7A986958-4124-4474-894B-B7189E45782A.jpg__460__390__CROPz0x460y390_1.jpeg 460w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/07\/sosua_images_7A986958-4124-4474-894B-B7189E45782A.jpg__460__390__CROPz0x460y390_1-300x235.jpeg 300w\" sizes=\"auto, (max-width: 460px) 100vw, 460px\" \/>Once dominicanos estar\u00e1n presentes en el Juego de Estrellas del 2013 en el Citifield, de Nueva York.&nbsp;El grupo es encabezado por el intermedista de los Yanquis de Nueva York, Robinson Can\u00f3, quien asiste por cuarto a\u00f1o en forma consecutiva como titular.<\/div>\n<p> <!--more-->  <a name=\"more\"><\/a><br \/>Can\u00f3 tiene promedio de .293, con 20 jonrones y 58 remolcadas y de paso ser\u00e1 el capit\u00e1n del equipo de la Liga Americana en el Derby de Jonrones que ser\u00e1 celebrado el 15 de julio.<\/p>\n<\/p>\n<div>En la Liga Americana, junto a Can\u00f3, aparecen como titulares el bateador designado de los Medias Rojas de Boston, David Ortiz y el jardinero de los Azulejos, Jos\u00e9 Bautista.<\/div>\n<div><\/div>\n<div>Ortiz comenz\u00f3 tarde la temporada mientras se recuperaba de su tal\u00f3n de Aquiles lastimado, pero su actuaci\u00f3n equivale a la de uno que ha jugado el a\u00f1o completo al batear para .321, con 17 jonrones y 61 remolcadas.<\/div>\n<div><\/div>\n<div>Bautista, por su parte, tiene 20 cuadrangulares y 52 remolcadas, adem\u00e1s de un promedio de .264.<\/div>\n<div><\/div>\n<div>&nbsp;Como sustitutos, salen a relucir los nombres de Manny Machado, de los Orioles de Baltimore; Nelson Cruz, de los Rangers de Texas y Jhonny Peralta, de los Tigres de Detroit.<\/div>\n<div><\/div>\n<div>Bartolo Col\u00f3n tambi\u00e9n fue incluido en el grupo de lanzadores para el partido que tendr\u00e1 como abridor a Clay Buchholz.<\/div>\n<div>En el viejo circuito no hay dominicanos entre los titulares para el evento cuyo ganador obtiene el derecho de ventaja de la casa en la Serie Mundial.<\/div>\n<div><\/div>\n<div>Sin embargo, hay varios jugadores que ganaron el cr\u00e9dito para ser sustitutos.<\/div>\n<div><\/div>\n<div>Ellos son: Carlos G\u00f3mez, jardinero de los Cerveceros de Milwaukee; Jean Segura, torpedero del mismo equipo y Pedro Alvarez, el antesalista de los Piratas de Pittsburgh.<\/div>\n<div><\/div>\n<div>El partido de Estrellas se jugar\u00e1 el 16 de julio, luego de un fin de semanas de actividades.<\/div>\n<div><\/div>\n<div><strong>ZOOM<br \/>Dominicanos en el Juego de Estrellas del 2013<br \/>Liga Americana<\/strong><\/div>\n<div><strong><br \/><\/strong><\/div>\n<div>1.&nbsp; Robinson Can\u00f3<br \/>2.&nbsp; David Ortiz<br \/>3. Jos\u00e9 Bautista<br \/>4.&nbsp; Edwin Encarnaci\u00f3n (sustituto)<br \/>5.&nbsp; Nelson Cruz (sustituto)<br \/>6. Manny Machado (sustituto)<br \/>7.&nbsp; Jhonny Peralta (sustituto)<br \/>8.&nbsp; Bartolo Col\u00f3n (sustituto)<\/div>\n<div>Liga Nacional<br \/>9.&nbsp; Pedro Alvarez (sustituto)<br \/>10.&nbsp; Jean Segura (sustituto)<br \/>11. Carlos G\u00f3mez (sustituto)<\/div>\n<div><\/div>\n<div>fuente: sacandomelao.com&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Once dominicanos estar\u00e1n presentes en el Juego de Estrellas del 2013 en el Citifield, de Nueva York.&nbsp;El grupo es encabezado por el intermedista de los Yanquis de Nueva York, Robinson Can\u00f3, quien asiste por cuarto a\u00f1o en forma consecutiva como titular.<\/p>\n","protected":false},"author":3,"featured_media":27994,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-27995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/27995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=27995"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/27995\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/27994"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=27995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=27995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=27995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}