{"id":28108,"date":"2013-07-10T18:04:20","date_gmt":"2013-07-10T22:04:20","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/alex-rodriguez-enfrenta-castigo\/"},"modified":"2013-07-10T18:04:20","modified_gmt":"2013-07-10T22:04:20","slug":"alex-rodriguez-enfrenta-castigo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/alex-rodriguez-enfrenta-castigo\/","title":{"rendered":"Alex Rodr\u00edguez enfrenta castigo"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-28107\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/07\/sosua_images_Alex-Rodriguez--300x216.jpg\" width=\"300\" height=\"216\" alt=\"Alex-Rodriguez--300x216\" class=\"caption\" style=\"float: left;\" \/>Ryan Braun de los Cerveceros de Milwaukee, y \u00c1lex Rodr\u00edguez de los Yankees de Nueva York, est\u00e1n acusados de violar por segunda vez la pol\u00edtica antidopaje de la Liga de B\u00e9isbol.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La oficina del comisionado de la Liga Mayor de B\u00e9isbol estadounidense, la MLB por sus siglas en ingl\u00e9s, podr\u00eda emitir suspensiones de hasta 100 partidos para los jugadores Ryan Braun y \u00c1lex Rodr\u00edguez.<\/p>\n<p>Tanto Braun de los Cerveceros de Milwaukee, como Rodr\u00edguez de los Yankees de Nueva York, est\u00e1n acusados de violar por segunda vez la pol\u00edtica antidopaje de la MLB.<\/p>\n<p>Braun y Rodr\u00edguez se suman a otros 20 jugadores que podr\u00edan ser cesados tras el receso del Juego de Estrellas que se llevar\u00e1 a cabo la pr\u00f3xima semana.<\/p>\n<p>Aunque ni Braun ni Rodr\u00edguez han sido castigados con anterioridad, cometieron presuntamente m\u00faltiples ofensas al recibir sustancias para mejor el rendimiento en el campo.<\/p>\n<p>El 29 de junio, Braun se reuni\u00f3 con la MLB y se neg\u00f3 a colaborar con la investigaci\u00f3n. Se espera que Rodr\u00edguez se re\u00fana con el comisionado de la MLB el pr\u00f3ximo viernes.<\/p>\n<\/p>\n<p>De acuerdo a&nbsp;<a href=\"http:\/\/www.voanoticias.com\/\">voanoticias.com<\/a>, el portavoz de la MLB, Patrick Courtney, dijo a&nbsp;<em>USA TODAY<\/em>&nbsp;que la liga sigue \u201cen el medio de una investigaci\u00f3n activa\u201d y que \u201cno se han tomado decisiones\u201d de momento con respecto a las suspensiones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ryan Braun de los Cerveceros de Milwaukee, y \u00c1lex Rodr\u00edguez de los Yankees de Nueva York, est\u00e1n acusados de violar por segunda vez la pol\u00edtica antidopaje de la Liga de B\u00e9isbol.<\/p>\n","protected":false},"author":3,"featured_media":28107,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-28108","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=28108"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28108\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/28107"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=28108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=28108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=28108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}