{"id":28126,"date":"2013-07-11T19:33:48","date_gmt":"2013-07-11T23:33:48","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/asi-luce-angelina-jolie-luego-de-la-doble-mastectomia\/"},"modified":"2013-07-11T19:33:48","modified_gmt":"2013-07-11T23:33:48","slug":"asi-luce-angelina-jolie-luego-de-la-doble-mastectomia","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/asi-luce-angelina-jolie-luego-de-la-doble-mastectomia\/","title":{"rendered":"As\u00ed luce Angelina Jolie luego de la doble mastectom\u00eda"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-28125\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/07\/sosua_images_angelina-jolie-170x300.jpg\" width=\"170\" height=\"300\" alt=\"angelina-jolie-170x300\" class=\"caption\" style=\"float: left;\" \/>En mayo, Angelina Jolie sorprendi\u00f3 a todos al revelar que se hab\u00eda hecho una doble mastectom\u00eda para disminuir sus chances de contraer c\u00e1ncer de mama, algo muy normal en su familia. Su madre y su t\u00eda materna murieron por esta enfermedad, y la actriz no quiso exponerse a tan elevado riesgo.&nbsp;<\/p>\n<p>  <!--more-->  <\/p>\n<div><strong><br \/><\/strong><\/div>\n<div>\n<p><strong>\u201cNo me siento menos mujer por haberme sacado los pechos\u201d<\/strong>, hab\u00eda dicho la esposa de Brad Pitt en la columna de The New York Times. Ahora, luego de los tres meses de chequeos y cuidados m\u00e9dicos, Angelina vuelve a disfrutar de su vida. As\u00ed fue que se la vio descansando en Hawai, estaba de muy buen humor y se mostr\u00f3 tan linda como siempre.<\/p>\n<p>Luego de haberse practicado la doble mastectom\u00eda, Angelina Jolie se hizo una cirug\u00eda reconstructiva, y a juzgar por las fotos, podemos asegurar que se ve divina. Siendo fiel a su look relajado y casual, la actriz us\u00f3 una blusa de seda negra y un pantal\u00f3n del mismo color. El toque trendy fue el sombrero, que combinado con las gafas de sol masculinas, le daban un aire muy chic, seg\u00fan contexto.com<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En mayo, Angelina Jolie sorprendi\u00f3 a todos al revelar que se hab\u00eda hecho una doble mastectom\u00eda para disminuir sus chances de contraer c\u00e1ncer de mama, algo muy normal en su familia. Su madre y su t\u00eda materna murieron por esta enfermedad, y la actriz no quiso exponerse a tan elevado riesgo.&nbsp;<\/p>\n","protected":false},"author":3,"featured_media":28125,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-28126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=28126"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28126\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/28125"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=28126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=28126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=28126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}