{"id":28221,"date":"2013-07-13T13:50:34","date_gmt":"2013-07-13T17:50:34","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/estrenimiento-y-alimentacion-las-claves-para-que-todo-funcione-bien\/"},"modified":"2013-07-13T13:50:34","modified_gmt":"2013-07-13T17:50:34","slug":"estrenimiento-y-alimentacion-las-claves-para-que-todo-funcione-bien","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/estrenimiento-y-alimentacion-las-claves-para-que-todo-funcione-bien\/","title":{"rendered":"Estre\u00f1imiento y alimentaci\u00f3n, las claves para que todo funcione bien"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-28220\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/07\/sosua_images_59218.jpg\" width=\"600\" height=\"400\" alt=\"59218\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/07\/sosua_images_59218.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/07\/sosua_images_59218-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>El estre\u00f1imiento cr\u00f3nico idiop\u00e1tico es la forma m\u00e1s frecuente de estre\u00f1imiento de larga evoluci\u00f3n, podemos intentar mejorarlo con la alimentaci\u00f3n. Los trastornos de la funci\u00f3n del intestino grueso se cuentan entre las afecciones m\u00e1s comunes de nuestro tiempo. Una de cada tres personas de las sociedades desarrolladas sufre de estre\u00f1imiento cr\u00f3nico.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>Los laxantes o preparados para la regulaci\u00f3n intestinal son uno de los medicamentos m\u00e1s vendidos. El problema es que se empieza por productos suaves hasta los m\u00e1s fuertes a los cuales el organismo se habit\u00faa dejando de reaccionar ante ellos.<\/p>\n<p>Adem\u00e1s los laxantes qu\u00edmicos irritan la mucosa del intestino grueso y, cuando se usan con frecuencia acaban produciendo una colitis o irritaci\u00f3n cr\u00f3nica de la mucosa intestinal dif\u00edcil de curar.<\/p>\n<p>El paso de los alimentos por los intestinos dura el doble produciendo s\u00edntomas de retenci\u00f3n en el bajo vientre y en la zona pelviana, debido al retardo en el paso por el intestino. La causa es la falta de sustancias de lastre o fibras, que a la larga dan lugar a hemorroides y congesti\u00f3n venosa.<\/p>\n<p>En lugar de productos de harina blanca utilizaremos exclusivamente productos elaborados con harina cien por cien integral.<\/p>\n<p>Los aceites vegetales engrasan y suavizan los intestinos por dentro. El arroz integral es un eficaz laxante que aporta gran cantidad de minerales y vitaminas del complejo B. Es adem\u00e1s un cereal muy diur\u00e9tico.<\/p>\n<p>El exceso de prote\u00ednas animales permanece demasiado tiempo en el intestino y provoca all\u00ed procesos de putrefacci\u00f3n que dan lugar a toxinas intestinales, las cuales alteran el normal funcionamiento de la mucosa.<\/p>\n<p>Consumir menos carne y m\u00e1s pescado azul mejorar\u00e1 notablemente la situaci\u00f3n.<\/p>\n<p>El consumo frecuente de alimentos crudos, ricos en sustancias de lastre (celulosa) a base de frutas, verduras y ensaladas, es absolutamente imprescindible.<\/p>\n<p>En todos los casos le recomendamos consultar con su m\u00e9dico, terapeuta u otro profesional de la salud competente. La informaci\u00f3n contenida en este art\u00edculo tiene una funci\u00f3n meramente informativa.<\/p>\n<p>Fuente: David Jim\u00e9nez\/&nbsp;<a href=\"http:\/\/elimpulso.com\/articulo\/estrenimiento-y-alimentacion#.UeBK6VQqmSp\" title=\"http:\/\/elimpulso.com\/articulo\/estrenimiento-y-alimentacion#.UeBK6VQqmSp\" rel=\"nofollow\">http:\/\/elimpulso.com\/articulo\/estrenimiento-y-alimentacion#.UeBK6VQqmSp<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El estre\u00f1imiento cr\u00f3nico idiop\u00e1tico es la forma m\u00e1s frecuente de estre\u00f1imiento de larga evoluci\u00f3n, podemos intentar mejorarlo con la alimentaci\u00f3n. Los trastornos de la funci\u00f3n del intestino grueso se cuentan entre las afecciones m\u00e1s comunes de nuestro tiempo. Una de cada tres personas de las sociedades desarrolladas sufre de estre\u00f1imiento cr\u00f3nico.<\/p>\n","protected":false},"author":3,"featured_media":28220,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-28221","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=28221"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28221\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/28220"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=28221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=28221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=28221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}