{"id":28281,"date":"2013-07-15T15:19:35","date_gmt":"2013-07-15T19:19:35","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/nuestro-padre-de-la-patria-fallecio-un-dia-como-hoy\/"},"modified":"2013-07-15T15:19:35","modified_gmt":"2013-07-15T19:19:35","slug":"nuestro-padre-de-la-patria-fallecio-un-dia-como-hoy","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/nuestro-padre-de-la-patria-fallecio-un-dia-como-hoy\/","title":{"rendered":"Nuestro Padre de la Patria falleci\u00f3 un d\u00eda como hoy"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-28280\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/07\/sosua_images_6a00d834518de369e20191043c2431970c-800wi67.jpg\" width=\"630\" height=\"358\" alt=\"6a00d834518de369e20191043c2431970c-800wi67\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/07\/sosua_images_6a00d834518de369e20191043c2431970c-800wi67.jpg 630w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/07\/sosua_images_6a00d834518de369e20191043c2431970c-800wi67-300x170.jpg 300w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/>Santo Domingo. El a\u00f1o que transcurre fue designado en honor a la memoria del patricio Juan Pablo Duarte, en ocasi\u00f3n del bicentenario de su nacimiento.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Juan Pablo Duarte y D\u00edez naci\u00f3 el 26 de enero de 1813, y falleci\u00f3 el 15 de julio de 1876, a los 63 a\u00f1os de edad, en Venezuela.<\/p>\n<p>Desde el pasado a\u00f1o, se integr\u00f3 una comisi\u00f3n para las actividades relativas a la celebraci\u00f3n del bicentenario. Desde enero pasado, las autoridades, as\u00ed como entidades privadas, han desarrollado una serie de actividades para exaltar la obra de Juan Pablo Duarte.<\/p>\n<p>El m\u00e9rito de Duarte, como patriota y como pol\u00edtico organizador, estriba, fundamentalmente, en que supo interpretar el momento hist\u00f3rico que viv\u00eda la sociedad dominicana de aquel entonces, renuente en sus capas m\u00e1s decisivas a aceptar la dominaci\u00f3n haitiana.<\/p>\n<p>fuente: diariolibre.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo. El a\u00f1o que transcurre fue designado en honor a la memoria del patricio Juan Pablo Duarte, en ocasi\u00f3n del bicentenario de su nacimiento.<\/p>\n","protected":false},"author":3,"featured_media":28280,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-28281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=28281"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28281\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/28280"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=28281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=28281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=28281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}