{"id":28356,"date":"2013-07-18T18:41:37","date_gmt":"2013-07-18T22:41:37","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/los-accidentes-sexuales-mas-extranos\/"},"modified":"2013-07-18T18:41:37","modified_gmt":"2013-07-18T22:41:37","slug":"los-accidentes-sexuales-mas-extranos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/los-accidentes-sexuales-mas-extranos\/","title":{"rendered":"Los accidentes sexuales m\u00e1s extra\u00f1os"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-28355\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/07\/sosua_images_accidentes_sexuales678.jpg\" width=\"600\" height=\"400\" alt=\"accidentes_sexuales678\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/07\/sosua_images_accidentes_sexuales678.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/07\/sosua_images_accidentes_sexuales678-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>Nos dio curiosidad conocer los accidentes sexuales m\u00e1s inusuales, as\u00ed que buscamos en la web y descubrimos estas curiosas situaciones que no le deseamos ni a nuestro peor enemigo.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p><strong>10. Kamatorados<\/strong><\/p>\n<p>Una pareja rusa recibi\u00f3 como regalo una copia del Kamasutra y decidieron intentar una complicada pose en la que los pies de la mujer quedan debajo de las axilas de su pareja. El poderoso orgasmo de la mujer de 51 a\u00f1os atrap\u00f3 el pene de su hombre (de 56) y ya no se pudieron despegar.<\/p>\n<p>Dos horas despu\u00e9s llamaron a una ambulancia. La mujer tuvo incluso que someterse a una cirug\u00eda pero ambos aventureros terminaron perfectamente sanos.<\/p>\n<p><strong>9. Besos sordos<\/strong><\/p>\n<p>Aparentemente, una mujer en China se qued\u00f3 sorda por dos meses despu\u00e9s de que su pareja la besara con tanta fuerza que cre\u00f3 un vac\u00edo en su boca que le afect\u00f3 el t\u00edmpano. Aunque no es permanente, los doctores en China recomiendan besar con cuidado.<\/p>\n<p><strong>8. Demasiado picante<\/strong><\/p>\n<p>Una se\u00f1ora se vio en la penosa necesidad de acudir al m\u00e9dico por un ardor en la vagina que ocurri\u00f3 despu\u00e9s de que su pareja le hiciera sexo oral. Pero el ardor no fue causado por una infecci\u00f3n vaginal, sino porque el chico hab\u00eda comido algo muy picante justo antes del acto.<\/p>\n<p><strong>7. Brackets y sexo oral<\/strong><\/p>\n<p>Es relativamente com\u00fan, pero lo estamos incluyendo en la lista por si no se les hab\u00eda ocurrido. El sexo oral y los brackets no se llevan. Aunque ciertamente se puede ser muy cuidadoso al momento de tener sexo oral cuando uno de los dos tiene brackets, existen casos de accidentes en los que los aparatos rasgan la piel.<\/p>\n<p><strong>6. Me robas el aliento (literalmente)<\/strong><\/p>\n<p>Uno de los casos de asfixia autoer\u00f3tica m\u00e1s conocido es el de Michael Hutchence de la banda INXS. El artista fue encontrado sin vida en un cuarto de hotel, desnudo y con un cinto alrededor de su cuello.<\/p>\n<p>La falta de ox\u00edgeno puede provocar erecciones intensas en los hombres. El m\u00e9todo de asfixia er\u00f3tica era utilizado hace siglos para solucionar la disfunci\u00f3n er\u00e9ctil sin embargo, se estima que entre 250 y mil personas mueren a causa de este fetiche en Estados Unidos anualmente (as\u00ed que no es tan raro, pero definitivamente vale la pena mencionarlo).<\/p>\n<p><strong>5. El chupet\u00f3n de la muerte<\/strong><\/p>\n<p>El verdadero problema es la intensidad con la que se succiona. Al igual que con el beso, una mujer sufri\u00f3 de un peque\u00f1o derrame cerebral cuando su pareja le hizo un chupet\u00f3n con tanta fuerza que cre\u00f3 un co\u00e1gulo en su brazo.<\/p>\n<p><strong>4. Una papa en el trasero<\/strong><\/p>\n<p>\u00bfQu\u00e9 tienen las papas que provocan que la gente se las inserte en lugares extra\u00f1os? Ya hab\u00edamos escuchado de las papas en la vagina para evitar violaciones, pero un sacerdote brit\u00e1nico tuvo que acudir al hospital cuando supuestamente estaba colgando cortinas en su cocina desnudo y se resbal\u00f3 cayendo encima de una papa que se le ator\u00f3 en el recto.<\/p>\n<p>Por nuestra parte podemos pensar en muchas otras frutas, verduras y tub\u00e9rculos con formas mucho m\u00e1s f\u00e1licas. \u00a1No que insertar comida en el ano o la vagina sea recomendable! Pero de todas formas\u2026<\/p>\n<p><strong>3. Karma<\/strong><\/p>\n<p>Esta historia est\u00e1 de ver para creer. Un hombre estaba teniendo un amor\u00edo con su secretaria. Estaban estacionados mientras ella le hac\u00eda sexo oral cuando una camioneta se impact\u00f3 con su coche. El golpe hizo que la amante cerrara la mand\u00edbula, arranc\u00e1ndole el pene.<\/p>\n<p>Lo m\u00e1s curioso de todo fue que el hombre estaba siendo monitoreado por un investigador privado que contrat\u00f3 su esposa, as\u00ed que todo el incidente se encuentra en video.<\/p>\n<p><strong>2. Sexo en el auto<\/strong><\/p>\n<p>Normalmente tener sexo en el auto es peligroso porque te puedes A) torcer, B) quedar sin pene como el se\u00f1or del punto 6, C) vergonzosamente pasar la noche en la c\u00e1rcel si te cachan los polic\u00edas o D) todas las anteriores, pero en el caso de dos adolescentes australianos el problema fue que hac\u00eda tanto fr\u00edo que decidieron prender el auto, estacionado en la cochera cerrada, para calentarse.<\/p>\n<p>Murieron de envenenamiento por mon\u00f3xido de carbono.<\/p>\n<p><strong>1. Coca\u00edna en el pene<\/strong><\/p>\n<p>Esto nos suena a \u201cR\u00e9quiem 2\u201d, pero es la historia real de un hombre que sol\u00eda inyectarse coca\u00edna en el pene para tener erecciones m\u00e1s duraderas, pero en una ocasi\u00f3n se le pas\u00f3 la mano y su erecci\u00f3n dur\u00f3 tres d\u00edas antes de que \u00e9l decidiera recibir atenci\u00f3n m\u00e9dica. Desarroll\u00f3 co\u00e1gulos en los genitales, brazos, piernas, espalda y pecho. Por la gangrena le tuvieron que amputar ambas piernas, el pene y nueve dedos.<\/p>\n<p>Fuente:&nbsp;<a href=\"http:\/\/diariodecaracas.com\/vida-sana\/los-10-accidentes-sexuales-mas-extranos\" title=\"http:\/\/diariodecaracas.com\/vida-sana\/los-10-accidentes-sexuales-mas-extranos\">http:\/\/diariodecaracas.com\/vida-sana\/los-10-accidentes-sexuales-mas-extr&#8230;<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nos dio curiosidad conocer los accidentes sexuales m\u00e1s inusuales, as\u00ed que buscamos en la web y descubrimos estas curiosas situaciones que no le deseamos ni a nuestro peor enemigo.<\/p>\n","protected":false},"author":3,"featured_media":28355,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-28356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=28356"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28356\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/28355"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=28356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=28356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=28356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}