{"id":28412,"date":"2013-07-20T13:50:18","date_gmt":"2013-07-20T17:50:18","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/usar-tacones-podria-deformar-los-pies\/"},"modified":"2013-07-20T13:50:18","modified_gmt":"2013-07-20T17:50:18","slug":"usar-tacones-podria-deformar-los-pies","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/usar-tacones-podria-deformar-los-pies\/","title":{"rendered":"Usar tacones podr\u00eda deformar los pies"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-28411\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/07\/sosua_images_Tacones-rojos_ESTIMA20121226_0006_12.jpg\" width=\"600\" height=\"400\" alt=\"Tacones-rojos_ESTIMA20121226_0006_12\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/07\/sosua_images_Tacones-rojos_ESTIMA20121226_0006_12.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/07\/sosua_images_Tacones-rojos_ESTIMA20121226_0006_12-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>El encargado del Departamento de Medicina F\u00edsica y Rehabilitaci\u00f3n del Hospital General Regional No. 1 Vicente Guerrero del IMSS en M\u00e9xico, Jos\u00e9 Luis Beltr\u00e1n D\u00e1valos, dijo que las mujeres son m\u00e1s vulnerables a deformidades en los pies, al utilizar zapatos con tacones de hasta 15 cent\u00edmetros de altura.<\/p>\n<p>  <!--more-->  <\/p>\n<div>El zapato ideal es con tac\u00f3n de cuatro cent\u00edmetros m\u00e1ximo, el calzado es indispensable para la vida cotidiana, ya que protege los pies de las agresiones del medio ambiente y del entorno.<\/div>\n<div>\n<p>Sin embargo, las mujeres adem\u00e1s del uso necesario, lo utilizan como un accesorio, que en ocasiones llega a ser inadecuado y afecta en forma considerable ambas extremidades.<\/p>\n<p>El m\u00e9dico especialista en Ortopedia explic\u00f3 que la caracter\u00edstica principal por lo que la mayor\u00eda de los zapatos son utilizados por las mujeres es porque contribuyen a verse bien vestidas y estilizar al m\u00e1ximo su figura, sin interesarse en los posibles da\u00f1os f\u00edsicos a corto y largo plazo.<\/p>\n<p>Actualmente un porcentaje considerable de mujeres utilizan zapatos con tacones arriba de 15 cent\u00edmetros, que adem\u00e1s de elevar la estatura de las personas, incrementan el riesgo de sufrir lesiones y accidentes.<\/p>\n<p>El hacer uso por tiempo prolongado de este tipo de calzado, altera la naturaleza del pie y ocasiona graves da\u00f1os que van m\u00e1s all\u00e1 de la cuesti\u00f3n est\u00e9tica: callos, juanetes, inflamaci\u00f3n en la planta o parte inferior del pie y dolor en la uni\u00f3n de los dedos con el pie.<\/p>\n<p>\u201cPara la anatom\u00eda y fisonom\u00eda adecuada del pie, y que este funcione de forma adecuada, el tac\u00f3n debe tener una elevaci\u00f3n de tres cent\u00edmetros a dos cent\u00edmetros y medio\u201d, refiri\u00f3. A\u00f1adi\u00f3 que del tal\u00f3n a la parte anterior del pie, debe tener soporte del lado medial, para que los m\u00fasculos de la parte de la planta no est\u00e9n en tensi\u00f3n. Los zapatos que se elevan m\u00e1s all\u00e1 empiezan a desplazar el peso del cuerpo hacia la parte anterior y el principal que sufre es el dedo gordo\u201d.<\/p>\n<p>Otra de las consecuencias de ponerse zapatos muy altos es el cambio del punto de equilibrio del cuerpo y la p\u00e9rdida de estabilidad al pisar, que pueden derivar en ca\u00eddas con consecuencias severas y ocasionar fracturas de brazo, mu\u00f1eca o codo, y en menor frecuencia, de rodillas o caderas (lesiones por transferencia o a distancia).<\/p>\n<p>Dijo que es necesario que antes de comprar un par de zapatos, se tome en cuenta el tipo de pie que se tiene, sano o con alguna deformidad, ya que nunca se pone atenci\u00f3n en esta parte tan importante del cuerpo.<\/p>\n<p><strong><\/strong><\/p>\n<p>Fuente:&nbsp;<a title=\"http:\/\/www.eluniversal.com.mx\/ciencia\/2013\/tacones-deformar-los-pies-79189.html\" href=\"http:\/\/www.eluniversal.com.mx\/ciencia\/2013\/tacones-deformar-los-pies-79189.html\">http:\/\/www.eluniversal.com.mx<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El encargado del Departamento de Medicina F\u00edsica y Rehabilitaci\u00f3n del Hospital General Regional No. 1 Vicente Guerrero del IMSS en M\u00e9xico, Jos\u00e9 Luis Beltr\u00e1n D\u00e1valos, dijo que las mujeres son m\u00e1s vulnerables a deformidades en los pies, al utilizar zapatos con tacones de hasta 15 cent\u00edmetros de altura.<\/p>\n","protected":false},"author":3,"featured_media":28411,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-28412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=28412"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28412\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/28411"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=28412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=28412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=28412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}