{"id":28481,"date":"2013-07-23T20:23:01","date_gmt":"2013-07-24T00:23:01","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/los-yankees-interesados-en-soriano\/"},"modified":"2013-07-23T20:23:01","modified_gmt":"2013-07-24T00:23:01","slug":"los-yankees-interesados-en-soriano","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/los-yankees-interesados-en-soriano\/","title":{"rendered":"Los Yankees interesados en Soriano"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-28480\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/07\/sosua_images_soriano463.png\" width=\"65\" height=\"90\" alt=\"soriano463\" class=\"caption\" style=\"float: left;\" \/>Los&nbsp;<a href=\"http:\/\/espndeportes.espn.go.com\/beisbol\/mlb\/equipo\/_\/nombre\/nyy\/new-york-yankees\">Yankees de Nueva York<\/a>&nbsp;han estado pendientes del jardinero de los&nbsp;<a href=\"http:\/\/espndeportes.espn.go.com\/beisbol\/mlb\/equipo\/_\/nombre\/chc\/chicago-cubs\">Cachorros de Chicago<\/a><a href=\"http:\/\/espndeportes.espn.go.com\/beisbol\/mlb\/jugador\/_\/id\/3993\/alfonso-soriano\">Alfonso Soriano<\/a>&nbsp;y podr\u00edan estar cerca de adquirirlo, seg\u00fan confirm\u00f3 una fuente de Grandes Ligas este lunes.<\/p>\n<p>  <!--more--> Tim Naehring, asistente principal del gerente de los Yankees Brian Cashman, ha estado pendiente de los jugadores de Chicago desde el viernes en Colorado. Naehring, considerado uno de los mejores evaluadores en el juego, sigui\u00f3 a los Cachorros a Arizona, donde juegan una serie de cuatro juegos esta semana. <\/p>\n<p>Una fuente de Grandes Ligas confirm\u00f3 que los Yankees est\u00e1n en b\u00fasqueda de bateo debido al estatus incierto de&nbsp;<a href=\"http:\/\/espndeportes.espn.go.com\/beisbol\/mlb\/jugador\/_\/id\/3246\/derek-jeter\">Derek Jeter<\/a>&nbsp;y&nbsp;<a href=\"http:\/\/espndeportes.espn.go.com\/beisbol\/mlb\/jugador\/_\/id\/3115\/alex-rodriguez\">Alex Rodr\u00edguez<\/a>, quienes se encuentran en la lista de lesionados por lastimaduras. Rodriguez tambi\u00e9n encara una posible suspensi\u00f3n por sus alegados v\u00ednculos con la cl\u00ednica Biogenesis.<\/p>\n<p>Soriano, de 37 a\u00f1os, comenz\u00f3 su carrera de Grandes Ligas con los Yankees en 1999. Fue cambiado a los&nbsp;<a href=\"http:\/\/espndeportes.espn.go.com\/beisbol\/mlb\/equipo\/_\/nombre\/tex\/texas-rangers\">Vigilantes de Texas<\/a>&nbsp;por Rodr\u00edguez el 2 de febrero del 2004, particip\u00f3 en dos temporadas con los Vigilantes, y una con los&nbsp;<a href=\"http:\/\/espndeportes.espn.go.com\/beisbol\/mlb\/equipo\/_\/nombre\/wsh\/washington-nationals\">Nacionales de Washington<\/a>&nbsp;antes de firmar con los Cachorros en noviembre del 2006. Al entrar a esta temporada, le quedaba un a\u00f1o de contrato en su acuerdo de ocho a\u00f1os y $136 millones.<\/p>\n<p>Soriano tambi\u00e9n tiene control de veto de 10-5 de cualquier cambio que los Cachorros intenten hacer. Cualquier jugador con 10 a\u00f1os en las Grandes Ligas y cinco con el mismo equipo tiene este control de veto. En el verano pasado \u00e9l rechaz\u00f3 un cambio que lo habr\u00eda enviado a los&nbsp;<a href=\"http:\/\/espndeportes.espn.go.com\/beisbol\/mlb\/equipo\/_\/nombre\/sf\/san-francisco-giants\">Gigantes de San Francisco<\/a>.<\/p>\n<p>\u00abNi siquiera pienso en eso [en un cambio]\u00bb, dijo Soriano cuando se le pregunt\u00f3 sobre su estatus antes del juego del lunes. \u00abEstamos a 22 de julio, y me gusta pensar que estamos en agosto. No me gusta escuchar mi nombre en discusiones de cambios en la fecha l\u00edmite\u00bb.<\/p>\n<p>Soriano respond\u00eda preguntas sobre el cambio de&nbsp;<a href=\"http:\/\/espndeportes.espn.go.com\/beisbol\/mlb\/jugador\/_\/id\/28528\/matt-garza\">Matt Garza<\/a>&nbsp;y su efecto en otros cambios que los Cachorros quieren hacer, y desconoc\u00eda del inter\u00e9s de los Yankees en \u00e9l cuando se le pregunt\u00f3 sobre ello el lunes en Arizona. Soriano ha dicho en numerosas ocasiones que le gustar\u00eda quedarse con los Cachorros, aunque la tentaci\u00f3n de volver a Nueva York y finalizar su carrera donde comenz\u00f3 podr\u00eda ser algo dif\u00edcil de resistir.<\/p>\n<p>Soriano se encuentra a 11 hits de los 2,000 en su carrera, y a 11 cuadrangulares de los 400. Batea .256 con 17 jonrones y 51 remolcadas esta temporada.<\/p>\n<p>fuente: ESPN<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los&nbsp;Yankees de Nueva York&nbsp;han estado pendientes del jardinero de los&nbsp;Cachorros de ChicagoAlfonso Soriano&nbsp;y podr\u00edan estar cerca de adquirirlo, seg\u00fan confirm\u00f3 una fuente de Grandes Ligas este lunes.<\/p>\n","protected":false},"author":3,"featured_media":28480,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-28481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=28481"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28481\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/28480"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=28481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=28481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=28481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}