{"id":28541,"date":"2013-07-29T18:13:54","date_gmt":"2013-07-29T22:13:54","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/la-terrible-confesion-de-psy-el-cantante-de-gangnam-style-que-sorprende-al-mundo\/"},"modified":"2013-07-29T18:13:54","modified_gmt":"2013-07-29T22:13:54","slug":"la-terrible-confesion-de-psy-el-cantante-de-gangnam-style-que-sorprende-al-mundo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-terrible-confesion-de-psy-el-cantante-de-gangnam-style-que-sorprende-al-mundo\/","title":{"rendered":"La terrible confesi\u00f3n de Psy, el cantante de Gangnam Style, que sorprende al mundo"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-28540\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/07\/sosua_images_Psy-300x179.jpg\" width=\"300\" height=\"179\" alt=\"Psy-300x179\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/07\/sosua_images_Psy-300x179.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/07\/sosua_images_Psy-300x179-500x300.jpg 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>COREA DEL SUR.-<strong>Se hizo famoso cuando su&nbsp;Gangnam Style&nbsp;fue furor en todo el mundo, y el pasito de baile del hit se convirti\u00f3 en toda una sensaci\u00f3n. Ahora, con nuevo tema musical que busca tenerlo en la cima del podio nuevamente,&nbsp;Psy&nbsp;confes\u00f3 que es alcoh\u00f3lico.<\/strong><\/p>\n<p>  <!--more-->  <\/p>\n<div><strong><br \/><\/strong><\/div>\n<div>\n<div><strong>\u201cBebo todo el tiempo. Si estoy feliz, bebo. Si estoy triste, bebo. Si el d\u00eda amanece soleado, bebo. Si amanece lluvioso, tambi\u00e9n\u201d<\/strong>, cont\u00f3 el el cantante surcoreano en una entrevista para The Sunday Times Magazine.<\/div>\n<div><\/div>\n<div>Psy&nbsp;dijo adem\u00e1s que el \u00fanico momento que est\u00e1 sobrio es cuando amanece con mucha resaca,&nbsp;<strong>\u201calgo que sucede frecuentemente\u201d.<\/strong><\/div>\n<div><strong><br \/><\/strong><\/div>\n<div><\/div>\n<div><strong>Destaca ElIntransigente que entre las bebidas favoritas del cantante, se encuentra el vodka coreano destilado, al que defini\u00f3 como \u201csu mejor amigo y compa\u00f1ero de vicio\u201d. Tambi\u00e9n es un fiel seguidor del whisky y el tequila.<\/strong><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>COREA DEL SUR.-Se hizo famoso cuando su&nbsp;Gangnam Style&nbsp;fue furor en todo el mundo, y el pasito de baile del hit se convirti\u00f3 en toda una sensaci\u00f3n. Ahora, con nuevo tema musical que busca tenerlo en la cima del podio nuevamente,&nbsp;Psy&nbsp;confes\u00f3 que es alcoh\u00f3lico.<\/p>\n","protected":false},"author":3,"featured_media":28540,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-28541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=28541"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28541\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/28540"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=28541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=28541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=28541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}