{"id":28709,"date":"2013-08-07T12:47:20","date_gmt":"2013-08-07T16:47:20","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/triple-choque-deja-dos-jovenes-gravemente-heridos-en-pueblo-nuevo-sosua\/"},"modified":"2013-08-07T12:47:20","modified_gmt":"2013-08-07T16:47:20","slug":"triple-choque-deja-dos-jovenes-gravemente-heridos-en-pueblo-nuevo-sosua","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/triple-choque-deja-dos-jovenes-gravemente-heridos-en-pueblo-nuevo-sosua\/","title":{"rendered":"Triple choque deja dos j\u00f3venes gravemente heridos en Pueblo Nuevo, Sos\u00faa"},"content":{"rendered":"<p>Sos\u00faa.- Un aparatoso accidente ocurrido pasado las 5:00 Pm de este pasado martes dej\u00f3 el saldo de dos j\u00f3venes gravemente heridos, en momentos en que estos a bordo de una motocicleta color rojo &nbsp;impactaran una jeepeta desliz\u00e1ndose y cayendo debajo de un cami\u00f3n patana.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Los nombres de los heridos se desconocen, pero se afirman residen en la comunidad de cangrejos, mientras que el conductor de una jeepeta color gris emprendi\u00f3 la huida, el tercer veh\u00edculo es un cami\u00f3n patana propiedad de la empresa MERCASID, color gris, ficha F-40, conducido por Raymundo Vald\u00e9s.<\/p>\n<p>Los heridos fueron trasladados de emergencia al Centro M\u00e9dico Cabarete.<\/p>\n<p>fuente: detrasdelrumor.com&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sos\u00faa.- Un aparatoso accidente ocurrido pasado las 5:00 Pm de este pasado martes dej\u00f3 el saldo de dos j\u00f3venes gravemente heridos, en momentos en que estos a bordo de una motocicleta color rojo &nbsp;impactaran una jeepeta desliz\u00e1ndose y cayendo debajo de un cami\u00f3n patana.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-28709","post","type-post","status-publish","format-standard","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=28709"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28709\/revisions"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=28709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=28709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=28709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}