{"id":28753,"date":"2013-08-11T15:33:55","date_gmt":"2013-08-11T19:33:55","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/ise-puede-vivir-sin-sexo\/"},"modified":"2013-08-11T15:33:55","modified_gmt":"2013-08-11T19:33:55","slug":"ise-puede-vivir-sin-sexo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ise-puede-vivir-sin-sexo\/","title":{"rendered":"\u00bfSe puede vivir sin sexo?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-28752\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/08\/sosua_images_5961_Mujer-sin-sexo-.jpg\" width=\"600\" height=\"400\" alt=\"5961_Mujer-sin-sexo-\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/08\/sosua_images_5961_Mujer-sin-sexo-.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/08\/sosua_images_5961_Mujer-sin-sexo--300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>La asexualidad, a la que muchos consideran una nueva orientaci\u00f3n sexual, est\u00e1 ganando terreno en el mundo. Son las personas que eligen vivir sin tener sexo. Una mujer de 26 a\u00f1os relata c\u00f3mo es vivir sin los placeres de las relaciones sexuales.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>Seg\u00fan un estudio brit\u00e1nico sobre el tema, se estima que entre el 1% y el 5% de la poblaci\u00f3n de todo el mundo no practica el sexo. No est\u00e1n enfermos, ni lo hacen por motivos morales o religiosos: ellos se definen como asexuales y afirman que no sienten ninguna atracci\u00f3n sexual por otros individuos ni de su mismo sexo ni hacia el g\u00e9nero opuesto.<\/p>\n<p>Las personas asexuales, cuando tienen pareja, crean un lazo afectivo diferente hacia el otro y esto no implica tener sexo. Los asexuales se involucran sentimentalmente con otras personas a trav\u00e9s de relaciones rom\u00e1nticas que no difieren mucho de la amistad, porque est\u00e1 ausente el componente f\u00edsico.<\/p>\n<p><strong>El sexo y la salud<\/strong><\/p>\n<p>Johanna Villamil es una joven colombiana que se desempe\u00f1a como artista y gestora cultural. Se declara asexual y afirma: \u00abPienso que las opciones a la hora de relacionarnos son muy limitadas, s\u00f3lo puedes ser amigo o tener una relaci\u00f3n rom\u00e1ntica, que no es lo mismo que un v\u00ednculo con sexo\u00bb, declar\u00f3 al diario El Mundo.<\/p>\n<p>Dice que este sentimiento de asexualidad se origin\u00f3 en ella a los 20 a\u00f1os, \u00abCuando estaba leyendo el libro &#8216;La filosof\u00eda de Andy Warhol&#8217; para una clase de arte. Me sent\u00ed identificada con las reflexiones que hac\u00eda sobre el sexo y el amor; me di cuenta que hab\u00eda alguien que pensaba y sent\u00eda lo mismo que yo, y esto me impuls\u00f3 a buscar m\u00e1s personas. As\u00ed fue como llegu\u00e9 a la asexualidad\u00bb, declar\u00f3.<\/p>\n<p><strong>El sitio oficial de los asexuales<\/strong><\/p>\n<p>Los asexuales quieren hacerse o\u00edr y defender sus derechos, por eso han creado un sitio en la red: Asexual Visibility and Education Network (AVEN) una comunidad virtual que se est\u00e1 expandiendo en todo el mundo.<\/p>\n<p>\u00abLa web tiene varios objetivos. Por un lado, queremos tener un lugar de encuentro para nosotros, donde podamos conocer a m\u00e1s personas y crecer como comunidad. El segundo es tener un espacio de educaci\u00f3n para nosotros y para quienes est\u00e9n interesados. Actualmente, en la versi\u00f3n hispanoamericana tenemos a 2,000 personas afiliadas y contamos con 300 visitas diarias\u00bb, dice Villamil, una de las impulsoras del sitio.<\/p>\n<p>\u00abEstamos inmersos en una sociedad en donde el amor, el sexo y la intimidad son inseparables la una de la otra. Si no tienes sexo es dif\u00edcil imaginar c\u00f3mo acceder al amor y, mucho menos, tener intimidad con alguien. En nuestra comunidad, se\u00f1ala, pensamos que la intimidad es un factor importante dentro de una relaci\u00f3n, y afortunadamente, hay m\u00e1s v\u00edas para generar intimidad aparte del sexo\u201d.<\/p>\n<p>La comunidad asexual cree que en un mundo cada vez m\u00e1s sexualizado, el n\u00famero de personas que disfrutan m\u00e1s de una intimidad no-sexual est\u00e1 aumentando.<\/p>\n<p><strong>\u00bfQu\u00e9 es la asexualidad?<\/strong><\/p>\n<p>Existen pocos estudios cient\u00edficos dedicados a la asexualidad. El investigador Anthony Bogaert, de la Universidad de Brock (Ontario, Canad\u00e1) fue uno de los que m\u00e1s estudi\u00f3 el tema. Public\u00f3 en \u201cThe Journal of Sex Research\u201d el resultado de un estudio brit\u00e1nico con 18,000 personas, donde observ\u00f3 que el 1% de los encuestados manifest\u00f3 que nunca hab\u00eda sentido atracci\u00f3n sexual por otra persona.<\/p>\n<p>Bogaert define a la asexualidad como el estado de no tener ninguna atracci\u00f3n sexual por uno u otro sexo. Es decir, es la falta de una verdadera orientaci\u00f3n sexual, en la cual un individuo presenta poca o ninguna atracci\u00f3n sexual hacia varones o hembras.<\/p>\n<p>Seg\u00fan su orientaci\u00f3n rom\u00e1ntica, algunos asexuales se definen a s\u00ed mismos como heterosexuales, homosexuales o bisexuales, pero esto est\u00e1 relacionado con el concepto de orientaci\u00f3n afectiva, no sexual.<\/p>\n<p>El Kinsey Institute (fundado por Alfred Kinsey) realiz\u00f3 un peque\u00f1o estudio sobre el tema de la asexualidad, donde concluy\u00f3 que: \u201cLos asexuales parecen caracterizarse m\u00e1s por un escaso deseo y excitaci\u00f3n sexual que por niveles bajos de comportamiento sexual o niveles altos de represi\u00f3n sexual\u201d.<\/p>\n<p><strong>Asexualidad y religi\u00f3n<\/strong><\/p>\n<p>Seg\u00fan las creencias cristianas, aunque la Biblia no explica nada acerca de la vida sexual o privada, los \u00e1ngeles ser\u00edan asexuales, ya que no mantendr\u00edan relaciones sexuales de ning\u00fan tipo.<\/p>\n<p>La asexualidad es diferente que el celibato, los votos de castidad que realizan monjas y sacerdotes. Aunque la creencia popular es que a los asexuales les resultar\u00eda m\u00e1s f\u00e1cil llevar a cabo el celibato, dada su ausencia de atracci\u00f3n sexual.<\/p>\n<p>Fuente:&nbsp;<a href=\"http:\/\/salud.univision.com\/es\/salud-sexual\/se-puede-vivir-sin-sexo\" title=\"http:\/\/salud.univision.com\/es\/salud-sexual\/se-puede-vivir-sin-sexo\">http:\/\/salud.univision.com\/es\/salud-sexual\/se-puede-vivir-sin-sexo<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La asexualidad, a la que muchos consideran una nueva orientaci\u00f3n sexual, est\u00e1 ganando terreno en el mundo. Son las personas que eligen vivir sin tener sexo. Una mujer de 26 a\u00f1os relata c\u00f3mo es vivir sin los placeres de las relaciones sexuales.<\/p>\n","protected":false},"author":3,"featured_media":28752,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-28753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=28753"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28753\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/28752"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=28753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=28753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=28753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}