{"id":28757,"date":"2013-08-11T15:53:04","date_gmt":"2013-08-11T19:53:04","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/cerveza-en-sobres-pa-darse-un-jumo-en-todos-lados\/"},"modified":"2013-08-11T15:53:04","modified_gmt":"2013-08-11T19:53:04","slug":"cerveza-en-sobres-pa-darse-un-jumo-en-todos-lados","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/cerveza-en-sobres-pa-darse-un-jumo-en-todos-lados\/","title":{"rendered":"Cerveza en sobres pa&#8217; darse un jumo en todos lados"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-28756\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/08\/sosua_images_134555_kuxlarge_1_principal.jpg\" width=\"600\" height=\"400\" alt=\"134555_kuxlarge_1_principal\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/08\/sosua_images_134555_kuxlarge_1_principal.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/08\/sosua_images_134555_kuxlarge_1_principal-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>La compa\u00f1\u00eda de bebidas concentradas Pat&#8217;s Backcountry, ha creado una genial manera de llevar la cerveza a todas partes, se trata de cerveza en sobres de 41 mililitros que se convierten en \u00abfrias\u00bb con s\u00f3lo a\u00f1adir agua y un agente carb\u00f3nico.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>El sistema est\u00e1 basado en una botella de pl\u00e1stico similar a las utilizadas en l ciclismo o monta\u00f1ismo, se llama \u00abCarbonator\u00bb. Esta botella es un recipiente a presi\u00f3n que convierte cualquier l\u00edquido en una bebida carb\u00f3nica. El gas para preparar la cerveza se obtiene del contenido de los sobrecitos, una mezcla de bicarbonato de potasio y \u00e1cido c\u00edtrico, que al agregar agua y agitar, produce burbujas de CO2.<\/p>\n<p>Para el concentrado de cerveza, la compa\u00f1\u00eda no utiliz\u00f3 el m\u00e9todo de deshidrataci\u00f3n habitual, sino un sistema de destilaci\u00f3n completamente natural que no necesita de mucha agua. Se trata de un jarabe con un contenido alcoh\u00f3lico de 49 grados.<\/p>\n<p>Entonces, para preparar la cerveza, basta con mezclar los contenidos del sobre de concentrado de cerveza, el del gas y agua bien fr\u00eda dentro del Carbonator, agitar bien fuerte y listo, la \u00abchela\u00bb viajera estar\u00e1 lista para ser ingerida. La cerveza obtenida tiene 5.2 grados de alcohol y su sabor resulta satisfactorio.<\/p>\n<p>Las ventajas m\u00e1s obvias de estas cervezas, es que por su bajo peso y presentaci\u00f3n en sobre, pueden ser transportadas a cualquier lugar y en grandes cantidades para abastecer a cualquier paladar cervecero respetable. Adem\u00e1s de que evita altercados que involucren botellas de vidrio y borrachos en medio del bosque.<\/p>\n<p>Un paquete con 4 sobres de cerveza cuesta 9.95 d\u00f3lares y el Carbonator unos 29.95 d\u00f3lares.<\/p>\n<p> <center><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"http:\/\/www.youtube.com\/embed\/MLkjZ_RMeKA\" frameborder=\"0\" allowfullscreen=\"\"><\/iframe><\/center> <\/p>\n<p>Fuente:&nbsp;<a href=\"http:\/\/www.sdpnoticias.com\/sorprendente\/2013\/08\/10\/cerveza-en-sobres-para-tomar-en-todos-lados\" title=\"http:\/\/www.sdpnoticias.com\/sorprendente\/2013\/08\/10\/cerveza-en-sobres-para-tomar-en-todos-lados\">http:\/\/www.sdpnoticias.com\/sorprendente\/2013\/08\/10\/cerveza-en-sobres-par&#8230;<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La compa\u00f1\u00eda de bebidas concentradas Pat&#8217;s Backcountry, ha creado una genial manera de llevar la cerveza a todas partes, se trata de cerveza en sobres de 41 mililitros que se convierten en \u00abfrias\u00bb con s\u00f3lo a\u00f1adir agua y un agente carb\u00f3nico.<\/p>\n","protected":false},"author":3,"featured_media":28756,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-28757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=28757"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28757\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/28756"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=28757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=28757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=28757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}