{"id":28803,"date":"2013-08-13T15:12:10","date_gmt":"2013-08-13T19:12:10","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/martes-13-imala-suerte\/"},"modified":"2013-08-13T15:12:10","modified_gmt":"2013-08-13T19:12:10","slug":"martes-13-imala-suerte","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/martes-13-imala-suerte\/","title":{"rendered":"Martes 13: \u00bfmala suerte?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-28802\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/08\/sosua_images_gato-mala-suerte-300x166.jpg\" width=\"300\" height=\"166\" alt=\"gato-mala-suerte-300x166\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/08\/sosua_images_gato-mala-suerte-300x166.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/08\/sosua_images_gato-mala-suerte-300x166-400x220.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Una tendencia marcada por la superstici\u00f3n lo abrig\u00f3 durante a\u00f1os con un halo oscuro y muchos llegaron a creer que cuando el n\u00famero coincid\u00eda con el d\u00eda martes, la mala suerte perdurar\u00eda durante toda una jornada cada vez que el calendario marcara su llegada.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Sin embargo, el martes 13 ya no est\u00e1 encasillado como ese d\u00eda opacado por eventos desafortunados, sino todo lo contrario.<\/p>\n<p>Incluso, quienes se dedican a estudiar disciplinas alternativas, como la parapsicolog\u00eda, el tarotismo, la numerolog\u00eda y hasta la metaf\u00edsica, coinciden que justamente hoy ser\u00e1 un d\u00eda \u00f3ptimo, en el que no faltar\u00e1n las sorpresas ni las buenas noticias debido a que justamente el tan temido n\u00famero aparece como una ecuaci\u00f3n \u201credonda\u201d, debido a su coincidencia con el a\u00f1o que transitamos.<\/p>\n<p>Azucena Ag\u00fcero Blanch es parapsic\u00f3loga y astr\u00f3loga. Desde su punto de vista, esta jornada es la que m\u00e1s suerte traer\u00e1. Es que, atendiendo a las conclusiones que arroja la numerolog\u00eda, el martes 13 no s\u00f3lo aparece en sinton\u00eda perfecta con el 2013, sino que es el \u00fanico en todo el a\u00f1o.<\/p>\n<p>\u201cLa gente tiene mucho miedo al n\u00famero 13, pero en realidad es una buena cifra\u201d, explica Ag\u00fcero Blanch y desarrolla la siguiente s\u00edntesis: si sumamos los cuatro n\u00fameros de este a\u00f1o, el resultado ser\u00e1 6. Y si sumamos las dos cifras que tiene el 13, obtendremos un 4. Entonces, si sumamos 4 m\u00e1s 6, el resultado ser\u00e1 un 10.<br \/>&nbsp;<br \/>\u201cEl n\u00famero 1 es s\u00edmbolo de prosperidad, marca el principio de algo, mientras que el 0 representa una renovaci\u00f3n eterna\u201d, asegura la parapsic\u00f3loga y contin\u00faa su fundamento. Dice que en realidad los astros han bendicido al n\u00famero y que adem\u00e1s, muchos episodios importantes en la historia de la humanidad han estado marcados por el n\u00famero 13.<\/p>\n<p><strong>El 4<\/strong>&nbsp;-suma de los dos d\u00edgitos que forman el 13- representa a los cuatro puntos cardinales, algo que es interpretado como una especie de protecci\u00f3n divina. \u201cLos chamanes, por ejemplo, bendicen los puntos cardinales con el 13\u2033, aclara Ag\u00fcero Blanch.<\/p>\n<p>Pero esto no es todo. La tan admirada Luna, objeto de inspiraci\u00f3n y fuente de luz en las horas de desvelo, da 13 vueltas a la Tierra en un a\u00f1o. En la \u00faltima Cena de Jes\u00fas, de acuerdo a la Biblia, en la mesa hab\u00eda 13 comensales.<\/p>\n<p>La mitolog\u00eda griega tambi\u00e9n tiene su cap\u00edtulo especial con este n\u00famero: Zeus es el d\u00e9cimotercer dios del Olimpo, se trata de una de las divinidades por excelencia dentro de esta creencia acu\u00f1ada en aquellas legendarias y lejanas tierras.<\/p>\n<p>En lo cotidiano, agrega Ag\u00fcero Blanch, la cifra aparece como objeto de buenos deseos y augurios. Los comerciantes, por ejemplo, aplican la \u201cregla del 13\u2033 cada vez que agregan un poco m\u00e1s a una docena de cualquier producto. Se trata de la tan bien recibida \u201cyapa\u201d.<\/p>\n<p><strong>\u201cEste es un s\u00edmbolo que trae felicidad a quien entrega un poquito m\u00e1s de lo pedido y da prosperidad a quien recibe la atenci\u00f3n. Se trata de un gesto de acercamiento que alienta a la multiplicaci\u00f3n de las energ\u00edas positivas\u201d<\/strong>, dice la astr\u00f3loga mendocina.<\/p>\n<p>Siguiendo por la l\u00ednea de las buenas noticias que puede esconder el 13, tambi\u00e9n se menciona que incluso el aguinaldo, tan necesario y esperado por cualquier trabajador, tiene una connotaci\u00f3n ligada al n\u00famero. Es, pues, el salario que viene a complementarse, por derecho, con el resto de los sueldos logrados en los 12 meses que conforman el a\u00f1o.<\/p>\n<p>Para el tarot, esta jornada tambi\u00e9n est\u00e1 alejada de todo embrujo. \u201cPara nosotros el 13 es un n\u00famero de buena suerte\u201d, considera la astr\u00f3loga y tarotista Erica Gallardo. La especialista mendocina asegura adem\u00e1s que en las cartas estos d\u00edgitos significan la muerte.<\/p>\n<p>Pero el hecho, aclara, es que \u00e9sta es considerada como una transformaci\u00f3n que se relaciona con cambios importantes desde un punto de vista positivo. Es decir, no se refiere a la muerte en s\u00ed, sino m\u00e1s bien al t\u00e9rmino de todo lo malo que nos aquejaba para reiniciar un camino lleno de luz y espiritualidad.<\/p>\n<p>Es decir, una oportunidad. \u201cEs un mito pensar que el martes 13 es sin\u00f3nimo de mala suerte. Todo lo contrario\u201d, explica Gallardo y aclara que este es un buen momento para orar y pedir por la uni\u00f3n familiar.<\/p>\n<p>Por \u00faltimo, la metaf\u00edsica tampoco atribuye nada raro, ni al 13, ni al martes. \u201cEs un d\u00eda como cualquier otro, pero depende de las creencias de las personas y de su nivel de sugesti\u00f3n respecto de la fecha\u201d, considera Luis Cohen, quien se presenta como \u201cmetaf\u00edsico\u201d.<\/p>\n<p><br clear=\"all\" \/><b>Fuente<\/b>:&nbsp;<a href=\"http:\/\/www.losandes.com.ar\/notas\/2013\/8\/13\/martes-ahora-trae-buena-suerte-731785.asp\" target=\"_blank\">http:\/\/www.losandes.com.ar<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una tendencia marcada por la superstici\u00f3n lo abrig\u00f3 durante a\u00f1os con un halo oscuro y muchos llegaron a creer que cuando el n\u00famero coincid\u00eda con el d\u00eda martes, la mala suerte perdurar\u00eda durante toda una jornada cada vez que el calendario marcara su llegada.<\/p>\n","protected":false},"author":3,"featured_media":28802,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-28803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=28803"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28803\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/28802"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=28803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=28803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=28803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}