{"id":28845,"date":"2013-08-16T17:12:15","date_gmt":"2013-08-16T21:12:15","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/dominicanos-celebran-15o-aniversario-de-la-restauracion\/"},"modified":"2013-08-16T17:12:15","modified_gmt":"2013-08-16T21:12:15","slug":"dominicanos-celebran-15o-aniversario-de-la-restauracion","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/dominicanos-celebran-15o-aniversario-de-la-restauracion\/","title":{"rendered":"Dominicanos celebran 15o aniversario de la Restauraci\u00f3n"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-28844\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/08\/sosua_images_BANDERA13.jpg\" width=\"275\" height=\"183\" alt=\"BANDERA13\" class=\"caption\" style=\"float: left;\" \/>Las autoridades nacionales y municipales desarrollar\u00e1n hoy un amplio programa de actividades en ocasi\u00f3n del 150 aniversario de la Restauraci\u00f3n de la Rep\u00fablica. Entre los actos figura la celebraci\u00f3n de un tedeum en la catedral Santiago Ap\u00f3stol al que asistir\u00e1 el presidente Danilo Medina.<\/p>\n<p>  <!--more-->  <\/p>\n<p>El acto religioso en honor a&nbsp; los pr\u00f3ceres y m\u00e1rtires de la Restauraci\u00f3n ser\u00e1 oficiado por el arzobispo de la Arquidi\u00f3cesis de Santiago, monse\u00f1or Ram\u00f3n Benito de la Rosa y Carpio.<\/p>\n<p>El jefe del Estado asistir\u00e1 a la ceremonia acompa\u00f1ado&nbsp; de miembros del gabinete, la gobernadora provincial, Aurora Toribio, y otras autoridades, representantes de instituciones pol\u00edticas, culturales y de organizaciones empresariales de la provincia.<\/p>\n<p>La informaci\u00f3n la ofreci\u00f3 el historiador Juan Daniel Balc\u00e1cer, presidente de la Comisi\u00f3n Permanente de Efem\u00e9rides Patrias.<\/p>\n<p>Balc\u00e1cer resalt\u00f3 que en todas las provincias del pa\u00eds se tributar\u00e1n hoy similares homenajes a los h\u00e9roes de la Restauraci\u00f3n a trav\u00e9s de&nbsp; actos religiosos y, entre otros, ofrendas florales en monumentos y parques.<\/p>\n<p>En estas actividades participar\u00e1n las autoridades locales y estudiantes abanderados, invitados especiales y personalidades de instituciones p\u00fablicas, privadas y culturales.<\/p>\n<p>En&nbsp; la tarde ser\u00e1 develizado en Loma de Cabrera un busto en honor al h\u00e9roe restaurador general Jos\u00e9 Cabrera, uno de los catorce patriotas que el 16 de agosto de 1863 enarbolaron, en el cerro de Capotillo, la bandera tricolor y dieron inicio a la gesta restauradora.<\/p>\n<p>Un batall\u00f3n de las Fuerzas Armadas realizar\u00e1 una parada militar y se rendir\u00e1n los&nbsp; honores de estilo&nbsp; a los h\u00e9roes de la patria.<\/p>\n<p><a href=\"http:\/\/www.puertoplatahabla.com\/articles.php?art_id=11776&amp;start=1\">fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las autoridades nacionales y municipales desarrollar\u00e1n hoy un amplio programa de actividades en ocasi\u00f3n del 150 aniversario de la Restauraci\u00f3n de la Rep\u00fablica. Entre los actos figura la celebraci\u00f3n de un tedeum en la catedral Santiago Ap\u00f3stol al que asistir\u00e1 el presidente Danilo Medina.<\/p>\n","protected":false},"author":3,"featured_media":28844,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-28845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=28845"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/28845\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/28844"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=28845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=28845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=28845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}