{"id":29083,"date":"2013-09-04T19:12:33","date_gmt":"2013-09-04T23:12:33","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/la-camara-de-diputados-aprueba-de-urgencia-el-911-y-el-codigo-civil\/"},"modified":"2013-09-04T19:12:33","modified_gmt":"2013-09-04T23:12:33","slug":"la-camara-de-diputados-aprueba-de-urgencia-el-911-y-el-codigo-civil","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-camara-de-diputados-aprueba-de-urgencia-el-911-y-el-codigo-civil\/","title":{"rendered":"La C\u00e1mara de Diputados aprueba de urgencia el 911 y el C\u00f3digo Civil"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-29082\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/09\/sosua_images_aprueban_911_y_codigo_civil.jpg\" width=\"348\" height=\"232\" alt=\"aprueban_911_y_codigo_civil\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/09\/sosua_images_aprueban_911_y_codigo_civil.jpg 348w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/09\/sosua_images_aprueban_911_y_codigo_civil-300x200.jpg 300w\" sizes=\"auto, (max-width: 348px) 100vw, 348px\" \/>SANTO DOMINGO. La C\u00e1mara de Diputados declar\u00f3 de urgencia y aprob\u00f3, en dos lecturas consecutivas, el Sistema Nacional de Atenci\u00f3n a Emergencias y Seguridad 9-1-1, y en primera lectura el nuevo C\u00f3digo Civil.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Ambas propuestas perimieron y fueron reintroducidas. El sistema 911 pasa al Senado para su ponderaci\u00f3n, y el C\u00f3digo Civil ser\u00e1 conocido en segunda lectura la pr\u00f3xima semana.<\/p>\n<p>El programa de emergencia, que se iniciar\u00e1 con recursos que aportar\u00e1 el Gobierno, en su primera etapa conllevar\u00eda una erogaci\u00f3n de RD$2,000 millones. La propuesta fue sometida por el diputado El\u00edas Serulle.<\/p>\n<p>Elpidio B\u00e1ez, presidente de la comisi\u00f3n que estudi\u00f3 el proyecto, dijo que el Estado asumir\u00e1 en principio el costo del programa, pero considera que en una segunda etapa se tendr\u00e1 que cobrar para la sostenibilidad del sistema.<\/p>\n<p>Se dispone que se reconfigurar\u00e1 todo el sistema de emergencia en el \u00e1mbito nacional, y para su implementaci\u00f3n se contempla instalar 1,000 c\u00e1maras en puntos estrat\u00e9gicos y la compra de 300 veh\u00edculos para la Polic\u00eda, 300 ambulancias y motocicletas y 200 unidades de atenci\u00f3n, lo que significa una inversi\u00f3n de m\u00e1s de RD$2,000 millones.<\/p>\n<p>C\u00f3digo Civil<\/p>\n<p>Las novedades del C\u00f3digo Civil establecen sobre el divorcio que tambi\u00e9n puede ser pronunciado por violaci\u00f3n repetida y renovada de los deberes inherentes al matrimonio; adulterio de uno de los c\u00f3nyuges; condena definitiva de uno de los c\u00f3nyuges a una pena criminal; violencia f\u00edsica o sicol\u00f3gica de un c\u00f3nyuge respecto del otro; sevicias e injurias graves cometidas por uno de los dos; embriaguez habitual o uso de drogas estupefacientes e incompatibilidad de caracteres, justificada por hechos que causan infelicidad de los c\u00f3nyuges.<\/p>\n<p>Igualmente se dispone que a petici\u00f3n de los c\u00f3nyuges, el juez podr\u00e1 limitarse a constatar en los motivos de la sentencia que existen hechos que constituyen una causa de divorcio, sin tener que especificar las acusaciones de las partes.<\/p>\n<p>El nuevo C\u00f3digo fijar\u00e1 en su art\u00edculo 236 que el c\u00f3nyuge com\u00fan en bienes, demandante o demandado en divorcio, podr\u00e1, a partir de la demanda, en todo estado de causa, tomar cualquier medida conservatoria para la preservaci\u00f3n de sus derechos. Igualmente, el divorcio s\u00f3lo surtir\u00e1 efectos cuando el c\u00f3nyuge que lo haya obtenido presente en un plazo de dos meses un requerimiento ante el oficial del estado civil para que pronuncie el divorcio y transcriba el dispositivo de la sentencia.<\/p>\n<p>A falta de un arreglo convencional entre los c\u00f3nyuges, el juez pronuncia el divorcio, ordena la liquidaci\u00f3n y la divisi\u00f3n del patrimonio com\u00fan. Se pronuncia, adem\u00e1s, sobre las solicitudes de mantenimiento en la indivisi\u00f3n o de atribuci\u00f3n preferencial y puede tambi\u00e9n conceder a uno o a los dos c\u00f3nyuges un anticipo sobre su parte de la comunidad o bienes indivisos.<\/p>\n<p>fuente: diariolibre.com&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO. La C\u00e1mara de Diputados declar\u00f3 de urgencia y aprob\u00f3, en dos lecturas consecutivas, el Sistema Nacional de Atenci\u00f3n a Emergencias y Seguridad 9-1-1, y en primera lectura el nuevo C\u00f3digo Civil.<\/p>\n","protected":false},"author":3,"featured_media":29082,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-29083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=29083"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29083\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/29082"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=29083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=29083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=29083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}