{"id":29109,"date":"2013-09-06T14:10:13","date_gmt":"2013-09-06T18:10:13","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/colgate-patenta-cepillo-de-dientes-que-liberara-droga-en-cada-cepillada\/"},"modified":"2013-09-06T14:10:13","modified_gmt":"2013-09-06T18:10:13","slug":"colgate-patenta-cepillo-de-dientes-que-liberara-droga-en-cada-cepillada","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/colgate-patenta-cepillo-de-dientes-que-liberara-droga-en-cada-cepillada\/","title":{"rendered":"Colgate patenta cepillo de dientes que liberar\u00e1 droga en cada cepillada"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-29108\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/09\/sosua_images_cepillo36u67.jpg\" width=\"600\" height=\"400\" alt=\"cepillo36u67\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/09\/sosua_images_cepillo36u67.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/09\/sosua_images_cepillo36u67-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>Para muchas personas el verdadero momento del despertar ocurre solo cuando se bebe el primer trago de caf\u00e9 por las ma\u00f1anas. Antes de eso, antes del golpe con que la cafe\u00edna los empuja al mundo, hay quienes se encuentran todav\u00eda en una suerte de limbo existencial, expulsados del sue\u00f1o y el descanso pero todav\u00eda no listos para entrar de lleno a la realidad y sus exigencias.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>Pero si a alguien no le basta con la taza o la jarra de caf\u00e9 matutino, la empresa Colgate Palmolive, que domina la industria de la higiene dental, ha patentado un cepillo de dientes que en cada cepillada liberar\u00e1 sutiles dosis de cafe\u00edna, o alg\u00fan qu\u00edmico de efecto equivalente.<\/p>\n<p>El registro describe un parche adjunto al cepillo \u201cque libera un qu\u00edmico en la boca durante su uso\u201d, de cafe\u00edna a otras dise\u00f1adas para perder peso o aliviar el dolor, aunque tambi\u00e9n remedios naturales como lavanda o canela.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Para muchas personas el verdadero momento del despertar ocurre solo cuando se bebe el primer trago de caf\u00e9 por las ma\u00f1anas. Antes de eso, antes del golpe con que la cafe\u00edna los empuja al mundo, hay quienes se encuentran todav\u00eda en una suerte de limbo existencial, expulsados del sue\u00f1o y el descanso pero todav\u00eda no listos para entrar de lleno a la realidad y sus exigencias.<\/p>\n","protected":false},"author":3,"featured_media":29108,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-29109","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=29109"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29109\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/29108"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=29109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=29109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=29109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}