{"id":29125,"date":"2013-09-08T14:42:09","date_gmt":"2013-09-08T18:42:09","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/10-alimentos-que-te-hacen-feliz\/"},"modified":"2013-09-08T14:42:09","modified_gmt":"2013-09-08T18:42:09","slug":"10-alimentos-que-te-hacen-feliz","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/10-alimentos-que-te-hacen-feliz\/","title":{"rendered":"10 alimentos que te hacen feliz"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-29124\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/09\/sosua_images_happy-woman-eating-chocolate-0710-410x290.jpg\" width=\"600\" height=\"400\" alt=\"happy-woman-eating-chocolate-0710-410x290\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/09\/sosua_images_happy-woman-eating-chocolate-0710-410x290.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/09\/sosua_images_happy-woman-eating-chocolate-0710-410x290-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>Existen algunas comidas que son muy saludables y que tambi\u00e9n tienen un poder antidepresivo, estas comidas tienen propiedades que te hacen m\u00e1s feliz. En caso que te est\u00e9s preguntando cu\u00e1les son estas maravillosas comidas, contin\u00faa leyendo, veremos 10 alimentos que te hacen feliz.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>Si bien el gusto en las comidas es subjetivo, pues a cada quien le hace feliz saborear su comida favorita y \u00e9sta es casi siempre diferente en cada uno, algunos alimentos nos har\u00e1n m\u00e1s felices a todos, sin importar tus gustos para la comida.<\/p>\n<p><strong>Alimentos que te hacen m\u00e1s feliz<\/strong><\/p>\n<p><strong>Chocolate amargo<\/strong><\/p>\n<p>Pues \u00bfa qui\u00e9n lo le hace feliz el chocolate? Adem\u00e1s de ser delicioso, tiene grandes beneficios para nosotros, uno de los m\u00e1s importantes es que ayuda a regular el flujo de sangre en el cerebro, lo que mejora nuestro humor y nuestra capacidad de concentraci\u00f3n. Un poco de chocolate har\u00e1 que te sientas m\u00e1s en\u00e9rgico y vibrante.<\/p>\n<p><strong>Mejillones<\/strong><\/p>\n<p>Es incre\u00edble la enorme cantidad de beneficios que los mejillones tienen para nosotros. Aportan grandes cantidades de vitamina B12, que ayuda a fortalecer las c\u00e9lulas del cerebro y mantenernos activos; tambi\u00e9n aportan prote\u00ednas y yodo, lo que ayuda a regular la gl\u00e1ndula tiroidea, esto nos mantiene de buen humor y en un peso saludable para nuestro cuerpo, as\u00ed como tambi\u00e9n lo hacen el zinc y el selenio que aportan los mejillones.<\/p>\n<p><strong>Papas azules<\/strong><\/p>\n<p>Las papas azules son excelentes combatientes contra la depresi\u00f3n. No s\u00f3lo tienen antioxidantes que ayudan a reducir la inflamaci\u00f3n del cerebro directamente vinculada a la depresi\u00f3n, sino que adem\u00e1s incrementan la memoria a corto plazo y ayudan a regular la gl\u00e1ndula tiroidea. Aunque son algo dif\u00edciles de encontrar, su b\u00fasqueda vale la pena.<\/p>\n<p><strong>Esp\u00e1rragos<\/strong><\/p>\n<p>Los niveles bajos de folato (\u00e1cido f\u00f3lico) y tript\u00f3fano (amino\u00e1cido esencial en la nutrici\u00f3n humana) est\u00e1n directamente relacionados con la depresi\u00f3n. Afortunadamente el esp\u00e1rrago aporta de estos dos en grandes cantidades, lo que nos hace sentir calmados y tranquilos.<\/p>\n<p><strong>Acelga<\/strong><\/p>\n<p>Este vegetal contiene mucho magnesio, esta propiedad es vital para nuestras reacciones bioqu\u00edmicas as\u00ed como tambi\u00e9n para aumentar el nivel de energ\u00eda en nuestro cuerpo. Estudios realizados hace algunos a\u00f1os demuestran que el bajo nivel de magnesio est\u00e1n directamente relacionados con la depresi\u00f3n. As\u00ed que intenta recetas como tarta de espinaca y acelga, seguro te sentir\u00e1s muy bien luego de saborearla.<\/p>\n<p><strong>Coco<\/strong><\/p>\n<p>El coco promueve el buen humor y cuida la salud del cerebro, \u00bfc\u00f3mo? Pues a trav\u00e9s de los triglic\u00e9ridos que aporta a nuestro cuerpo. Un alimento muy saludable, que nos hacen felices a todos.<\/p>\n<p><strong>Tomates<\/strong><\/p>\n<p>Los tomates tienen un antioxidante llamado licopeno, el licopeno ayuda a eliminar las inflamaciones en el cerebro y lo protege. Consumiendo tomate con aceite de oliva aseguramos una mayor absorci\u00f3n de este antioxidante que tan bien nos hace.<\/p>\n<p><strong>Huevos<\/strong><\/p>\n<p>Los huevos nos ayudan a tener energ\u00eda, la suma de sus caracter\u00edsticas nos dan suficiente energ\u00eda para tener un d\u00eda completo. El huevo contiene zinc, vitamina B, yodo, omega 3, prote\u00edna y \u00e1cido graso, todo esto los hace un alimento necesario para nuestra alimentaci\u00f3n. No dejes de incorporarlo a tus recetas, existen muchas formas diferentes de cocinar con huevo.<\/p>\n<p><strong>Miel<\/strong><\/p>\n<p>Este n\u00e9ctar dorado es un excelente alimento para nuestra salud. La miel contiene kaempferol y quercetina, que nos ayudan a evitar la depresi\u00f3n y mantener nuestro cerebro saludable. Adem\u00e1s, sustituyendo el az\u00facar por miel, puedes evitar tambi\u00e9n el sobrepeso.<\/p>\n<p><strong>Yogur griego<\/strong><\/p>\n<p>El yogur griego aporta calcio, incluso m\u00e1s calcio del que aporta la leche, esto nos ayuda a estimular los neurotransmisores del cerebro que nos hacen sentir felices. Tambi\u00e9n aporta mucha prote\u00edna y \u00e9sto nos ayuda con la p\u00e9rdida del exceso de peso.<\/p>\n<p>Fuente:&nbsp;<a href=\"http:\/\/www.elgranchef.com\/6903\/10-alimentos-que-te-hacen-feliz\" title=\"http:\/\/www.elgranchef.com\/6903\/10-alimentos-que-te-hacen-feliz\">http:\/\/www.elgranchef.com\/6903\/10-alimentos-que-te-hacen-feliz<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Existen algunas comidas que son muy saludables y que tambi\u00e9n tienen un poder antidepresivo, estas comidas tienen propiedades que te hacen m\u00e1s feliz. En caso que te est\u00e9s preguntando cu\u00e1les son estas maravillosas comidas, contin\u00faa leyendo, veremos 10 alimentos que te hacen feliz.<\/p>\n","protected":false},"author":3,"featured_media":29124,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-29125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=29125"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29125\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/29124"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=29125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=29125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=29125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}