{"id":29186,"date":"2013-09-10T14:07:04","date_gmt":"2013-09-10T18:07:04","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/icomo-detectar-una-mentira-en-whatsapp\/"},"modified":"2013-09-10T14:07:04","modified_gmt":"2013-09-10T18:07:04","slug":"icomo-detectar-una-mentira-en-whatsapp","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/icomo-detectar-una-mentira-en-whatsapp\/","title":{"rendered":"\u00bfC\u00f3mo detectar una mentira en WhatsApp?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-29185\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/09\/sosua_images_pict_435231t24534.jpg\" width=\"600\" height=\"400\" alt=\"pict_435231t24534\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/09\/sosua_images_pict_435231t24534.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/09\/sosua_images_pict_435231t24534-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>Existen indicadores que hacen posible detectar una mentira a trav\u00e9s de un mensaje digital, ya sea en una conversaci\u00f3n de whatsapp, en las redes sociales o en un sms, asegura un estudio realizado en la Universidad Brigham Young (EE UU).<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>Concretamente, se puede reconocer a un mentiroso porque tarda m\u00e1s en responder, edita m\u00e1s mientras escribe (borrando y reescribiendo) y sus mensajes son m\u00e1s cortos de lo habitual, seg\u00fan explican los autores del estudio.<\/p>\n<p>\u00abLas conversaciones digitales son un terreno que fomenta el enga\u00f1o, porque las personas pueden disimular y hacer que sus mensajes parezcan cre\u00edbles\u00bb, subraya Tom Meservy, coautor del estudio que publica la revista ACM Transactions on Management Information Systems.<\/p>\n<p>Seg\u00fan el investigador, mientras que en un contexto presencial las personas pueden detectar mentiras con precisi\u00f3n en un 54% de las ocasiones, este porcentaje desciende en la comunicaci\u00f3n digital al no poder o\u00edr la voz, ni ver la expresi\u00f3n del rostro o los gestos de las manos del interlocutor.<\/p>\n<p>En su experimento, Meservy y sus colegas trabajaron con m\u00e1s de un centenar de estudiantes universitarios que mantuvieron conversaciones con un ordenador que les formulaba decenas de preguntas.<\/p>\n<p>Al pedirles que mintieran en la mitad de sus contestaciones, los cient\u00edficos comprobaron que tardaban un 10% m\u00e1s de tiempo en escribir las respuestas falsas, y que estas \u00faltimas eran editadas muchas m\u00e1s veces.<\/p>\n<p>Con estos conocimientos, augura Meservy, se podr\u00edan crear sistemas de conversaci\u00f3n capaces de detectar mentiras en tiempo real.<\/p>\n<p>Fuente:&nbsp;<a href=\"http:\/\/www.rpp.com.pe\/2013-09-09--como-detectar-una-mentira-en-whatsapp-noticia_629292.html\" title=\"http:\/\/www.rpp.com.pe\/2013-09-09--como-detectar-una-mentira-en-whatsapp-noticia_629292.html\">http:\/\/www.rpp.com.pe\/2013-09-09&#8211;como-detectar-una-mentira-en-whatsapp-&#8230;<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Existen indicadores que hacen posible detectar una mentira a trav\u00e9s de un mensaje digital, ya sea en una conversaci\u00f3n de whatsapp, en las redes sociales o en un sms, asegura un estudio realizado en la Universidad Brigham Young (EE UU).<\/p>\n","protected":false},"author":3,"featured_media":29185,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-29186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=29186"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29186\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/29185"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=29186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=29186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=29186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}