{"id":29354,"date":"2013-09-19T19:02:41","date_gmt":"2013-09-19T23:02:41","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/escabeche-de-gallina-a-la-antigua\/"},"modified":"2013-09-19T19:02:41","modified_gmt":"2013-09-19T23:02:41","slug":"escabeche-de-gallina-a-la-antigua","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/escabeche-de-gallina-a-la-antigua\/","title":{"rendered":"Escabeche de gallina a la antigua"},"content":{"rendered":"<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-29353\" alt=\"escabeche_de_gallina\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/09\/sosua_images_escabeche_de_gallina.jpg\" width=\"320\" height=\"267\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/09\/sosua_images_escabeche_de_gallina.jpg 320w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/09\/sosua_images_escabeche_de_gallina-300x250.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>Esta es una receta de cocina que se debe preparar de un d\u00eda para otro, para lograr se integren totalmente los sabores.<\/p>\n<p>  <!--more-->  <\/p>\n<p> <center> <\/p>\n<h3>Ingredientes para escabeche de gallina a la antigua (ocho porciones)<\/h3>\n<p> <\/center> <\/p>\n<p>*Una gallina criolla entera<br \/>*Dos cebollas<br \/>*Un poro en trozos<br \/>*Un tallo de apio en trozos<br \/>*Media taza de aceite<br \/>*Un aj\u00ed amarillo sin venas ni semillas, en tiras<br \/>*Cuatro cucharadas de aj\u00ed panca molido<br \/>*Una hoja de laurel<br \/>*Un diente de ajo<br \/>*Dos clavos de olor<br \/>*Cinco ramas de or\u00e9gano<br \/>*Un cuarto de taza de vinagre rojo<br \/>*Un camote cocido, en cuartos<br \/>*Ocho aceitunas negras<br \/>*Dos huevos cocidos, en cuartos<br \/>*Granos de pimienta<br \/>*Sal al gusto<\/p>\n<\/p>\n<p> <center> <\/p>\n<h4>\u00bfC\u00f3mo se prepara escabeche de gallina a la antigua?<\/h4>\n<p> <\/center> <\/p>\n<div>En una olla y con dos litros de agua, cocinamos a fuego bajo la gallina con una cebolla en trozos, el poro, el apio, granos de pimienta y sal, durante una hora y 45 minutos aproximadamente, hasta que la carne est\u00e9 suave. Bajamos del fuego y colar, reservamos un cuarto de taza del caldo y cortamos la gallina en ocho presas.<\/div>\n<\/p>\n<div><\/div>\n<\/p>\n<div>En una olla calentamos la mitad del aceite y salteamos durante un minuto las tiras de aj\u00ed amarillo con la cebolla restante cortada a la pluma. Agregamos el aj\u00ed panca, el laurel, el ajo, los clavos de olor y una rama de or\u00e9gano. Verter el vinagre y el caldo de gallina que reservamos y dejamos hervir hasta reducir a la mitad de su volumen. Incorporamos las presas de gallina, removemos y retiramos del fuego. Sazonamos con sal y lo ba\u00f1amos con el resto del aceite. Reservamos en el refrigerador durante una noche.<\/div>\n<\/p>\n<div><\/div>\n<\/p>\n<div>Servir el camote y acomodar en cima las presas de gallina cubiertas con el escabeche. Decorar con las ramas de or\u00e9gano restante, la aceituna y los huevos.<\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta es una receta de cocina que se debe preparar de un d\u00eda para otro, para lograr se integren totalmente los sabores.<\/p>\n","protected":false},"author":3,"featured_media":29353,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-29354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=29354"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29354\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/29353"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=29354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=29354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=29354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}