{"id":29387,"date":"2013-09-21T17:05:31","date_gmt":"2013-09-21T21:05:31","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/planean-romper-record-guinness-de-twerking\/"},"modified":"2013-09-21T17:05:31","modified_gmt":"2013-09-21T21:05:31","slug":"planean-romper-record-guinness-de-twerking","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/planean-romper-record-guinness-de-twerking\/","title":{"rendered":"Planean romper r\u00e9cord Guinness de Twerking"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-29386\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/09\/sosua_images_165234_gtwerkin_principal.jpg\" width=\"600\" height=\"400\" alt=\"165234_gtwerkin_principal\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/09\/sosua_images_165234_gtwerkin_principal.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/09\/sosua_images_165234_gtwerkin_principal-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>Al parecer todav\u00eda hay gente que cree que el Twerking no tiene consecuencias, vean a Miley Cyrus, lo hizo y su prometido la dej\u00f3 y se fue a dar besos con Eiza Gonz\u00e1lez. Bueno, entre esta gente est\u00e1 Big Freedia, un artista de New Orleans que pretende romper el r\u00e9cord Guinness de Twerking este fin de semana.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>Para ello el muchach\u00f3n ha decidido invitar a 250 bailarines de Twerking al Herald Square de Manhattan, en donde mover\u00e1n sus traseros por dos minutos; Record Breaking Booty Shaking: Break the GUINNESS WORLD RECORDS\u00ae Twerk Record with Big Freedia, es el nombre del evento.<\/p>\n<p>Freedia es recordado por atacar a Miley Cyrus y su presentaci\u00f3n en los VMA&#8217;s 2013, \u00abes ofensivo para muchas personas que han estado haciendo twerking y moviendo su trasero por a\u00f1os, especialmente en la cultura negra\u00bb.<\/p>\n<p>Tranquilo, Freedia, si tu inventaste el twerking, te lo regalamos.<\/p>\n<p>\u00abCuando algo se pone de moda, todo mundo quiere subirse al barco y actuar como si lo hubiera creado. Eso es totalmente comprensible, pero ellos tienen que dar el cr\u00e9dito a quien lo merece\u00bb.<\/p>\n<p>Bueno, entonces si andan por Manhattan este pr\u00f3ximo 25 de septiembre, no duden en formar parte de este r\u00e9cord, s\u00f3lo tienen que ir a mover un poco el trasero. Esta invitaci\u00f3n no va para ti, Miley.<\/p>\n<p>Fuente:&nbsp;<a href=\"http:\/\/www.enelshow.com\/musica\/2013\/09\/19\/planean-romper-record-guinness-de-twerking\" title=\"http:\/\/www.enelshow.com\/musica\/2013\/09\/19\/planean-romper-record-guinness-de-twerking\">http:\/\/www.enelshow.com\/musica\/2013\/09\/19\/planean-romper-record-guinness&#8230;<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Al parecer todav\u00eda hay gente que cree que el Twerking no tiene consecuencias, vean a Miley Cyrus, lo hizo y su prometido la dej\u00f3 y se fue a dar besos con Eiza Gonz\u00e1lez. Bueno, entre esta gente est\u00e1 Big Freedia, un artista de New Orleans que pretende romper el r\u00e9cord Guinness de Twerking este fin de semana.<\/p>\n","protected":false},"author":3,"featured_media":29386,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-29387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=29387"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29387\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/29386"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=29387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=29387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=29387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}