{"id":29428,"date":"2013-09-25T14:51:27","date_gmt":"2013-09-25T18:51:27","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/ejercicios-para-revertir-el-dano-de-estar-sentado\/"},"modified":"2013-09-25T14:51:27","modified_gmt":"2013-09-25T18:51:27","slug":"ejercicios-para-revertir-el-dano-de-estar-sentado","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ejercicios-para-revertir-el-dano-de-estar-sentado\/","title":{"rendered":"Ejercicios para revertir el da\u00f1o de estar sentado"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-29427\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/09\/sosua_images_ejercicio-oficina.jpg\" width=\"600\" height=\"400\" alt=\"ejercicio-oficina\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/09\/sosua_images_ejercicio-oficina.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/09\/sosua_images_ejercicio-oficina-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\u00bfEres de los que deben trabajar en oficina? \u00bfTienes que permanecer sentado por largos periodos de tiempo? \u00bfDedicas ocho horas o m\u00e1s a estar frente a la computadora? Es importante que sepas que esto es muy da\u00f1ino para la salud, as\u00ed que debes hacer algo al respecto. Haz ejercicio, \u00a1incluso en la oficina!<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p><strong>Riesgo renal<\/strong><\/p>\n<p>De acuerdo con el Dr. Thomas Yates, de la Universidad de Leicester, en Reino Unido, permanecer sentado por largo rato aumenta el riesgo de enfermedades renales cr\u00f3nicas, condiciones en la que los ri\u00f1ones no son capaces de filtrar adecuadamente la sangre, lo que puede conducir a la acumulaci\u00f3n de toxinas en el cuerpo y, finalmente, insuficiencia renal cr\u00f3nica.<\/p>\n<p>A\u00fan si te levantas de forma ocasional de tu silla, tus m\u00fasculos permanecen contra\u00eddos, lo cual los obliga a un esfuerzo mayor para estirarse al momento en que regresas a alguna actividad f\u00edsica. El tip es moverte cada hora como m\u00ednimo e intentar hacer algunos ejercicios f\u00e1ciles con los que podr\u00e1s en acci\u00f3n los m\u00fasculos que no usas mientras permaneces sentado.<\/p>\n<p><strong>Ejercicios b\u00e1sicos<\/strong><\/p>\n<p><strong>Impulso de talones<\/strong><\/p>\n<p>Estira y contrae la espinilla. Puedes hacer este movimiento sentado, simplemente alza tu pie en un \u00e1ngulo de 90 grados y repite la acci\u00f3n por lo menos 30 veces. Si dispones de una banda el\u00e1stica, util\u00edzala.<\/p>\n<p><strong>Levantamiento de pierna (trasero)<\/strong><\/p>\n<p>Ponte de pie y coloca los antebrazos en tu escritorio, entonces alza tu pierna hacia atr\u00e1s en un \u00e1ngulo de 45 grados sin flexionar las rodillas. Con este sencillo movimiento fortalecer\u00e1s tu pierna y desarrollar\u00e1s los m\u00fasculos del tronco para mantener tu cuerpo erguido.<\/p>\n<p><strong>Presi\u00f3n con una pelota<\/strong><\/p>\n<p>Sentado, coloca una pelota flexible en tus rodillas y apri\u00e9tala lentamente. Sost\u00e9n por 20 segundos, descansa y repite la operaci\u00f3n. Otra variante de este ejercicio es levantar tus espinillas luego de que presiones la pelota y alternar cada pie. Con este ejercicio ayudar\u00e1s a que la r\u00f3tula trabaje correctamente, tambi\u00e9n fortalecer\u00e1s tus caderas y cuad\u00edceps.<\/p>\n<p><strong>Estiramiento de brazos<\/strong><\/p>\n<p>Levanta tus brazos lo m\u00e1s arriba que puedas, trata de tocar el cielo, esfu\u00e9rzate un poco m\u00e1s. Ahora, gira tu tronco a la derecha mientras jalas con la mano diestra tu codo izquierdo. Cambia de lado. Mueve tus mu\u00f1ecas de forma circulas y repite una vez m\u00e1s el ejercicio.<\/p>\n<p><strong>Movimiento de cadera<\/strong><\/p>\n<p>Col\u00f3cate de pie con los pies separados al mismo nivel que tus hombros. Lleva los brazos al frente sin mover las caderas, gira tu cuerpo a la derecha y a la izquierda. Mueve la cintura y siente como trabaja tu espalda. Trata de no hacer este ejercicio de forma brusca porque podr\u00edas lastimarte, ll\u00e9valo con cuidado.<\/p>\n<p>Fuente:&nbsp;<a href=\"http:\/\/www2.esmas.com\/salud\/actividad-fisica\/644861\/ejercicios-revertir-dano-estar-sentado\/\" title=\"http:\/\/www2.esmas.com\/salud\/actividad-fisica\/644861\/ejercicios-revertir-dano-estar-sentado\/\">http:\/\/www2.esmas.com\/salud\/actividad-fisica\/644861\/ejercicios-revertir-&#8230;<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfEres de los que deben trabajar en oficina? \u00bfTienes que permanecer sentado por largos periodos de tiempo? \u00bfDedicas ocho horas o m\u00e1s a estar frente a la computadora? Es importante que sepas que esto es muy da\u00f1ino para la salud, as\u00ed que debes hacer algo al respecto. Haz ejercicio, \u00a1incluso en la oficina!<\/p>\n","protected":false},"author":3,"featured_media":29427,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-29428","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=29428"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29428\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/29427"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=29428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=29428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=29428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}