{"id":29769,"date":"2013-10-15T01:32:30","date_gmt":"2013-10-15T05:32:30","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/las-nuevas-camaras-sin-espejo-y-full-frame-de-sony-te-tentaran-pronto\/"},"modified":"2013-10-15T01:32:30","modified_gmt":"2013-10-15T05:32:30","slug":"las-nuevas-camaras-sin-espejo-y-full-frame-de-sony-te-tentaran-pronto","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/las-nuevas-camaras-sin-espejo-y-full-frame-de-sony-te-tentaran-pronto\/","title":{"rendered":"Las nuevas c\u00e1maras sin espejo y Full Frame de Sony te tentar\u00e1n pronto"},"content":{"rendered":"<p data-textannotation-id=\"e44c3d5ef360825cfd4d6377f7d7c876\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-29768\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_nueva_camara_sony.jpg\" width=\"561\" height=\"353\" alt=\"nueva_camara_sony\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_nueva_camara_sony.jpg 561w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_nueva_camara_sony-300x188.jpg 300w\" sizes=\"auto, (max-width: 561px) 100vw, 561px\" \/>Dicen los especialistas en&nbsp;fotograf\u00eda&nbsp;que hay un antes y un despu\u00e9s de las c\u00e1maras con sensor de formato completo o Full Frame. Que una vez las pruebas, ya no quieres otra cosa. El \u00faltimo en pasarse a este formato equivalente a 35 mil\u00edmetros en c\u00e1maras sin espejo es Sony, con las Sony Alpha A7 y A7R.<\/p>\n<p>  <!--more-->  <\/p>\n<p data-textannotation-id=\"245f407ab97afe2a0d46302d4cc48609\">De momento no se conocen todos los detalles sobre estas bestias llamadas a ocupar alg\u00fan nicho entre las NEX y las r\u00e9flex Alpha, en el segmento de gama alta. Los primeros datos indican que estamos ante sensores de 24 y 36 magap\u00edxeles respectivamente. Ambas contar\u00e1n con adaptador para lentes E y NEX APS-C, y tambi\u00e9n con conectividad WiFi y NFC.<\/p>\n<p data-textannotation-id=\"c800181258ab34e50d9b4a9f9a275dc0\">Los precios de estas c\u00e1maras podr\u00edan estar entre los 1.700 y los 2.200 d\u00f3lares solo para el cuerpo. Con una lente 28-70mm, el precio de la m\u00e1s asequible subir\u00eda hasta los 2.000. Se prev\u00e9 que ambos modelos se presenten esta semana, as\u00ed que no faltan muchos d\u00edas para conocer sus caracter\u00edsticas m\u00e1s en detalle. [<a href=\"http:\/\/digicame-info.com\/2013\/10\/77-13.html\" target=\"_blank\" sl-processed=\"1\">DigitalCameraInfo<\/a>&nbsp;v\u00eda&nbsp;<a href=\"http:\/\/www.sonyalpharumors.com\/sr5-hot-first-full-size-images-of-the-a7-and-a7r-cameras-with-lenses\/\" target=\"_blank\" sl-processed=\"1\">SonyAlphaRumors<\/a>&nbsp;v\u00eda&nbsp;<a href=\"http:\/\/www.slashgear.com\/sony-a7-and-a7r-camera-specs-and-images-leak-14301248\/\" target=\"_blank\" sl-processed=\"1\">SlashGear<\/a>]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dicen los especialistas en&nbsp;fotograf\u00eda&nbsp;que hay un antes y un despu\u00e9s de las c\u00e1maras con sensor de formato completo o Full Frame. Que una vez las pruebas, ya no quieres otra cosa. El \u00faltimo en pasarse a este formato equivalente a 35 mil\u00edmetros en c\u00e1maras sin espejo es Sony, con las Sony Alpha A7 y A7R.<\/p>\n","protected":false},"author":3,"featured_media":29768,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-29769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=29769"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29769\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/29768"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=29769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=29769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=29769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}