{"id":29798,"date":"2013-10-16T12:34:48","date_gmt":"2013-10-16T16:34:48","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/fideos-con-ajo-y-aji\/"},"modified":"2013-10-16T12:34:48","modified_gmt":"2013-10-16T16:34:48","slug":"fideos-con-ajo-y-aji","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/fideos-con-ajo-y-aji\/","title":{"rendered":"Fideos con ajo y aj\u00ed"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-29797\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_ideos_con_ajo.jpg\" width=\"315\" height=\"256\" alt=\"ideos_con_ajo\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_ideos_con_ajo.jpg 315w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_ideos_con_ajo-300x243.jpg 300w\" sizes=\"auto, (max-width: 315px) 100vw, 315px\" \/>Ingredientes para fideos con ajo y aj\u00ed (seis porciones), suena bueno, preparalo en tu casa. <!--more--> <\/p>\n<p>*Medio kilo de fideos<br \/>*Un cuarto de taza de aceite de oliva<br \/>*Dos cucharadas de ajo en rebanadas muy finas<br \/>*Dos cucharadas de perejil picado<br \/>*Un aj\u00ed panca chico sin semillas ni venas<br \/>*Media taza de queso parmesano rallado<br \/>*Sal y pimienta al gusto <\/p>\n<p> <center> <\/p>\n<h4>\u00bfC\u00f3mo se prepara fideos con ajo y aj\u00ed?<\/h4>\n<p> <\/center> <\/p>\n<div>Cocinamos los fideos al dente, en abundante agua con sal. Colamos y reservamos un cuarto de taza de la cocci\u00f3n.<\/div>\n<div><\/div>\n<div>En una sart\u00e9n doramos el ajo con la mitad del aceite de oliva. Agregamos el perejil y el aj\u00ed panca cortado en tiras, dejamos cocinar unos segundos. A\u00f1adimos los fideos, el agua y el resto de aceite. Mover y dejamos cocinar durante unos minutos.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ingredientes para fideos con ajo y aj\u00ed (seis porciones), suena bueno, preparalo en tu casa.<\/p>\n","protected":false},"author":3,"featured_media":29797,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-29798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=29798"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29798\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/29797"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=29798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=29798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=29798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}