{"id":29805,"date":"2013-10-16T13:08:43","date_gmt":"2013-10-16T17:08:43","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/a-partir-de-este-mes-tasa-de-interes-a-uso-de-tarjetas-de-credito-sera-menor\/"},"modified":"2013-10-16T13:08:43","modified_gmt":"2013-10-16T17:08:43","slug":"a-partir-de-este-mes-tasa-de-interes-a-uso-de-tarjetas-de-credito-sera-menor","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/a-partir-de-este-mes-tasa-de-interes-a-uso-de-tarjetas-de-credito-sera-menor\/","title":{"rendered":"A partir de este mes tasa de inter\u00e9s a uso de tarjetas de cr\u00e9dito ser\u00e1 menor"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-29804\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_baja_interes_tarjetas.jpg\" width=\"324\" height=\"193\" alt=\"baja_interes_tarjetas\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_baja_interes_tarjetas.jpg 324w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_baja_interes_tarjetas-300x178.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_baja_interes_tarjetas-500x300.jpg 500w\" sizes=\"auto, (max-width: 324px) 100vw, 324px\" \/>La Superintendencia de Bancos anunci\u00f3 hoy que a partir de este mes reducir\u00e1 los intereses al uso de tarjetas de cr\u00e9dito, debido a un nuevo modelo de negocios propuesto de por las entidades de intermediaci\u00f3n financiera que operan &nbsp;en el pa\u00eds.<\/p>\n<p>  <!--more-->  <\/p>\n<p>El anuncio fue hecho por el superintendente, Rafael Camilo, quien dijo que se ha iniciado un proceso de cambios en beneficio de los tarjetahabientes.<\/p>\n<p>Agreg\u00f3 que la tasa de inter\u00e9s pasar\u00e1 de 7% a 5.5% mensual y explic\u00f3 que para junio del 2014 disminuir\u00e1 de 5.5% a 5 y en enero de 2015 a 4.5%.<\/p>\n<p>Indic\u00f3 que con la aplicaci\u00f3n de este cronograma se reducir\u00e1 en un 36%.<\/p>\n<p>\u201cLos beneficios en junio ser\u00e1n de cinco mil 100 millones y en enero del 2015 ser\u00eda un total de seis mil 900\u2033, se\u00f1al\u00f3.<\/p>\n<p>Precis\u00f3 que con la medida los tarjetahabientes recibir\u00e1n un beneficio de tres mil 500 millones de pesos, al tiempo que manifest\u00f3 que el sector financiero nacional cuenta con tres millones de usuarios de tarjetas de cr\u00e9dito.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Superintendencia de Bancos anunci\u00f3 hoy que a partir de este mes reducir\u00e1 los intereses al uso de tarjetas de cr\u00e9dito, debido a un nuevo modelo de negocios propuesto de por las entidades de intermediaci\u00f3n financiera que operan &nbsp;en el pa\u00eds.<\/p>\n","protected":false},"author":3,"featured_media":29804,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-29805","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=29805"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29805\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/29804"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=29805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=29805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=29805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}