{"id":29807,"date":"2013-10-16T13:15:16","date_gmt":"2013-10-16T17:15:16","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/esto-es-insolito-agrupacion-de-mujeres-dominicana-se-declaran-qpro-haitiq\/"},"modified":"2013-10-16T13:15:16","modified_gmt":"2013-10-16T17:15:16","slug":"esto-es-insolito-agrupacion-de-mujeres-dominicana-se-declaran-qpro-haitiq","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/esto-es-insolito-agrupacion-de-mujeres-dominicana-se-declaran-qpro-haitiq\/","title":{"rendered":"ESTO ES INS\u00d3LITO! agrupaci\u00f3n  de mujeres dominicana se declaran \u00abPRO-HAITI\u00bb"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-29806\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_MUJERES_PROHAITI.jpg\" width=\"785\" height=\"577\" alt=\"MUJERES_PROHAITI\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_MUJERES_PROHAITI.jpg 785w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_MUJERES_PROHAITI-300x220.jpg 300w\" sizes=\"auto, (max-width: 785px) 100vw, 785px\" \/>SANTO DOMINGO.-Un grupo de mujeres trataron de boicotear el discurso del presidente Danilo Medina durante la XII Conferencia Regional sobre la Mujer de Am\u00e9rica Latina y del Caribe, que se desarrolla en el Hotel Hilton, de esta capital.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Tan pronto el mandatario de par\u00f3 en el p\u00f3dium para iniciar su discurso, unas 20 mujeres que participaban del evento, se pararon y con carteles en manos empezaron a corear: \u201cTodos somos Hait\u00ed\u201d.<\/p>\n<p>De inmediato, otras damas presentes, incluida la periodista Consuelo Despradel, reprocharon la actitud respondi\u00e9ndoles: \u201cY nosotras somos dominicanas\u201d. Adem\u00e1s, mandaron a callar al grupo pro haitiano, pidiendo respeto para Medina.<\/p>\n<p>Tras la acci\u00f3n, la secretaria ejecutiva de la Comisi\u00f3n Econ\u00f3mica para Am\u00e9rica Latina y el Caribe (Cepal), Alicia B\u00e1rcena, tom\u00f3 un micr\u00f3fono y pidi\u00f3 a las manifestantes dejar que el Presidente se expresara.&nbsp;<\/p>\n<p>Mientras las mujeres protestaban, el jefe de Estado se qued\u00f3 parado en el p\u00f3dium y de inmediato fue abordado por varios miembros de su equipo de seguridad, quienes le susurraron algo. Segundos despu\u00e9s se alejaron y Medina se qued\u00f3 en el mismo lugar.<\/p>\n<p>Destaca DiarioLibre que la calma retorn\u00f3 tras unos tres minutos de manifestaci\u00f3n y el presidente Medina pudo emitir su discurso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.-Un grupo de mujeres trataron de boicotear el discurso del presidente Danilo Medina durante la XII Conferencia Regional sobre la Mujer de Am\u00e9rica Latina y del Caribe, que se desarrolla en el Hotel Hilton, de esta capital.<\/p>\n","protected":false},"author":3,"featured_media":29806,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-29807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=29807"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29807\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/29806"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=29807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=29807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=29807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}