{"id":29858,"date":"2013-10-18T14:17:13","date_gmt":"2013-10-18T18:17:13","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/10-cosas-que-probablemente-no-sabias-sobre-el-dolor\/"},"modified":"2013-10-18T14:17:13","modified_gmt":"2013-10-18T18:17:13","slug":"10-cosas-que-probablemente-no-sabias-sobre-el-dolor","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/10-cosas-que-probablemente-no-sabias-sobre-el-dolor\/","title":{"rendered":"10 cosas que probablemente no sab\u00edas sobre el dolor"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-29857\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_dolor_16.jpg\" width=\"600\" height=\"400\" alt=\"dolor_16\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_dolor_16.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_dolor_16-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>Este pasado jueves se celebr\u00f3 el D\u00eda Mundial contra el Dolor y en este contexto queremos contarte algunas curiosidades al respecto.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>Seg\u00fan la Biblioteca Nacional de Medicina de Estados Unidos \u201cel dolor es una sensaci\u00f3n desencadenada por el sistema nervioso. El dolor puede ser agudo o sordo. Puede ser intermitente o ser constante. Puede sentir dolor en alg\u00fan lugar del cuerpo, como la espalda, el abdomen o el pecho o sentir dolor generalizado, como los dolores musculares durante una gripe\u201d.<\/p>\n<p>Adem\u00e1s, esta experiencia sensorial desagradable \u201cpuede ayudar a diagnosticar un problema\u201d. Y es que \u201csin dolor, usted podr\u00eda lastimarse gravemente sin saberlo o no darse cuenta de que tiene un problema m\u00e9dico que requiere tratamiento\u201d, explican, a\u00f1adiendo que una vez que se aborda la causa, el dolor suele desaparecer.<\/p>\n<p>\u201cSin embargo, a veces el dolor contin\u00faa durante semanas, meses o a\u00f1os. Esto se conoce como dolor cr\u00f3nico. Algunas veces el dolor cr\u00f3nico se debe a una causa constante, como c\u00e1ncer o artritis. Otras veces la causa es desconocida. Una persona puede tener m\u00e1s de un tipo de dolor cr\u00f3nico al mismo tiempo\u201d, indican.<\/p>\n<p>A continuaci\u00f3n, revisa algunas curiosidades en torno a esta sensaci\u00f3n.<\/p>\n<p>1. El dolor envejece: El dolor cr\u00f3nico puede acelerar el envejecimiento. Un estudio publicado en Journal of the American Geriatric Society y aplicado a m\u00e1s de 18 mil personas, determin\u00f3 que algunos individuos j\u00f3venes pueden verse y sentirse 20 o 30 a\u00f1os m\u00e1s viejos cuando sufren de dolores por un tiempo prolongado, inform\u00f3 Muy Interesante.<\/p>\n<p>2. Afecta a la memoria: Una investigaci\u00f3n de la Universidad de Alberto (EEUU) determin\u00f3 que el dolor cr\u00f3nico afecta en forma negativa a la memoria y la concentraci\u00f3n.<\/p>\n<p>3. La m\u00fasica calma el dolor: El doctor en psicolog\u00eda, Joseph Cardillo, especialista en medicina de \u201ccuerpo y mente\u201d, asegura que ciertas melod\u00edas son eficaces para calmar cefaleas. El experto dice que algunas piezas musicales provocan un aumento de varios neurotransmisores en el cerebro, tales como la dopamina, u hormona del bienestar. \u201cEl poder relajante de la dopamina no es ning\u00fan placebo. Es algo fuerte\u201d, dice el profesional. Puedes revisar algunas melod\u00edas efectivas en este enlace.<\/p>\n<p>4. El chocolate caliente y el agua tambi\u00e9n sirven: De acuerdo a una investigaci\u00f3n de la Universidad de Chicago (EEUU), publicado en la revista Journal of Neuroscience, comer 50 gramos de chocolate negro -o tomar una taza de chocolate caliente- o beber agua ayuda a que un dolor producido por el calor desaparezca. Pese a ello, expertos de la Universidad de Michigan (EEUU) advirtieron que en caso de padecer cefalea el chocolate no es conveniente, ya que la tiramina contenida en este alimento podr\u00eda propiciar los ataques de migra\u00f1a.<\/p>\n<p>5. La obesidad duele: Un estudio publicado en la revista Obesity, determin\u00f3 que las personas con sobrepeso sufren un 20% m\u00e1s de dolores, cifra que se eleva en un 68% en quienes tienen obesidad tipo I y a un 168% en los de obesidad tipo II.<\/p>\n<p>6. La depresi\u00f3n causa mayor dolor f\u00edsico: De acuerdo a la Universidad de Oxford quienes sufren de depresi\u00f3n, tienden a percibir el dolor en forma m\u00e1s intensa. Esto se deber\u00eda a que el cerebro procesa la sensaci\u00f3n de dolor con una carga emocional mucho mayor.<\/p>\n<p>7. Decir groser\u00edas ayuda: Por m\u00e1s extra\u00f1o que parezca, decir groser\u00edas reduce la intensidad del dolor que sufre una persona. As\u00ed lo sugiri\u00f3 un estudio publicado en 2009 por Richard Stephens, docente de la Escuela de Psicolog\u00eda de la Universidad de Keele (Inglaterra), el cual demostr\u00f3 que proferir groser\u00edas permite resistir por m\u00e1s tiempo el dolor generado al meter las manos en un recipiente lleno de hielo durante 40 segundos.<\/p>\n<p>8. Cruzar los brazos confunde al cerebro cuando nos duele algo: Un estudio de la University College de Londres (Inglaterra), publicado en 2011 en la revista Pain, concluy\u00f3 que cruzar los brazos tras sufrir una quemadura o recibir un golpe en las manos permite reducir el dolor. Esto, seg\u00fan el informe, pues al cruzar las extremidades superiores sobre el cuerpo el cerebro confunde el origen del dolor: \u201cEn otras palabras, el gesto enga\u00f1a al cerebro\u201d, indicaron en la publicaci\u00f3n espa\u00f1ola.<\/p>\n<p>9. Escupir es un analg\u00e9sico m\u00e1s potente que la morfina: Seg\u00fan descubrieron en 2006 los cient\u00edficos del Instituto Pasteur (Francia), en la saliva humana existe una especie de \u201canalg\u00e9sico natural\u201d hasta 6 veces m\u00e1s potente que la morfina. \u00c9ste se llama opiorfina y permite activar el funcionamiento de opi\u00e1ceos end\u00f3genos, los cuales son producidos por nuestro cuerpo, que bloquean las se\u00f1ales dolorosas y sirven como antidepresivos.<\/p>\n<p>En este sentido, escupir cuando sientes dolor aumenta la segregaci\u00f3n de saliva y puede ayudar a reducir el sufrimiento.<\/p>\n<p>10. El amor alivia: Seg\u00fan Sean Mackey, de la Universidad de Stanford (EEUU), el amor es un eficaz analg\u00e9sico. Lo anterior lo determin\u00f3 tras estudiar en 2010 el cerebro de estudiantes enamorados, por medio de un esc\u00e1ner de resonancia magn\u00e9tica funcional, mientras eran sometidos al dolor. Luego de esta prueba, comprob\u00f3 que la magnitud de alivio del dolor cuando vemos las fotos de un ser amado es parecida a la morfina. Precisamente, el amor permite reducir el malestar de una persona mediante el n\u00facleo accumbens, el centro de la recompensa en el cerebro.<\/p>\n<p>Fuente:&nbsp;<a href=\"http:\/\/www.biobiochile.cl\/2013\/10\/17\/11-cosas-que-probablemente-no-sabias-sobre-el-dolor.shtml\" title=\"http:\/\/www.biobiochile.cl\/2013\/10\/17\/11-cosas-que-probablemente-no-sabias-sobre-el-dolor.shtml\">http:\/\/www.biobiochile.cl\/2013\/10\/17\/11-cosas-que-probablemente-no-sabia&#8230;<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Este pasado jueves se celebr\u00f3 el D\u00eda Mundial contra el Dolor y en este contexto queremos contarte algunas curiosidades al respecto.<\/p>\n","protected":false},"author":3,"featured_media":29857,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-29858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=29858"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29858\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/29857"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=29858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=29858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=29858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}