{"id":29866,"date":"2013-10-18T14:43:04","date_gmt":"2013-10-18T18:43:04","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/amnistia-internacional-pide-a-rd-revertir-la-sentencia-del-tribunal-constitucional-sobre-la-nacionalidad\/"},"modified":"2013-10-18T14:43:04","modified_gmt":"2013-10-18T18:43:04","slug":"amnistia-internacional-pide-a-rd-revertir-la-sentencia-del-tribunal-constitucional-sobre-la-nacionalidad","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/amnistia-internacional-pide-a-rd-revertir-la-sentencia-del-tribunal-constitucional-sobre-la-nacionalidad\/","title":{"rendered":"Amnist\u00eda Internacional pide a RD revertir la sentencia del Tribunal Constitucional sobre la nacionalidad"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-29865\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_amnistia-internacional-logo.jpg\" width=\"350\" height=\"329\" alt=\"amnistia-internacional-logo\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_amnistia-internacional-logo.jpg 350w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_amnistia-internacional-logo-300x282.jpg 300w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/>Amnist\u00eda Internacional en un comunicado enviado hoy temprano indica que la Rep\u00fablica Dominicana no debe aplicar una sentencia del Tribunal Constitucional que podr\u00eda convertir en ap\u00e1tridas a cientos de miles de dominicanos de origen extranjero, ha dicho hoy Amnist\u00eda Internacional.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>En virtud de la decisi\u00f3n del Constitucional, las personas de origen extranjero \u2013grupo al que pertenece la inmensa mayor\u00eda de los dominicanos de origen haitiano\u2013 podr\u00edan ser privadas de su nacionalidad y verse obligadas a salir del pa\u00eds y solicitarla de nuevo.<\/div>\n<div><\/div>\n<div>\n<p><strong>\u201cSi se aplica \u00edntegramente, esta sentencia tendr\u00e1 un efecto devastador en las vidas de cientos de miles de personas, cuyas c\u00e9dulas de identidad ser\u00edan canceladas y, por consiguiente, muchos de sus derechos humanos \u2013a la libertad de circulaci\u00f3n, a la educaci\u00f3n, al trabajo y al acceso a la atenci\u00f3n a la salud\u2013 les ser\u00edan totalmente negados\u201d, ha dicho Chiara Liguori, investigadora de Amnist\u00eda Internacional sobre el Caribe.<\/strong><\/p>\n<p><strong>El mes pasado, el Tribunal Constitucional resolvi\u00f3 que Juliana Deguis, nacida en la Rep\u00fablica Dominicana en 1984 de padres haitianos, hab\u00eda sido inscrita irregularmente como dominicana al nacer.<\/strong><\/p>\n<p>Los efectos discriminatorios de este caso podr\u00edan ser de gran alcance, especialmente para las personas dominicanas de origen haitiano.<\/p>\n<p>El tribunal dispuso tambi\u00e9n que la Junta Central Electoral realizara un inventario de todas las inscripciones de nacimiento del Registro Civil desde 1929 e identificara en una lista a todas las personas a quienes supuestamente se inscribi\u00f3 irregularmente y se otorg\u00f3 la ciudadan\u00eda dominicana, y determin\u00f3 que sus casos deb\u00edan ser tratados de la misma forma que el de Juliana Deguis.<\/p>\n<p>Algunas partes de la sentencia ya han comenzado a aplicarse. A la Juliana Deguis se le ha permitido permanecer en el pa\u00eds hasta que un Plan Nacional de Regularizaci\u00f3n decida la suerte de aquellas personas a quienes se considera residentes ilegales.<\/p>\n<p>\u201cQuiero trabajar, pero no puedo. Tengo cuatro hijos que no pueden ir a la escuela. Nacimos ac\u00e1 y somos de ac\u00e1, pero sufrimos mucha discriminaci\u00f3n\u201d, dijo Deguis a Amnist\u00eda Internacional.<\/p>\n<p>As\u00ed aplicada, la sentencia violar\u00eda las obligaciones de derechos humanos de la Rep\u00fablica Dominicana. Adem\u00e1s, tambi\u00e9n incumplir\u00eda una hist\u00f3rica decisi\u00f3n de 2005 de la Corte Interamericana de Derechos Humanos y vulnerar\u00eda un principio b\u00e1sico de derecho que la Constituci\u00f3n dominicana establece expresamente: la prohibici\u00f3n de la retroactividad de la ley.<\/p>\n<p>Esta sentencia del Tribunal Constitucional es la \u00faltima de una serie de decisiones administrativas, legislativas y judiciales que desde comienzos de la d\u00e9cada de 2000 han ido privando retroactivamente a los dominicanos de origen haitiano de la nacionalidad dominicana.<\/p>\n<p>\u201cEsta \u00faltima decisi\u00f3n destroza totalmente las vidas de los ciudadanos dominicanos de origen haitiano, especialmente si son obligados a salir del pa\u00eds por el Plan Nacional de Regularizaci\u00f3n.<\/p>\n<p>\u201cEs totalmente injusto decir que personas que han vivido como dominicanos durante d\u00e9cadas ya no pertenecen al pa\u00eds ni tienen ning\u00fan derecho en \u00e9l\u201d, ha dicho Chiara Liguori.<\/p>\n<p>No se sabe con certeza a cu\u00e1ntas personas afecta esta sentencia del Tribunal Constitucional. Seg\u00fan una reciente encuesta de la Oficina Nacional de Estad\u00edstica, en la Rep\u00fablica Dominicana hay 244.151 personas nacidas de padres \u201cextranjeros\u201d. El 86 por ciento de ellas son de origen haitiano.<\/p>\n<p>\u201cLas autoridades dominicanas deben tomar todas las medidas necesarias para garantizar a Juliana Deguis y a otras personas dominicanas de origen extranjero el acceso a sus documentos de identidad para recobrar los derechos de que disfrutaban cuando estaban reconocidas como ciudadanas dominicanas\u201d, ha a\u00f1adido Liguori.<\/p>\n<p>Informaci\u00f3n complementaria<\/p>\n<p>En 2008, Juliana Deguis interpuso un recurso de revisi\u00f3n constitucional al serle retirado su certificado de nacimiento por la Junta Central Electoral cuando acudi\u00f3 a solicitar su c\u00e9dula de identidad, bas\u00e1ndose en que sus apellidos eran \u201chaitianos\u201d.<\/p>\n<p><strong>El 23 de septiembre de 2013, el Tribunal Constitucional dominicano rechaz\u00f3 el recurso de amparo de Juliana Deguis, afirmando que la Junta Central Electoral no hab\u00eda violado sus derechos.<\/strong><\/p>\n<p>Seg\u00fan dicha sentencia, Juliana, nacida en la Rep\u00fablica Dominicana en 1984 de padres haitianos, hab\u00eda sido inscrita irregularmente como dominicana al nacer. Sus padres eran considerados \u201cextranjeros en tr\u00e1nsito\u201d porque no pod\u00edan demostrar cu\u00e1l era su situaci\u00f3n jur\u00eddica en la Rep\u00fablica Dominicana, y por consiguiente Juliana nunca debi\u00f3 haber tenido nacionalidad dominicana, motivo por el cual \u00e9sta deb\u00eda retir\u00e1rsele.<\/p>\n<p>Aunque hay al menos 40 casos similares en espera de una decisi\u00f3n del Tribunal Constitucional, no es probable que el alto tribunal se pronuncie sobre cada uno de ellos, pues en esta sentencia ha especificado de forma expresa que se proceda de la misma manera respecto a todos ellos.<\/p>\n<p>Aunque es derecho soberano del Estado dominicano decidir las condiciones para conceder la nacionalidad dominicana, el derecho internacional de los derechos humanos le exige que no prive arbitrariamente a nadie de su nacionalidad, especialmente cuando la consecuencia de hacerlo pueda ser la apatridia.<\/p>\n<\/p><\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Amnist\u00eda Internacional en un comunicado enviado hoy temprano indica que la Rep\u00fablica Dominicana no debe aplicar una sentencia del Tribunal Constitucional que podr\u00eda convertir en ap\u00e1tridas a cientos de miles de dominicanos de origen extranjero, ha dicho hoy Amnist\u00eda Internacional.<\/p>\n","protected":false},"author":3,"featured_media":29865,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-29866","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=29866"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29866\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/29865"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=29866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=29866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=29866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}