{"id":29882,"date":"2013-10-19T14:48:38","date_gmt":"2013-10-19T18:48:38","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/aguilas-estrellas-y-leones-arrancan-ganando-en-el-inicio-de-la-pelota-invernal\/"},"modified":"2013-10-19T14:48:38","modified_gmt":"2013-10-19T18:48:38","slug":"aguilas-estrellas-y-leones-arrancan-ganando-en-el-inicio-de-la-pelota-invernal","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/aguilas-estrellas-y-leones-arrancan-ganando-en-el-inicio-de-la-pelota-invernal\/","title":{"rendered":"\u00c1guilas, Estrellas y Leones arrancan ganando en el inicio de la pelota invernal"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-29881\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_Estadio_Quisqueya2.jpg\" width=\"500\" height=\"375\" alt=\"Estadio_Quisqueya2\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_Estadio_Quisqueya2.jpg 500w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_Estadio_Quisqueya2-300x225.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>Las \u00c1guilas Cibae\u00f1as, Las Estrellas Orientales y los Leones del Escogido arrancaron con buen pie, ganando su primer encuentro al inicio de la temporada de b\u00e9isbol invernal.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>El derecho \u00c1ngel Castro localiz\u00f3 buenos pitcheos, combinando su bola r\u00e1pida con rompientes para que las Aguilas Cibae\u00f1as derrotaran 6 por 1 a los Gigantes del Cibao en la apertura del Campeonato Nacional 2013-2014, dedicado a don Miguel Heded, in memoriam.<\/div>\n<div><\/div>\n<div>\n<p>El respaldo para Castro vino acompa\u00f1ado por un bateo de poder de Mike Bianucci y Zoilo Almonte Al derecho s\u00f3lo le conectaron dos imparables durante m\u00e1s de cinco entradas. Toler\u00f3 una anotaci\u00f3n, ponch\u00f3 a seis y transfiri\u00f3 a tres, para anotarse su primer triunfo de la incipiente temporada.<\/p>\n<p>Varios jugadores aguiluchos presentaron buenas credenciales; Bianucci conect\u00f3 jonr\u00f3n y sencillo con dos remolques. Almonte -quien lleg\u00f3 v\u00eda cambio-, comenz\u00f3 a dar dividendos a los mameyes tras disparar un largo cuadrangular en solitario por encima de la verja del prado derecho en el s\u00e9ptimo cap\u00edtulo.<\/p>\n<p>Despu\u00e9s que los Gigantes anotaran primero, gracias a un tetrabases del importado Anthony Aliotti, las cuyayas pisaron el plato tres veces en la segunda entrada y mantuvieron la pizarra a su favor todo el resto de partido.<\/p>\n<p>El derecho TJ Pe\u00f1a, realiz\u00f3 una vital labor de relevo en el sexto acto. Al heredar una situaci\u00f3n de dos hombres en circulaci\u00f3n y un out; Despu\u00e9s de recibir un hit, Oscar Tejeda conect\u00f3 rodado por tercera y el antesalista aguilucho, Andy Marte, inici\u00f3 una doble matanza que finaliz\u00f3 el episodio.<\/p>\n<p><strong>Toros quedaron tendidos ante las Estrellas<\/strong><\/p>\n<p>Las Estrellas Orientales derrotaron 3 carreras por 2 a los Toros del Este en la fecha inaugural este viernes del torneo de B\u00e9isbol oto\u00f1o invernal celebrado en el Estadio Tetelo Vargas de esta ciudad.<\/p>\n<p>El partido se decidi\u00f3 en el noveno episodio en el que los Orientales anotaron la carrera de la victoria para dejar en el terreno a los Toros. \u00c1lex Valdez negoci\u00f3 boleto abriendo la entrada y fue sustituido por Eliezer Mesa, quien lleg\u00f3 a segunda con lanzamiento desviado del lanzador Fabio Castillo. Mesa anot\u00f3 con sencillo por el jard\u00edn derecho del receptor Leandro Castro para poner fin al encuentro.<\/p>\n<p>El relevista Marcos Mateo (1-0) lanz\u00f3 una entrada en blanco para anotarse la victoria, mientras que el rev\u00e9s recay\u00f3 sobre Castillo (0-1).<\/p>\n<p>El dirigente del equipo verde, Dino Ebel, le dio trabajo a cuatro relevistas, los cuales permitieron un imparable en cinco entradas de labor con cuatro boletos y tres ponches.<\/p>\n<p>Ambos lanzadores abridores salieron sin decisi\u00f3n. Por los Toros, Claudio Vargas lanz\u00f3 tres entradas y un tercio de tres imparables, dos carreras y cuatro ponches, mientras que por los Orientales, Greg Smith trabaj\u00f3 cuatro innings, permiti\u00f3 cuatro hits, dos carreras (una limpia) y abanic\u00f3 a un bateador.<\/p>\n<p>Los Toros anotaron la primera carrera del partido en el tercer episodio contra el importado Greg Smith. El segunda base Jos\u00e9 Ram\u00edrez dispar\u00f3 rodado lento por tercera, lleg\u00f3 a segunda por error en tiro de Miguel San\u00f3 y anot\u00f3 con sencillo al jard\u00edn central del veterano Eugenio V\u00e9lez. La segunda anotaci\u00f3n lleg\u00f3 en el cuarto inning tras un cuadrangular del importado Mat Hague por el jard\u00edn izquierdo.<\/p>\n<p>Las Estrellas igualaron las acciones 2-2 en el cierre de la cuarta entrada contra el abridor de los Toros Claudio Vargas, quien otorg\u00f3 boleto a Vince Belnome y luego Alfredo Marte conect\u00f3 jonr\u00f3n por el prado izquierdo.<\/p>\n<p>Por las Estrellas, que ligaron tres imparables, Alfredo Marte peg\u00f3 jonr\u00f3n con par de vueltas empujadas en cuatro turnos; Leandro Castro, de 4-1, con una remolcada, y Jonathan G\u00e1lvez, de 4-1.<\/p>\n<p>Por los Toros, que pegaron cinco indiscutibles, Mat Hague dispar\u00f3 jonr\u00f3n, sencillo y negoci\u00f3 un boleto en tres turnos; Eugenio V\u00e9lez, de 2-1, con dos boletos; Jos\u00e9 Ram\u00edrez, de 3-1, y Gary S\u00e1nchez, de 3-1.<\/p>\n<p>Las Estrellas Orientales reciben este s\u00e1bado, a las 8:00 de la noche, a los Leones del Escogido en el Estadio Tetelo Vargas y tendr\u00e1n como lanzador al importado Bruce Billings.<\/p>\n<p>Leones vence a Licey en inicio de torneo<\/p>\n<p>Gregory Polanco conect\u00f2 un jonr\u00f2n de tres carreras en la quinta entrada para virar el marcador y guiar a los Leones del Escogido a una victoria 4-1 ante los Tigres del Licey en la inauguraci\u00f3n del torneo de b\u00e9isbol profesional oto\u00f1o-invernal 2013-14 dedicado a Miguel Heded Azar en partido celebrado en el Estadio Quisqueya.<\/p>\n<p><strong><\/strong><\/p>\n<p>Fuente&nbsp;<a href=\"http:\/\/www.lidom.com\/home\/\" target=\"_blank\">Lidom.com<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Las \u00c1guilas Cibae\u00f1as, Las Estrellas Orientales y los Leones del Escogido arrancaron con buen pie, ganando su primer encuentro al inicio de la temporada de b\u00e9isbol invernal.<\/p>\n","protected":false},"author":3,"featured_media":29881,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-29882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=29882"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29882\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/29881"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=29882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=29882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=29882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}