{"id":29947,"date":"2013-10-25T11:56:59","date_gmt":"2013-10-25T15:56:59","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/bebe-causa-sensacion-con-extrano-disfraz-de-luz-video\/"},"modified":"2013-10-25T11:56:59","modified_gmt":"2013-10-25T15:56:59","slug":"bebe-causa-sensacion-con-extrano-disfraz-de-luz-video","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/bebe-causa-sensacion-con-extrano-disfraz-de-luz-video\/","title":{"rendered":"Beb\u00e9 causa sensaci\u00f3n con extra\u00f1o disfraz de luz (Video)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-29946\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_bebe_causa_sensacion_con_disfraz_de_luz.jpg\" width=\"600\" height=\"400\" alt=\"bebe_causa_sensacion_con_disfraz_de_luz\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_bebe_causa_sensacion_con_disfraz_de_luz.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_bebe_causa_sensacion_con_disfraz_de_luz-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>Llega la \u00e9poca de Halloween y comienzan las competencias por el mejor disfraz, el m\u00e1s ingenioso, el m\u00e1s \u00abparecido\u00bb (si se imita a un personaje), es decir, el mejor. Este beb\u00e9 se lleva el premio con un disfraz bastante original y luminoso.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>n beb\u00e9 de 22 meses luce un disfraz muy original y lleno de luz, que atemoriza a una joven en el medio de un pasillo. Desde lejos, y en medio del pasillo oscuro, parece que el beb\u00e9 es una especie de mini extraterrestre que camina.<\/p>\n<p>Sin duda esa familia se lleva el premio por originalidad y por confecci\u00f3n, ya que es un disfraz realizado con luz LED.<\/p>\n<p><iframe loading=\"lazy\" width=\"600\" height=\"450\" src=\"http:\/\/www.youtube.com\/embed\/GkBDRUO8hAo\" frameborder=\"0\" allowfullscreen=\"\"><\/iframe><\/p>\n<p>AJ\/ Informe21<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Llega la \u00e9poca de Halloween y comienzan las competencias por el mejor disfraz, el m\u00e1s ingenioso, el m\u00e1s \u00abparecido\u00bb (si se imita a un personaje), es decir, el mejor. Este beb\u00e9 se lleva el premio con un disfraz bastante original y luminoso.<\/p>\n","protected":false},"author":3,"featured_media":29946,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-29947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=29947"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/29947\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/29946"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=29947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=29947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=29947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}