{"id":30005,"date":"2013-10-28T02:45:41","date_gmt":"2013-10-28T06:45:41","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/investigaciones-revelan-nuevos-genes-ligados-a-la-enfermedad-de-alzheimer\/"},"modified":"2013-10-28T02:45:41","modified_gmt":"2013-10-28T06:45:41","slug":"investigaciones-revelan-nuevos-genes-ligados-a-la-enfermedad-de-alzheimer","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/investigaciones-revelan-nuevos-genes-ligados-a-la-enfermedad-de-alzheimer\/","title":{"rendered":"Investigaciones revelan nuevos genes ligados a la enfermedad de Alzheimer"},"content":{"rendered":"<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"caption alignleft size-full wp-image-30004\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/wscdn.bbc.co.uk_worldservice_assets_images_2013_10_10_131010104937_alzheimer_304x171_spl.jpg\" border=\"0\" align=\"left\" width=\"304\" height=\"171\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/wscdn.bbc.co.uk_worldservice_assets_images_2013_10_10_131010104937_alzheimer_304x171_spl.jpg 304w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/wscdn.bbc.co.uk_worldservice_assets_images_2013_10_10_131010104937_alzheimer_304x171_spl-300x168.jpg 300w\" sizes=\"auto, (max-width: 304px) 100vw, 304px\" \/>Los cient\u00edficos esperan que estudios posteriores establezcan de forma m\u00e1s precisa qu\u00e9 es lo que funciona mal en el cerebro y que conduzcan a eventuales tratamientos para la enfermedad de Alzheimer.Los cient\u00edficos identificaron once nuevos genes que aumentan el riesgo de desarrollar la enfermedad de Alzheimer.   <!--more-->  <\/p>\n<p>Esos genes tienen una cantidad de impactos: en la forma como funciona el sistema inmunol\u00f3gico y en c\u00f3mo las c\u00e9lulas en el cerebro transportan material.Un equipo internacional de investigadores dijo que el hallazgo representa un gran avance en la comprensi\u00f3n de las causas de la demencia.El mayor estudio hasta el momento de la enfermedad de Alzheimer ha puesto al descubierto varios nuevos genes vinculados a su desarrollo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los cient\u00edficos esperan que estudios posteriores establezcan de forma m\u00e1s precisa qu\u00e9 es lo que funciona mal en el cerebro y que conduzcan a eventuales tratamientos para la enfermedad de Alzheimer.Los cient\u00edficos identificaron once nuevos genes que aumentan el riesgo de desarrollar la enfermedad de Alzheimer.<\/p>\n","protected":false},"author":3,"featured_media":30004,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-30005","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=30005"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30005\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/30004"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=30005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=30005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=30005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}