{"id":30019,"date":"2013-10-28T04:00:00","date_gmt":"2013-10-28T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/aguilas-tigres-y-leones-ganan-en-beisbol-invernal-dominicano\/"},"modified":"2013-10-28T04:00:00","modified_gmt":"2013-10-28T08:00:00","slug":"aguilas-tigres-y-leones-ganan-en-beisbol-invernal-dominicano","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/aguilas-tigres-y-leones-ganan-en-beisbol-invernal-dominicano\/","title":{"rendered":"\u00c1guilas, Tigres y Leones ganan en b\u00e9isbol invernal dominicano"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-30018\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_Estadio_Quisqueya2_1fnghffsd.jpg\" width=\"500\" height=\"375\" alt=\"Estadio_Quisqueya2_1fnghffsd\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_Estadio_Quisqueya2_1fnghffsd.jpg 500w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_Estadio_Quisqueya2_1fnghffsd-300x225.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>Santo Domingo. Los conjuntos \u00c1guilas Cibae\u00f1as, Leones del Escogido y Tigres de Licey ganaron sus respectivos compromisos en la jornada del domingo del campeonato de b\u00e9isbol profesional dominicano.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div><strong>Las \u00c1guilas vencieron como locales a las Estrellas Orientales&nbsp; con marcador de seis vueltas por una en partido disputado en el estadio Cibao de la norte\u00f1a Santiago de los Caballeros, para mantenerse firmes en la cima del torneo beisbolero.<\/strong><\/div>\n<div><strong><br \/><\/strong><\/div>\n<div>\n<p>El triunfo de las cuyayas fue respaldado por una buena labor monticular del zurdo estadounidense Chris Cody, quien permiti\u00f3 una carrera durante seis episodios.<\/p>\n<p>El lanzador derrotado fue el criollo Omar Javier, quien permiti\u00f3 cuatro carreras en apenas dos episodios.<\/p>\n<p>Fue la tercera victoria seguida del equipo comandado por F\u00e9lix Ferm\u00edn, que se mantiene firme en la cima de la tabla con marca de siete triunfos y un rev\u00e9s, mientras los orientales acumulan tres ganados y seis derrotas.<\/p>\n<p><strong>En otro encuentro de la jornada, los Tigres de Licey derrotaron 7-0 como visitantes a los Toros del Este, en el parque Francisco Micheli de la ciudad de La Romana, en el este del pa\u00eds caribe\u00f1o.<\/strong><\/p>\n<p>Los felinos mejoraron su marca de ganados y perdidos en seis victorias y tres derrotas, mientras los Toros acumulan un triunfo y siete reveses, para mantenerse en el \u00faltimo puesto de la tabla.<\/p>\n<p>El equipo azul est\u00e1 a juego y medio del primer pelda\u00f1o que ocupan las \u00c1guilas.<\/p>\n<p><strong>De su lado, los Leones ganaron 6-2 como locales a los Gigantes del Cibao, en el estadio Quisqueya de Santo Domingo, para mantenerse firmes en el tercer puesto de la tabla.<\/strong><\/p>\n<p>Los escarlatas mejoraron su marca de ganados y perdidos (5-3), mientras que los Gigantes cuentan con tres victorias y cinco derrotas.<\/p>\n<p>Este lunes no hay encuentros programados en el principal evento deportivo que se disputa en Santo Domingo.<\/p>\n<p><a href=\"http:\/\/www.bloglovin.com\/frame?post=1808998741&amp;group=0&amp;frame_type=a&amp;blog=8927485&amp;link=aHR0cDovL3d3dy5lbnNlZ3VuZG9zLm5ldC8yMDEzLzEwLzI3L2FndWlsYXMtdGlncmVzLXktbGVvbmVzLWdhbmFuLWVuLWJlaXNib2wtaW52ZXJuYWwtZG9taW5pY2Fuby8&amp;frame=1&amp;click=0&amp;user=0\">fuente<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo. Los conjuntos \u00c1guilas Cibae\u00f1as, Leones del Escogido y Tigres de Licey ganaron sus respectivos compromisos en la jornada del domingo del campeonato de b\u00e9isbol profesional dominicano.<\/p>\n","protected":false},"author":3,"featured_media":30018,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-30019","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=30019"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30019\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/30018"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=30019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=30019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=30019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}