{"id":30022,"date":"2013-10-28T04:00:00","date_gmt":"2013-10-28T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/las-10-cualidades-que-debe-tener-un-artista-para-ser-bultero\/"},"modified":"2013-10-28T04:00:00","modified_gmt":"2013-10-28T08:00:00","slug":"las-10-cualidades-que-debe-tener-un-artista-para-ser-bultero","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/las-10-cualidades-que-debe-tener-un-artista-para-ser-bultero\/","title":{"rendered":"Las 10 cualidades que debe tener un artista para ser bultero"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-17804\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/06\/sosua_images_Omega-en-los-Casandra-2012.jpg\" width=\"640\" height=\"425\" alt=\"Omega-en-los-Casandra-2012\" class=\"caption\" style=\"float: left;\" \/>1-Aparecerse con gafas oscuras en una actividad nocturna.<\/p>\n<p>2-Subir a la tarima con una multitud de espalderos.<\/p>\n<p>  <!--more-->  <\/p>\n<p>3-Poner fotos a las redes sociales mostrando botellas de bebidas alcoh\u00f3licas caras.<\/p>\n<p>4-Siempre andar con muchas prendas y joyas en exceso con su nombre tallado en ellas (Relojes, Anillos, Cadenas, Guillos, etc)<\/p>\n<p>5- Llegar tarde a todos los eventos, siempre.<\/p>\n<p>6-Exige cosas extra\u00f1as que nunca usar\u00e1 o comer\u00e1, en su camerino.<\/p>\n<p>7-Sus v\u00eddeos est\u00e1n basados en tres aspectos: Autos lujosos, muchas mujeres y bebidas.<\/p>\n<p>8-Se inventa falsas informaciones para lograr que todos hablen de \u00e9l.<\/p>\n<p>9-Dice que sus canciones est\u00e1n sonando \u201cfuertemente en el extranjero\u201d, pero no aparecen en los listados de las emisoras cuando se publican.<\/p>\n<p>10- En las entrevistas, responde en tercera persona.<\/p>\n<p>Para los que viven en el extranjero y desconocen el vocablo \u201cBultero\u201d: Es un ente de la sociedad que se dedica a \u201cprivar\u201d de lo que no es y en algunos casos de lo que s\u00ed es, es decir, a vender de espejismos sobre su realidad econ\u00f3mica y\/o social o a promocionar de manera agresiva o sutil su estatus, posibilidades y calidad de vida, el bulto se puede tomar como una de las m\u00faltiples facetas de la vanidad del artista.<\/p>\n<p>El \u201cBultero\u201d en nuestro pa\u00eds es sin\u00f3nimo de \u201ccompar\u00f3n\u201d, ostentoso, aparatoso, jactancioso y en ocasiones hasta pedante.<\/p>\n<p><strong><br \/>Por Troi Orlando Espejo<\/strong><\/p>\n<p><strong>fuente: ensegundos.net<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>1-Aparecerse con gafas oscuras en una actividad nocturna. 2-Subir a la tarima con una multitud de espalderos.<\/p>\n","protected":false},"author":3,"featured_media":17804,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-30022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=30022"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30022\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/17804"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=30022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=30022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=30022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}