{"id":30045,"date":"2013-10-29T22:16:54","date_gmt":"2013-10-30T02:16:54","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/gordon-debutara-este-martes-ante-aguilas-engel-beltre-el-miercoles\/"},"modified":"2013-10-29T22:16:54","modified_gmt":"2013-10-30T02:16:54","slug":"gordon-debutara-este-martes-ante-aguilas-engel-beltre-el-miercoles","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/gordon-debutara-este-martes-ante-aguilas-engel-beltre-el-miercoles\/","title":{"rendered":"GORDON DEBUTAR\u00c1 ESTE MARTES ANTE \u00c1GUILAS; ENGEL BELTR\u00c9 EL MI\u00c9RCOLES"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-30044\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/www.lidom.com_home_images_noticias2013_DeeGordon-SM.jpg\" border=\"0\" align=\"left\" width=\"400\" height=\"240\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/www.lidom.com_home_images_noticias2013_DeeGordon-SM.jpg 400w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/www.lidom.com_home_images_noticias2013_DeeGordon-SM-300x180.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/www.lidom.com_home_images_noticias2013_DeeGordon-SM-500x300.jpg 500w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p> El veloz y conocido jugador importado de los Tigres del Licey, Dee Gordon, arrib\u00f3 al pa\u00eds el fin de semana y estar\u00e1 en roster este martes para el partido que disputar\u00e1 contra las \u00c1guilas Cibae\u00f1as en el Estadio Quisqueya, en la continuaci\u00f3n del Torneo Nacional de B\u00e9isbol 2013-14, Miguel Heded, in memoriam. <!--more-->  <\/p>\n<p>Asimismo, el jardinero central Engel Beltr\u00e9 tendr\u00e1 su debut el mi\u00e9rcoles frente a los Gigantes del Cibao; mientras que el lanzador Ram\u00f3n Ortiz tendr\u00e1 su primera aparici\u00f3n del campeonato el viernes frente a los Leones del Escogido, ambos en el parque capitalino.<\/p>\n<p>Las informaciones fueron ofrecidas este lunes por el gerente general del club, Manny Acta, quien agreg\u00f3 que el tambi\u00e9n veterano Guillermo Mota se prepara para unirse el cuerpo monticular de los Tigres.<\/p>\n<p>\u201cDee Gordon podr\u00eda estar debutando en lo inmediato y estar\u00e1 en roster el martes para el partido contra las \u00c1guilas\u201d, manifest\u00f3 Acta al informar de la presencia del jugador de la organizaci\u00f3n Dodgers de Los \u00c1ngeles, quien esta vez jugar\u00e1 en los jardines.<\/p>\n<p>Gordon reforz\u00f3 al Licey en la campa\u00f1a anterior, pero en su posici\u00f3n original de torpedero. En 29 encuentros bate\u00f3 para .269. En 108 turnos dispar\u00f3 29 imparables, incluidos tres dobles y seis triples, anot\u00f3 16 carreras, impuls\u00f3 12, rob\u00f3 nueve bases, recibi\u00f3 11 boletos y 22 ponches.<\/p>\n<p>Engel Beltr\u00e9, quien este a\u00f1o debut\u00f3 en Grandes Ligas con los Rangers de Texas y realiz\u00f3 buena campa\u00f1a como su jardinero central y abridor con Round Rock, en la Liga de la Costa del Pac\u00edfico (AAA), tiene dos semanas prepar\u00e1ndose para unirse a los felinos.<\/p>\n<p>\u201cEl Barbero de Cotu\u00ed\u201d, Ram\u00f3n Ortiz, ha tenido dos presentaciones con el equipo Licey de la Liga Instruccional, la \u00faltima, este lunes contra la finca de los Rangers de Texas, a los que retir\u00f3 a los tres bateadores que enfrent\u00f3. La primera fue el pasado jueves ante el de los Yankees.<\/p>\n<p>Guillermo Mota, veterano lanzador que no tuvo actuaci\u00f3n en este verano en el b\u00e9isbol organizado, tir\u00f3 1.0 acto contra los Rangers este lunes, toler\u00f3 un hit, sin otra cosa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El veloz y conocido jugador importado de los Tigres del Licey, Dee Gordon, arrib\u00f3 al pa\u00eds el fin de semana y estar\u00e1 en roster este martes para el partido que disputar\u00e1 contra las \u00c1guilas Cibae\u00f1as en el Estadio Quisqueya, en la continuaci\u00f3n del Torneo Nacional de B\u00e9isbol 2013-14, Miguel Heded, in memoriam.<\/p>\n","protected":false},"author":3,"featured_media":30044,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-30045","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=30045"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30045\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/30044"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=30045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=30045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=30045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}