{"id":30095,"date":"2013-10-31T19:39:56","date_gmt":"2013-10-31T23:39:56","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/un-estudio-explica-por-que-no-hay-cura-para-el-resfriado-comun\/"},"modified":"2013-10-31T19:39:56","modified_gmt":"2013-10-31T23:39:56","slug":"un-estudio-explica-por-que-no-hay-cura-para-el-resfriado-comun","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/un-estudio-explica-por-que-no-hay-cura-para-el-resfriado-comun\/","title":{"rendered":"Un estudio explica por qu\u00e9 no hay cura para el resfriado com\u00fan"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-30094\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_mujer-con-resfriado-comun.jpg\" width=\"600\" height=\"400\" alt=\"mujer-con-resfriado-comun\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_mujer-con-resfriado-comun.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_mujer-con-resfriado-comun-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>El resfriado com\u00fan es una enfermedad viral de las v\u00edas respiratorias altas, en la mayor\u00eda de los casos causada por los rinovirus A, B y C. Y lo curioso es que, a pesar de tratarse de la enfermedad infecciosa m\u00e1s frecuente en los seres humanos, de momento no existe cura conocida.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>Un estudio de la Universidad Wisconsin-Madison (EE UU) publicado en la revista Virology parece haber dado con el motivo de que el resfriado sea \u00abincurable\u00bb.<\/p>\n<p>Usando secuencias gen\u00e9ticas de genomas de 500 rinovirus ha creado un modelo topogr\u00e1fico en tres dimensiones de la cubierta proteica (c\u00e1pside) del virus del resfriado, concretamente del rinovirus C. Y asegura que los medicamentos antivirales usados hasta ahora no surten ning\u00fan efecto sobre esta estructura. Sin embargo, ahora que se conoce c\u00f3mo es, se podr\u00edan desarrollar f\u00e1rmacos espec\u00edficos para que estos virus no logren evadir al sistema inmune.<\/p>\n<p>Los drogas antivirales act\u00faan atacando y modificando las caracter\u00edsticas superficiales de los virus, pero para ser efectivas deben encajar como la pieza de un rompecabezas. De ah\u00ed que conocer con exactitud la estructura tridimensional del rinovirus C sea el mejor punto de partida para desarrollar tratamientos farmacol\u00f3gicos eficaces sin dar \u00abpalos de ciego\u00bb, seg\u00fan aclaran los autores.<\/p>\n<p>Fuente:&nbsp;<a href=\"http:\/\/www.muyinteresante.es\/salud\/articulo\/un-estudio-explica-por-que-no-hay-cura-para-el-resfriado-comun-141383120407\" title=\"http:\/\/www.muyinteresante.es\/salud\/articulo\/un-estudio-explica-por-que-no-hay-cura-para-el-resfriado-comun-141383120407\">http:\/\/www.muyinteresante.es\/salud\/articulo\/un-estudio-explica-por-que-n&#8230;<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El resfriado com\u00fan es una enfermedad viral de las v\u00edas respiratorias altas, en la mayor\u00eda de los casos causada por los rinovirus A, B y C. Y lo curioso es que, a pesar de tratarse de la enfermedad infecciosa m\u00e1s frecuente en los seres humanos, de momento no existe cura conocida.<\/p>\n","protected":false},"author":3,"featured_media":30094,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-30095","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=30095"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30095\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/30094"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=30095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=30095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=30095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}