{"id":30109,"date":"2013-10-31T14:20:54","date_gmt":"2013-10-31T18:20:54","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/david-ortiz-es-el-mas-valioso-de-la-serie-mundial\/"},"modified":"2013-10-31T14:20:54","modified_gmt":"2013-10-31T18:20:54","slug":"david-ortiz-es-el-mas-valioso-de-la-serie-mundial","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/david-ortiz-es-el-mas-valioso-de-la-serie-mundial\/","title":{"rendered":"David Ortiz es el M\u00c1S VALIOSO de la Serie Mundial"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-29599\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_david_ortiz_da_tabla.png\" width=\"262\" height=\"192\" alt=\"david_ortiz_da_tabla\" \/>Se suma a Pedro Guerrero, Jos\u00e9 Rijo y Manny Ramirez como los dominicanos que han ganado el MVP&#8230;<\/div>\n<p>  <!--more-->  <\/p>\n<div>\n<p><span style=\"font-size: 11px;\">El inicialista \/ bateador designado dominicano David Ortiz se llev\u00f3 el premio al Jugador M\u00e1s Valioso de la Serie Mundial este mi\u00e9rcoles, superando a otros candidatos como Jon Lester, Koji Uehara y Shane Victorino.<\/p>\n<p><\/span><span style=\"font-size: 11px;\">A continuaci\u00f3n los Jugadores M\u00e1s Valiosos (MVP) de las Series Mundiales de las Grandes Ligas del b\u00e9isbol norteamericano desde 1955:<\/p>\n<p><\/span><span style=\"font-size: 11px;\">2013 David Ortiz Medias Rojas de Boston<\/span><\/div>\n<div>2012 Pablo Sandoval Gigantes de San Francisco<\/div>\n<div>2011 David Freese Cardenales de St. Louis<\/div>\n<div>2010 Edgar Renter\u00eda Gigantes de San Francisco<\/div>\n<div>2009 Hideki Matsui Yankees de Nueva York<\/div>\n<div>2008 Cole Hamles Filis de Filadelfia<\/div>\n<div>2007 Mike Lowell Medias Rojas de Boston<\/div>\n<div>2006 David Eckstein Cardenales de St. Louis<\/div>\n<div>2005 Jermaine Dye Medias Blancas de Chicago<\/div>\n<div>2004 Manny Ram\u00edrez Medias Rojas de Boston<\/div>\n<div>2003 Josh Beckett Marlins de la Florida<\/div>\n<div>2002 Troy Glaus Angelinos de Anaheim<\/div>\n<div>2001 Randy Johnson Diamondbacks de Arizona<\/div>\n<div>Curt Schilling Diamondbacks de Arizona<\/div>\n<div>2000 Derek Jeter Yankees de Nueva York<\/div>\n<div>1999 Mariano Rivera Yankees de Nueva York<\/div>\n<div>1998 Scott Brosius Yankees de Nueva York<\/div>\n<div>1997 Liv\u00e1n Hern\u00e1ndez Marlins de Florida<\/div>\n<div>1996 John Wetteland Yankees de Nueva York<\/div>\n<div>1995 Tom Glavine Bravos de Atlanta<\/div>\n<div>1994 Serie cancelada por una huelga de jugadores<\/div>\n<div>1993 Paul Molitor Azulejos de Toronto<\/div>\n<div>1992 Pat Borders Azulejos de Toronto<\/div>\n<div>1991 Jack Morris Mellizos de Minnesota<\/div>\n<div>1990 Jos\u00e9 Rijo Rojos de Cincinnati<\/div>\n<div>1989 Dave Stewart Atl\u00e9ticos de Oakland<\/div>\n<div>1988 Orel Hershiser Dodgers de Los Angeles<\/div>\n<div>1987 Frank Viola Mellizos de Minnesota<\/div>\n<div>1986 Ray Knight Mets de Nueva York<\/div>\n<div>1985 Bret Saberhagen Reales de Kansas City<\/div>\n<div>1984 Alan Trammell Tigres de Detroit<\/div>\n<div>1983 Rick Dempsey Orioles de Baltimore<\/div>\n<div>1982 Darrell Porter Cardenales de St. Louis<\/div>\n<div>1981 Ron Cey Dodgers de Los Angeles<\/div>\n<div>Pedro Guerrero Dodgers de Los Angeles<\/div>\n<div>Steve Yeager Dodgers de Los Angeles<\/div>\n<div>1980 Mike Schmidt Filis de Filadelfia<\/div>\n<div>1979 Willie Stargell Piratas de Pittsburgh<\/div>\n<div>1978 Bucky Dent Yankees de Nueva York<\/div>\n<div>1977 Reggie Jackson Yankees de Nueva York<\/div>\n<div>1976 Johnny Bench Rojos de Cincinnati<\/div>\n<div>1975 Pete Rose Rojos de Cincinnati<\/div>\n<div>1974 Rollie Fingers Atl\u00e9ticos de Oakland<\/div>\n<div>1973 Reggie Jackson Atl\u00e9ticos de Oakland<\/div>\n<div>1972 Gene Tenace Atl\u00e9ticos de Oakland<\/div>\n<div>1971 Roberto Clemente Piratas de Pittsburgh<\/div>\n<div>1970 Brooks Robinson Orioles de Baltimore<\/div>\n<div>1969 Donn Clendenon Mets de Nueva York<\/div>\n<div>1968 Mickey Lolich Tigres de Detroit<\/div>\n<div>1967 Bob Gibson Cardenales de St. Louis<\/div>\n<div>1966 Frank Robinson Orioles de Baltimore<\/div>\n<div>1965 Sandy Koufax Dodgers de Los Angeles<\/div>\n<div>1964 Bob Gibson Cardenales de St. Louis<\/div>\n<div>1963 Sandy Koufax Dodgers de Los Angeles<\/div>\n<div>1962 Ralph Terry Yankees de Nueva York<\/div>\n<div>1961 Whitey Ford Yankees de Nueva York<\/div>\n<div>1960 Bobby Richardson Yankees de Nueva York<\/div>\n<div>1959 Larry Sherry Dodgers de Los Angeles<\/div>\n<div>1958 Bob Turley Yankees de Nueva York<\/div>\n<div>1957 Lew Burdette Bravos de Milwaukee<\/div>\n<div>1956 Don Larsen Yankees de Nueva York<\/div>\n<div>1955 Johnny Podres Dodgers de Brooklyn<\/div>\n<div>AFP<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Se suma a Pedro Guerrero, Jos\u00e9 Rijo y Manny Ramirez como los dominicanos que han ganado el MVP&#8230;<\/p>\n","protected":false},"author":3,"featured_media":29599,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-30109","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=30109"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30109\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/29599"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=30109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=30109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=30109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}