{"id":30234,"date":"2013-11-05T15:20:21","date_gmt":"2013-11-05T19:20:21","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/aseguran-que-el-dengue-esta-en-un-repunte-epidemiologico-en-toda-republica-dominicana\/"},"modified":"2013-11-05T15:20:21","modified_gmt":"2013-11-05T19:20:21","slug":"aseguran-que-el-dengue-esta-en-un-repunte-epidemiologico-en-toda-republica-dominicana","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/aseguran-que-el-dengue-esta-en-un-repunte-epidemiologico-en-toda-republica-dominicana\/","title":{"rendered":"Aseguran que el dengue est\u00e1 en un repunte epidemiol\u00f3gico en toda Rep\u00fablica Dominicana"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-30233\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/11\/sosua_images_05-05-05-35-56-4241464.jpg\" width=\"700\" height=\"463\" alt=\"05-05-05-35-56-4241464\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/11\/sosua_images_05-05-05-35-56-4241464.jpg 700w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/11\/sosua_images_05-05-05-35-56-4241464-300x198.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/>PUERTO PLATA.- &nbsp;De acuerdo a las estad\u00edsticas oficiales ofrecidas por las autoridades del Ministerio de Salud, con &nbsp;un &nbsp;total de 96 fallecimientos por dengue, en la actualidad Rep\u00fablica Dominicana registra el mayor n\u00famero de casos de los \u00faltimos seis a\u00f1os.<\/div>\n<p>  <!--more-->  <\/p>\n<div>&nbsp;<\/div>\n<div>&nbsp;Se asegur\u00f3 que el 2013 es el a\u00f1o que m\u00e1s muertes por dengue se han registrado en el pa\u00eds desde el 2007 hasta la fecha, a pesar de que es uno de los que menos lluvias ha recibido, condici\u00f3n natural que aumenta la posibilidad de reproducci\u00f3n de la enfermedad.<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;El promedio de las muertes por dengue entre el 2007 y el 2013, es de 59, cifra alta que se atribuye, por un lado, a la forma tard\u00eda en algunos diagn\u00f3sticos, al desconocimiento y la confusi\u00f3n de los s\u00edntomas con otras enfermedades epidemiol\u00f3gicas, no aplicar el protocolo de atenci\u00f3n debidamente, a la falta de empoderamiento por parte de la ciudadan\u00eda y a las campa\u00f1as de concienciaci\u00f3n que se refuerzan cuando el mal est\u00e1 en la \u00e9poca de pico o m\u00e1s alta.<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;El dengue est\u00e1 entre las enfermedades que causan m\u00e1s muertes pedi\u00e1tricas en el pa\u00eds, situaci\u00f3n que marca negativamente a una familia seg\u00fan un recuento de las estad\u00edsticas publicadas por la Direcci\u00f3n General de Epidemiolog\u00eda, del Ministerio de Salud P\u00fablica, en su p\u00e1gina web.<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;En el 2007 a pesar del paso de las tormentas \u00abNoel\u00bb y \u00abOlga\u00bb, en las cuales generaron torrenciales aguaceros y se contaminaron la mayor\u00eda de r\u00edos, y hubo la necesidad de aumentar el almacenaje de agua, los fallecimientos sumaron 21, lo que significa 75 menos con relaci\u00f3n a este a\u00f1o, que ya alcanza 96, y que es pr\u00e1cticamente seco.<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;Para el 2008 hasta la semana 43 (el total de semanas epidemiol\u00f3gica es de 52), se confirmaron 27 defunciones de 2,951 casos probables, de los cuales 111 fueron hemorr\u00e1gicos y el resto cl\u00e1sico.<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;En el 2009, hasta noviembre, se registraron 50 muertes por la enfermedad y m\u00e1s de 734 casos, en el 2010 se registraron 51 defunciones y 11 mil 958 casos, incluyendo 1,083 hemorr\u00e1gicos, el 2011 fue casi la excepci\u00f3n, al reportarse s\u00f3lo dos defunciones de 2,181 casos, en tanto que para el 2012, las notificaciones dan cuenta de 68 fallecimientos y 9,284 afectados.<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;Lo m\u00e1s alarmante es que el incremento semanal de mortalidad por el dengue desborda lo que las autoridades de salud hab\u00edan previsto para este 2013 ya que se ten\u00eda conocimiento de que este iba a ser un a\u00f1o epidemiol\u00f3gico, y hubo un momento en que el viceministro de Salud Colectiva, Rafael Shiffino, dijo que la cantidad de defunciones no era mayor por las medidas de precauci\u00f3n que tomaron.<\/div>\n<div>&nbsp;<\/div>\n<div><strong><em>&nbsp;M\u00e1s de 100 muertes<\/em><\/strong><\/div>\n<div>&nbsp;<\/div>\n<div>Con el registro de las 96 defunciones, se est\u00e1 a punto de confirmar la advertencia de hace dos meses del infect\u00f3logo Clemente Terrero, de que el 2013 cerrar\u00e1 con m\u00e1s de 100 fallecimientos.<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;En ese momento, los casos no llegaban a 60, lo cual era alto, seg\u00fan su punto de vista, y ahora, faltando 10 semanas epidemiol\u00f3gicas hay 96 muertes oficiales, sin incluir dos ocurridas esta semana en Santiago.<\/div>\n<div><\/div>\n<div><a href=\"http:\/\/www.puertoplatadigital.com\/verNoticia.aspx?Id=14023\">fuente<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>PUERTO PLATA.- &nbsp;De acuerdo a las estad\u00edsticas oficiales ofrecidas por las autoridades del Ministerio de Salud, con &nbsp;un &nbsp;total de 96 fallecimientos por dengue, en la actualidad Rep\u00fablica Dominicana registra el mayor n\u00famero de casos de los \u00faltimos seis a\u00f1os.<\/p>\n","protected":false},"author":3,"featured_media":30233,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-30234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=30234"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30234\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/30233"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=30234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=30234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=30234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}