{"id":30350,"date":"2013-11-11T13:17:13","date_gmt":"2013-11-11T17:17:13","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/un-cargador-inalambrico-para-iphone-tan-fino-como-una-lamina-de-plastico\/"},"modified":"2013-11-11T13:17:13","modified_gmt":"2013-11-11T17:17:13","slug":"un-cargador-inalambrico-para-iphone-tan-fino-como-una-lamina-de-plastico","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/un-cargador-inalambrico-para-iphone-tan-fino-como-una-lamina-de-plastico\/","title":{"rendered":"Un cargador inal\u00e1mbrico para iPhone tan fino como una l\u00e1mina de pl\u00e1stico"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-30349\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/11\/sosua_images_20131029062258-2013_10_10_0627-Recovered--644x362.jpg\" width=\"600\" height=\"400\" alt=\"20131029062258-2013_10_10_0627-Recovered--644x362\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/11\/sosua_images_20131029062258-2013_10_10_0627-Recovered--644x362.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/11\/sosua_images_20131029062258-2013_10_10_0627-Recovered--644x362-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>IQI&nbsp;<label datatype=\"t\">m\u00f3vil<\/label>&nbsp;es un&nbsp;<label datatype=\"t\">cargador<\/label>&nbsp;m\u00e1s peque\u00f1o y m\u00e1s delgado que una&nbsp;<label datatype=\"t\">tarjeta<\/label>&nbsp;de cr\u00e9dito, con tan solo 0,5 mil\u00edmetros en su parte m\u00e1s delgada. Este cargador tiene una conexi\u00f3n inal\u00e1mbrica Qi de recepci\u00f3n de carga con un dise\u00f1o que se transfiere a trav\u00e9s de una cinta delgada ultraflexible.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>El IQI busca financiaci\u00f3n con una campa\u00f1a de \u00abcrowdfunding\u00bb y se podr\u00e1 conectar a iPhone y a iPod Touch desliz\u00e1ndolo en la parte posterior de cualquier funda protectora blanda. Una vez que se ha instalado este sistema en el dispositivo, se puede cargar en cualquier plataforma de carga compatible. IQI puede recibir energ\u00eda inal\u00e1mbrica de los transmisores de carga est\u00e1ndar Qi.<\/p>\n<p>A lo largo de 2012 y 2013 la carga inal\u00e1mbrica se convirti\u00f3 cada vez m\u00e1s popular. Con el suministro de soluciones para dispositivos Android de carga, se hizo evidente que hab\u00eda hueco en el mercado para una buena soluci\u00f3n de carga inal\u00e1mbrica para dispositivos iOS como iPhone, iPod, iPad y el iPad Mini. La fecha de lanzamiento previsto para IQI Mobile es para principios de 2014 a un precio de 35 d\u00f3lares. El dispositivo es compatible con iPhone 5, los nuevos 5C, 5S y iPod Touch quinta generaci\u00f3n.<\/p>\n<p>Fuente:&nbsp;<a href=\"http:\/\/www.abc.es\/tecnologia\/informatica-hardware\/20131108\/abci-cargador-iphone-ipad-201311081517.html\" title=\"http:\/\/www.abc.es\/tecnologia\/informatica-hardware\/20131108\/abci-cargador-iphone-ipad-201311081517.html\">http:\/\/www.abc.es\/tecnologia\/informatica-hardware\/20131108\/abci-cargador&#8230;<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>IQI&nbsp;m\u00f3vil&nbsp;es un&nbsp;cargador&nbsp;m\u00e1s peque\u00f1o y m\u00e1s delgado que una&nbsp;tarjeta&nbsp;de cr\u00e9dito, con tan solo 0,5 mil\u00edmetros en su parte m\u00e1s delgada. Este cargador tiene una conexi\u00f3n inal\u00e1mbrica Qi de recepci\u00f3n de carga con un dise\u00f1o que se transfiere a trav\u00e9s de una cinta delgada ultraflexible.<\/p>\n","protected":false},"author":3,"featured_media":30349,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-30350","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=30350"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30350\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/30349"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=30350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=30350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=30350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}