{"id":30354,"date":"2013-11-11T13:26:09","date_gmt":"2013-11-11T17:26:09","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/queseto-miley-cyrus-se-droga-en-pleno-concierto-video\/"},"modified":"2013-11-11T13:26:09","modified_gmt":"2013-11-11T17:26:09","slug":"queseto-miley-cyrus-se-droga-en-pleno-concierto-video","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/queseto-miley-cyrus-se-droga-en-pleno-concierto-video\/","title":{"rendered":"Queseto?! Miley Cyrus se droga en pleno concierto  (video)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-30353\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/11\/sosua_images_Miley-Cyrus_se_droga_en_publico.jpg\" width=\"575\" height=\"419\" alt=\"Miley-Cyrus_se_droga_en_publico\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/11\/sosua_images_Miley-Cyrus_se_droga_en_publico.jpg 575w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/11\/sosua_images_Miley-Cyrus_se_droga_en_publico-300x218.jpg 300w\" sizes=\"auto, (max-width: 575px) 100vw, 575px\" \/>Miley Cyrus volvi\u00f3 a generar pol\u00e9mica sobre los escenarios al fumar un cigarrillo de marihuana, durante la entrega de los EMA\u00b4s 2013, en \u00c1msterdam.<\/p>\n<p>  <!--more-->  <\/p>\n<p><iframe loading=\"lazy\" id=\"kaltura_player_1384173799\" height=\"360\" width=\"590\" src=\"http:\/\/cdnapi.kaltura.com\/index.php\/kwidget\/wid\/0_0e65ix68\/uiconf_id\/6740162\/st_cache\/8681?&amp;\"><\/iframe><\/p>\n<div><a href=\"http:\/\/www.tmz.com\/videos\/0_1s2xq840\" target=\"_blank\">Miley Cyrus \u2014 Lights Up Joint ON-STAGE During Euro MTV Awards<\/a><\/div>\n<div>Adem\u00e1s de llevar un atuendo muy revelador y bailar twerking como acostumbra, la cantante reafirm\u00f3 su gusto por esta droga ante cientos de espectadores.<\/div>\n<div><\/div>\n<div>\n<p>De acuerdo con TMZ, Miley ya hab\u00eda amenzado con hacer algo escandaloso e irreverente, pero muchos consideran que sobrepas\u00f3 los l\u00edmites.<\/p>\n<p>Esto podr\u00eda traer graves consecuencias para ella, ya que en Holanda tambi\u00e9n es ilegal fumar este tipo de sustancias.<\/p>\n<p>De acuerdo con la BBC, en este pa\u00eds, el cultivo, provisi\u00f3n y posesi\u00f3n de marihuana constituyen delitos criminales, penalizados con prisi\u00f3n.<\/p>\n<p>Y adem\u00e1s, aunque la venta de esta planta est\u00e1 permitida en los cofee shops, solo ning\u00fan turista puede acudir a ellos.<\/p>\n<p>Fuente&nbsp;<strong>El Gr\u00e1fico<\/strong><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Miley Cyrus volvi\u00f3 a generar pol\u00e9mica sobre los escenarios al fumar un cigarrillo de marihuana, durante la entrega de los EMA\u00b4s 2013, en \u00c1msterdam.<\/p>\n","protected":false},"author":3,"featured_media":30353,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-30354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=30354"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30354\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/30353"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=30354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=30354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=30354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}