{"id":30502,"date":"2013-11-16T03:35:11","date_gmt":"2013-11-16T07:35:11","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/muere-a-los-41-anos-karla-alvarez-reconocida-actriz-de-telenovelas-mexicanas\/"},"modified":"2013-11-16T03:35:11","modified_gmt":"2013-11-16T07:35:11","slug":"muere-a-los-41-anos-karla-alvarez-reconocida-actriz-de-telenovelas-mexicanas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/muere-a-los-41-anos-karla-alvarez-reconocida-actriz-de-telenovelas-mexicanas\/","title":{"rendered":"Muere a los 41 a\u00f1os Karla \u00c1lvarez, reconocida actriz de telenovelas mexicanas"},"content":{"rendered":"<div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-30500\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/11\/sosua_images_Karla_alvare2.jpg\" width=\"354\" height=\"265\" alt=\"Karla_alvare2\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/11\/sosua_images_Karla_alvare2.jpg 354w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/11\/sosua_images_Karla_alvare2-300x224.jpg 300w\" sizes=\"auto, (max-width: 354px) 100vw, 354px\" \/>Particip\u00f3 en diversas novelas de Televisa, como Agujetas de color de rosa, Las tontas no van al&nbsp;<label datatype=\"t\">cielo<\/label>, La mentira, Mar\u00eda Mercedes y Acapulco cuerpo y alma.<\/p>\n<p>La actriz Karla \u00c1lvarez falleci\u00f3 hoy a los 41 a\u00f1os de edad, seg\u00fan inform\u00f3 su hermana al programa \u00abNo lo cuentes\u00bb. La causa de su muerte de la actriz es incierta hasta el momento.<\/p>\n<\/p><\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-30501\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/11\/sosua_images_Karla_alvare.jpeg\" width=\"240\" height=\"240\" alt=\"Karla_alvare\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/11\/sosua_images_Karla_alvare.jpeg 240w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/11\/sosua_images_Karla_alvare-150x150.jpeg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/11\/sosua_images_Karla_alvare-120x120.jpeg 120w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><br \/>\u00c1lvarez naci\u00f3 en la Ciudad de M\u00e9xico el 15 de octubre de 1972. Se gradu\u00f3 como bailarina profesional en la Escuela Nacional de Danza Contempor\u00e1nea y Cl\u00e1sica y posteriormente se incorpor\u00f3 al Centro de Educaci\u00f3n Art\u00edstica (CEA), de Televisa,&nbsp;<label datatype=\"t\">empresa<\/label>&nbsp;a la que perteneci\u00f3 a lo largo de toda su carrera.<\/p>\n<p>La actriz inici\u00f3 su carrera en la telenovela \u00abMar\u00eda Mercedes\u00bb, al lado de Thal\u00eda, se caracteriz\u00f3 por encarnar a personajes antag\u00f3nicos.<\/p>\n<p>Particip\u00f3 en melodramas de renombre como \u00abAgujetas de color de rosa\u00bb, \u00abMi querida Isabel\u00bb -donde tuvo su primera gran oportunidad como protagonista-, \u00abMujeres enga\u00f1adas\u00bb, \u00abAlma rebelde\u00bb, \u00abHeridas de amor\u00bb, \u00abLas tontas no van al cielo\u00bb, \u00abUn gancho al coraz\u00f3n\u00bb y \u00abQue bonito amor\u00bb, su \u00faltima participaci\u00f3n en televisi\u00f3n.<\/p>\n<p>Karla \u00c1lvarez tambi\u00e9n es recordada por su participaci\u00f3n en en el reality show \u00abBig&nbsp;<label datatype=\"t\">Brother<\/label>VIP\u00bb, transmitido en 2003, donde permaneci\u00f3 50 d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Particip\u00f3 en diversas novelas de Televisa, como Agujetas de color de rosa, Las tontas no van al&nbsp;cielo, La mentira, Mar\u00eda Mercedes y Acapulco cuerpo y alma. La actriz Karla \u00c1lvarez falleci\u00f3 hoy a los 41 a\u00f1os de edad, seg\u00fan inform\u00f3 su hermana al programa \u00abNo lo cuentes\u00bb. La causa de su muerte de la actriz es incierta hasta el momento. \u00c1lvarez naci\u00f3 en la Ciudad de M\u00e9xico el 15 de octubre de 1972. Se gradu\u00f3 como bailarina profesional en la Escuela Nacional de Danza Contempor\u00e1nea y Cl\u00e1sica y posteriormente se incorpor\u00f3 al Centro de Educaci\u00f3n Art\u00edstica (CEA), de Televisa,&nbsp;empresa&nbsp;a la que perteneci\u00f3 a lo largo de toda su carrera. La actriz inici\u00f3 su carrera en la telenovela \u00abMar\u00eda Mercedes\u00bb, al lado de Thal\u00eda, se caracteriz\u00f3 por encarnar a personajes antag\u00f3nicos. Particip\u00f3 en melodramas de renombre como \u00abAgujetas de color de rosa\u00bb, \u00abMi querida Isabel\u00bb -donde tuvo su primera gran oportunidad como protagonista-, \u00abMujeres enga\u00f1adas\u00bb, \u00abAlma rebelde\u00bb, \u00abHeridas de amor\u00bb, \u00abLas tontas no van al cielo\u00bb, \u00abUn gancho al coraz\u00f3n\u00bb y \u00abQue bonito amor\u00bb, su \u00faltima participaci\u00f3n en televisi\u00f3n. Karla \u00c1lvarez tambi\u00e9n es recordada por su participaci\u00f3n en en el reality show \u00abBig&nbsp;BrotherVIP\u00bb, transmitido en 2003, donde permaneci\u00f3 50 d\u00edas.<\/p>\n","protected":false},"author":3,"featured_media":30500,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-30502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=30502"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30502\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/30500"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=30502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=30502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=30502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}