{"id":30529,"date":"2013-11-18T04:00:00","date_gmt":"2013-11-18T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/celos-virtuales-icomo-manejarlos\/"},"modified":"2013-11-18T04:00:00","modified_gmt":"2013-11-18T08:00:00","slug":"celos-virtuales-icomo-manejarlos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/celos-virtuales-icomo-manejarlos\/","title":{"rendered":"Celos virtuales: \u00bfc\u00f3mo manejarlos?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-30528\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/11\/sosua_images_por-venir.com_.ar_580000_16112013_07.jpg\" width=\"600\" height=\"400\" alt=\"por-venir.com_.ar_580000_16112013_07\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/11\/sosua_images_por-venir.com_.ar_580000_16112013_07.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/11\/sosua_images_por-venir.com_.ar_580000_16112013_07-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>Desde que las redes virtuales como&nbsp;<label datatype=\"t\">Facebook<\/label>&nbsp;o Twitter se popularizaron, las reglas entre las parejas han cambiado. Hoy en d\u00eda, especificar por Facebook que &#8216;est\u00e1s en una relaci\u00f3n&#8217; es tan importante como usar el anillo de casado en la mano izquierda. Y si los celos existen en la&nbsp;<label datatype=\"t\">vida<\/label>&nbsp;real, \u00bfc\u00f3mo no van a existir tambi\u00e9n en la virtual?<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>\u00bfEs &#8216;normal&#8217; chequear el perfil de Facebook del otro? La psicoanalista Any Krieger, miembro de APA (Asociaci\u00f3n Psicoanal\u00edtica Argentina), explica a Ahguapas: \u00abmirar el perfil del Facebook de la pareja es un impulso que obedece a la curiosidad estructural, o sea que todos somos curiosos. Ahora, si esto pasa demasiado seguido, varias veces en el d\u00eda, tal vez estemos frente a algun temor m\u00e1s espec\u00edfico. Si la curiosidad se transforma en ansiedad, es un alerta y lo mejor ser\u00eda reflexionar acerca de lo que sentimos con nuestra pareja\u00bb.<\/p>\n<p>\u00abEspiar es una conducta humana, a veces no nos animamos a preguntar y entonces optamos por tratar de saber acerca del otro de la peor manera\u00bb, cuenta Any Krieger. Si bien querer saber sobre el otro sin que \u00e9l sepa es una conducta humana, la realidad es que el respeto mutuo en una pareja es fundamental. \u00abSi eso se pierde o no existe, estamos frente a un disfuncionamiento. En la pareja se trata siempre de negociar y si nuestra pareja sufre por<label datatype=\"t\">fotos<\/label>&nbsp;provocativas o frases reveladoras, es mejor entender que ser\u00e1 peor para los dos exhibirlas al p\u00fablico\u00bb.<\/p>\n<p>Hay que tener en cuenta que los celos &#8211; virtuales o f\u00edsicos &#8211; son s\u00edntomas de una gran desconfianza. \u00abLos celos, aunque sean virtuales, son reales. Los sentimos en el cuerpo. Si una pareja sufre de este tipo de celos, sugiero reflexionar en conjunto lo que acontece en nuestro interior. Esta acci\u00f3n enriquecer\u00e1 la relaci\u00f3n de pareja\u00bb, dice Krieger. Para solucionar los problemas que ocasionan los celos virtuales, lo m\u00e1s sano ser\u00eda hablar del tema sin tapujos y exponiendo nuestras inseguridades.<\/p>\n<p>Si la celosa sos vos, ten\u00e9 en cuenta que es normal que \u00e9l tenga otras amistades. Bajo la mente de una persona celosa, cualquier palabra puede ser interpretada de una forma sospechosa fuera de contexto. Dicho de otra manera, &#8216;el que busca, encuentra&#8217;. Adem\u00e1s, los celos forman parte de un amor entendido con sentido de propiedad y de pertenencia, es decir, un sentimiento insano. Si la v\u00edctima de sus celos sos vos, explicale que no tiene de qu\u00e9 preocuparse, y traten el tema de la confianza.<\/p>\n<p>Fuente:&nbsp;<a href=\"http:\/\/derf.com.ar\/despachos.asp?cod_des=580000&amp;ID_Seccion=54&amp;fecemi=16\/11\/2013&amp;Titular=celos-virtuales-iquestcoacutemo-manejarlos.html\" title=\"http:\/\/derf.com.ar\/despachos.asp?cod_des=580000&amp;ID_Seccion=54&amp;fecemi=16\/11\/2013&amp;Titular=celos-virtuales-iquestcoacutemo-manejarlos.html\">http:\/\/derf.com.ar\/despachos.asp?cod_des=580000&amp;ID_Seccion=54&amp;fecemi=16\/&#8230;<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Desde que las redes virtuales como&nbsp;Facebook&nbsp;o Twitter se popularizaron, las reglas entre las parejas han cambiado. Hoy en d\u00eda, especificar por Facebook que &#8216;est\u00e1s en una relaci\u00f3n&#8217; es tan importante como usar el anillo de casado en la mano izquierda. Y si los celos existen en la&nbsp;vida&nbsp;real, \u00bfc\u00f3mo no van a existir tambi\u00e9n en la virtual?<\/p>\n","protected":false},"author":3,"featured_media":30528,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-30529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=30529"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30529\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/30528"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=30529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=30529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=30529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}