{"id":30971,"date":"2013-12-17T03:05:43","date_gmt":"2013-12-17T07:05:43","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/conocer-sobre-la-hepatitis-b-puede-salvarle-la-vid\/"},"modified":"2013-12-17T03:05:43","modified_gmt":"2013-12-17T07:05:43","slug":"conocer-sobre-la-hepatitis-b-puede-salvarle-la-vid","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/conocer-sobre-la-hepatitis-b-puede-salvarle-la-vid\/","title":{"rendered":"Conocer sobre la hepatitis B puede salvarle la vida"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-30970\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/12\/sosua_images_hepatitis_b.jpg\" width=\"600\" height=\"450\" alt=\"hepatitis_b\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/12\/sosua_images_hepatitis_b.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/12\/sosua_images_hepatitis_b-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>La prevalencia de este virus en Venezuela var\u00eda de acuerdo al grupo y a la zona estudiada. Sin embargo, entre los grupos de alto riesgo se identifican los ind\u00edgenas Yucpas, del estado Zulia y los Yanomami del Amazonas.<\/p>\n<p>  <!--more-->  <\/p>\n<p>\u00abEsto es la hepatitis&#8230; Con\u00f3cela. Afr\u00f3ntala\u201d es el lema que la Organizaci\u00f3n Mundial de la Salud (OMS) defini\u00f3 para el 2013 como campa\u00f1a para concienciar a la poblaci\u00f3n sobre la importancia de prevenir esta patolog\u00eda. En total existen cinco tipos distintos de hepatitis, pero sin duda alguna la m\u00e1s peligrosa es la B, porque puede causar hepatopat\u00eda cr\u00f3nica (enfermedad recurrente de m\u00e1s de seis meses) y conlleva un alto riesgo de muerte por cirrosis y\/o c\u00e1ncer hep\u00e1tico.<\/p>\n<p> Se calcula que en el mundo hay unos 2.000 millones de personas infectadas por el virus de la hepatitis B (VHB) y m\u00e1s de 350 millones con infecci\u00f3n hep\u00e1tica cr\u00f3nica, seg\u00fan la OMS. El doctor Jorge Riera, infect\u00f3logo del Hospital Universitario de la UCV, asegura que si bien una cantidad considerable de pacientes con infecci\u00f3n VHB no presentan complicaciones hep\u00e1ticas, existe la posibilidad de que algunos evolucionen hacia una enfermedad grave en el curso de su vida, siendo m\u00e1s probable que esto ocurra en hombres.<\/p>\n<p> \u201cEntre 15% y 40% de los pacientes con infecci\u00f3n cr\u00f3nica han de presentar cirrosis, evolucionando a la insuficiencia hep\u00e1tica y\/o c\u00e1ncer de h\u00edgado. De hecho, la infecci\u00f3n por VHB es responsable de 500.000 a 1.200.000 muertes por a\u00f1o como consecuencia de los efectos agudos o cr\u00f3nicos de esta enfermedad\u201d, asegura el especialista.<\/p>\n<p> El virus de la hepatitis B se transmite por la exposici\u00f3n a sangre, semen y otros l\u00edquidos corporales infecciosos. Cuando la transmisi\u00f3n es vertical -de madre a hijo- u horizontal -entre ni\u00f1os peque\u00f1os durante el juego- la infecci\u00f3n casi siempre se hace cr\u00f3nica. Por el contrario, cuando la transmisi\u00f3n ocurre en adolescentes o adultos, habitualmente mediante el contacto sexual, agujas o productos sangu\u00edneos contaminados, la infecci\u00f3n habitualmente se resuelve; a no ser que el individuo tenga alteraciones en su sistema inmunitario (por ejemplo, que posea el virus de inmunodeficiencia humana \u2013VIH-).<\/p>\n<p> En Am\u00e9rica Latina la prevalencia de la hepatitis B es ampliamente variable. Resulta alta en regiones Amaz\u00f3nicas de Brasil, Venezuela, Colombia, Per\u00fa y Rep\u00fablica Dominicana por la falta de medidas de salubridad, lo que hace m\u00e1s f\u00e1cil su contagio. En el pa\u00eds, la prevalencia cambia de acuerdo al grupo y a la zona estudiada, seg\u00fan lo explica el doctor Riera.<\/p>\n<p> \u201cExisten tres grupos de prevalencia de hepatitis B: los de bajo, intermedio o alto riesgo. El primero est\u00e1 conformado por una poblaci\u00f3n sana en diferentes regiones del territorio nacional. Los estudios en embarazadas y\/o parturientas muestran una prevalencia muy baja, al igual que en todos los casos de reci\u00e9n nacidos que fueron estudiados, lo que demuestra que la transmisi\u00f3n horizontal es m\u00e1s importante en nuestro pa\u00eds\u201d.<\/p>\n<p> El grupo de riesgo intermedio est\u00e1 conformado por aquellas personas que por su profesi\u00f3n o actividad laboral est\u00e1n expuestas al contagio, como m\u00e9dicos, bioanalistas y enfermeras \u2013 entre otros trabajadores de salud\u2013, cuando estos sufren pinchazos accidentales de aguja mientras asisten a personas infectadas por el virus. Entre los sectores de alto riesgo se identifican los ind\u00edgenas Yucpas, del estado Zulia y los Yanomami del Amazonas porque principalmente no se vacunan ni siguen medidas importantes de salubridad.<\/p>\n<p> El tratamiento<br \/> Una de las formas de prevenir la hepatitis B es la vacunaci\u00f3n y el aislamiento de las personas contaminadas. Sin embargo, cuando se posee el virus se debe atacar con tratamiento para disminuir el avance de la enfermedad, a fin de evitar la cirrosis y c\u00e1ncer de h\u00edgado.<\/p>\n<p> \u201cEl control del virus requiere una terapia de mantenimiento a largo plazo. Sin embargo, la desventaja de este tipo de tratamiento es el riesgo de generar resistencia. Para reducir esta posibilidad, la mayor\u00eda de los pacientes coinfectados necesitan una terapia de combinaci\u00f3n contra el virus de hepatitis B\u201d. Para la terapia antiviral, se prefiere utilizar tratamientos con una baja tasa de resistencia, uno de ellos es la telbivudina, una mol\u00e9cula que inhibe la replicaci\u00f3n del VHB por medio de un mecanismo de acci\u00f3n que ataca directamente la cadena de ADN del virus.<\/p>\n<p> Sobre Novartis:<br \/> Con sede en Basilea, Suiza, el grupo Novartis ofrece desde hace m\u00e1s de 16 a\u00f1os soluciones para atender las necesidades de salud de pacientes y m\u00e9dicos, a trav\u00e9s de una amplia cartera de medicamentos innovadores, equipos quir\u00fargicos y tratamientos para el cuidado de la visi\u00f3n, farmac\u00e9uticos gen\u00e9ricos, productos de consumo, vacunas y herramientas de diagn\u00f3stico. Novartis produce el \u00fanico medicamento aprobado en el mundo para tratar la degeneraci\u00f3n macular asociada a la edad y cuenta con un tratamiento de primera l\u00ednea para pacientes con leucemia mieloide cr\u00f3nica, as\u00ed como un arsenal de medicamentos para la hipertensi\u00f3n, el dolor, el cuidado de los pacientes trasplantados, entre otros. Esta farmac\u00e9utica l\u00edder en Investigaci\u00f3n y Desarrollo de nuevas terapias para mejorar la salud y calidad de vida emplea en el mundo a m\u00e1s de 129.000 personas y est\u00e1 presente en 140 pa\u00edses.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La prevalencia de este virus en Venezuela var\u00eda de acuerdo al grupo y a la zona estudiada. Sin embargo, entre los grupos de alto riesgo se identifican los ind\u00edgenas Yucpas, del estado Zulia y los Yanomami del Amazonas.<\/p>\n","protected":false},"author":3,"featured_media":30970,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-30971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=30971"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30971\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/30970"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=30971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=30971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=30971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}